{"id":19218,"date":"2023-05-12T00:00:00","date_gmt":"2023-05-11T22:00:00","guid":{"rendered":"https:\/\/addi.de\/news\/addi-sucht-neue-mitarbeiter\/"},"modified":"2023-06-22T15:31:35","modified_gmt":"2023-06-22T13:31:35","slug":"addi-sucht-neue-mitarbeiter-mitarbeiterinnen-m-w-d","status":"publish","type":"news","link":"https:\/\/addi.de\/en\/news\/addi-sucht-neue-mitarbeiter-mitarbeiterinnen-m-w-d\/","title":{"rendered":"addi is looking for new employees"},"content":{"rendered":"<div id=\"header-text-block_7e77ded215fd2f6df488673739fb9a45\" class=\"header-text\" >\n    <section>\n        <div class=\"container\">\n            <div class=\"row position-relative\">\n                <div class=\"col-12 col-lg-3 offset-lg-1 order-2 order-lg-1\">\n                    <div class=\"text-wrapper\">\n                        <div class=\"color-area-secondary\"><\/div>\n                                                    <div class=\"topline hl-color\">\n                                News                            <\/div>\n                                                                                                    <h1>addi sucht neue Mitarbeiter<\/h1>\n                                                <div class=\"share-links\">\n                            <span>Teilen:<\/span>\n                            <a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Faddi.de%2Fen%2Fnews%2Faddi-sucht-neue-mitarbeiter-mitarbeiterinnen-m-w-d%2F\" class=\"d-inline-block px-2\" onclick=\"window.open(this.href, 'mywin', 'left=20,top=20,width=500,height=500,toolbar=1,resizable=0'); return false;\"><i class=\"fab fa-facebook-f hl-color\"><\/i><\/a>\n                            <a href=\"https:\/\/twitter.com\/intent\/tweet?text=https%3A%2F%2Faddi.de%2Fen%2Fnews%2Faddi-sucht-neue-mitarbeiter-mitarbeiterinnen-m-w-d%2F\" class=\"d-inline-block px-2\" onclick=\"window.open(this.href, 'mywin', 'left=20,top=20,width=500,height=500,toolbar=1,resizable=0'); return false;\"><i class=\"fa-brands fa-x-twitter hl-color\"><\/i><\/a>\n                        <\/div>\n                        <div class=\"text\">\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <div class=\"col-12 col-lg-7 offset-lg-1 mb-3 mb-lg-0 order-1 order-lg-2\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"958\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/01\/Mitarbeiter-gesucht-3-1280x958.jpg\" class=\"attachment-1280x970 size-1280x970\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/01\/Mitarbeiter-gesucht-3-1280x958.jpg 1280w, https:\/\/addi.de\/wp-content\/uploads\/2022\/01\/Mitarbeiter-gesucht-3-600x450.jpg 600w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>                                        <div class=\"row toc-wrapper\">\n                        <div class=\"col-12 col-lg-6 offset-lg-5\">\n                            <div class=\"toc-title\">\n                                Inhaltsverzeichnis                            <\/div>\n                            <div class=\"toc-content\">\n\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<\/div>\n\n\n\n            \n<div id=\"text-gallery-video-block_dc5fb3027854f5828b880f13c0375037\" class=\"text-gallery-video alignment-left company\" >\n    <section>\n        <div class=\"container position-relative\">\n            \n\n                                                                                <div class=\"gallery-wrapper  d-lg-block\">\n                                                                                                                        <div class=\"row align-items-end\">\n                                                <div class=\"col-12 col-lg-6 offset-lg-1\">\n                                                    <div class=\"text-wrapper mb-3\">\n                                                                                                                    <div class=\"text-background-small color-area-secondary\"><\/div>\n                                                                                                                                                                                                                                                                                            <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    <div class=\"text\">\n                                                                        <p>Das addi Team braucht Verst\u00e4rkung!<br \/>\nSeit 1829 produzieren wir unter dem bekannten Markennamen &#8222;addi&#8220; Premium Handarbeitsnadeln in Altena im sch\u00f6nen Sauerland.<br \/>\nUnd weil die addi Fangemeinde w\u00e4chst und w\u00e4chst und Kunden in mehr als 55 L\u00e4ndern sehns\u00fcchtig auf addi Nadeln made in Germany warten, suchen wir neue Mitarbeiter.<\/p>\n<p>Vielleicht ist die passende Stellenbeschreibungen dabei?! Ausf\u00fchrliche Infos gibt es auf den nachfolgenden Seiten:<br \/>\nStellenangebote oder <a href=\"http:\/\/www.karriere-suedwestfalen.de\/gustav-selter\" target=\"_blank\" rel=\"noopener\">im Portal von Karriere S\u00fcdwestfalen<\/a><\/p>\n<p>Bitte gerne weitersagen!<\/p>\n                                                                    <\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                                                                                    <div class=\"row link-wrapper\">\n                                                                <div class=\"col-12 col-lg-10 offset-lg-2\">\n                                                                    <div class=\"row\">\n                                                                                                                                                    <div class=\"col-12 col-lg-6\">\n                                                                                <a href=\"https:\/\/addi.de\/joboffers\/\" target=\"_blank\" class=\"buttonlink prio-1\">Stellenangebote<\/a>                                                                            <\/div>\n                                                                                                                                                                                                                    <\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                            <\/div>\n                                                    <div class=\"row\">\n                                                        <div class=\"col-12 col-lg-8 offset-lg-4\">\n                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_dc5fb3027854f5828b880f13c0375037\">\n                                                                    <img loading=\"lazy\" decoding=\"async\" width=\"520\" height=\"300\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Firmengeba\u0308ude-Produktion-2022OP9_0353Standort-Dahle-Altena-Selter-addi-520x300.jpg\" class=\"attachment-520x300 size-520x300\" alt=\"\" \/>                                                                <\/div>\n                                                                                                                    <\/div>\n                                                    <\/div>\n                                                                                                            <div class=\"row gallery-headline-wrapper centered\">\n                                                            <div class=\"col-12\">\n                                                                                                                                    <div class=\"scriptheadline hl-color\">\n                                                                        Werden Sie teil des Teams                                                                    <\/div>\n                                                                                                                                                                                            <\/div>\n                                                        <\/div>\n                                                                                                    <\/div>\n                                                <div class=\"col-12 col-lg-4\">\n                                                    <div class=\"row mb-3\">\n                                                        <div class=\"col-12 col-lg-9\">\n                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_dc5fb3027854f5828b880f13c0375037\">\n                                                                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/Selter-Gebaeude-Beschriftung-Luftbild-addi-rot-scaled-400x320.jpg\" class=\"attachment-400x320 size-400x320\" alt=\"\" \/>                                                                <\/div>\n                                                                                                                    <\/div>\n                                                    <\/div>\n                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_dc5fb3027854f5828b880f13c0375037\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/01\/klein_Claudia_Malcus_Mitarbeiter_Bloggerraum_addi_MadeingermanyOP9_0818-400x320.jpg\" class=\"attachment-400x320 size-400x320\" alt=\"Inhaberin und Gesch\u00e4ftsf\u00fchrerin Claudia Malcus\" \/>                                                        <\/div>\n                                                                                                                                                        <\/div>\n                                            <\/div>\n                                                                                                            <\/div>\n                               \n                                 \n                            <div class=\"gallery-wrapper d-block d-lg-none\">\n                                                                    <div class=\"text-wrapper mb-5\">\n                                                                                    <div class=\"text-background-small color-area-secondary full\"><\/div>\n                                                                                                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                    <div class=\"text\">\n                                                        <p>Das addi Team braucht Verst\u00e4rkung!<br \/>\nSeit 1829 produzieren wir unter dem bekannten Markennamen &#8222;addi&#8220; Premium Handarbeitsnadeln in Altena im sch\u00f6nen Sauerland.<br \/>\nUnd weil die addi Fangemeinde w\u00e4chst und w\u00e4chst und Kunden in mehr als 55 L\u00e4ndern sehns\u00fcchtig auf addi Nadeln made in Germany warten, suchen wir neue Mitarbeiter.<\/p>\n<p>Vielleicht ist die passende Stellenbeschreibungen dabei?! Ausf\u00fchrliche Infos gibt es auf den nachfolgenden Seiten:<br \/>\nStellenangebote oder <a href=\"http:\/\/www.karriere-suedwestfalen.de\/gustav-selter\" target=\"_blank\" rel=\"noopener\">im Portal von Karriere S\u00fcdwestfalen<\/a><\/p>\n<p>Bitte gerne weitersagen!<\/p>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                                                                    <div class=\"row link-wrapper\">\n                                                <div class=\"col-12 col-lg-6 offset-lg-2\">\n                                                    <div class=\"row\">\n                                                                                                                    <div class=\"col-12 col-lg-6\">\n                                                                <a href=\"https:\/\/addi.de\/joboffers\/\" target=\"_blank\" class=\"buttonlink prio-1\">Stellenangebote<\/a>                                                            <\/div>\n                                                                                                                                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                            <\/div>\n                                                                            <div class=\"row mb-4\">\n                                            <div class=\"col-12\">\n                                                                                                    <div id=\"galleryCarousel-block_dc5fb3027854f5828b880f13c0375037\" class=\"carousel slide\" data-ride=\"carousel\" data-interval=\"2500\" data-pause=\"false\" data-keyboard=\"false\">\n                                                        <div class=\"carousel-inner\" data-countslides=\"3\">\n                                                                                                                            <div class=\"carousel-item active\">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_dc5fb3027854f5828b880f13c0375037\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/Selter-Gebaeude-Beschriftung-Luftbild-addi-rot-scaled-1280x970.jpg\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/Selter-Gebaeude-Beschriftung-Luftbild-addi-rot-scaled-400x320.jpg\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                            <div class=\"carousel-item \">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_dc5fb3027854f5828b880f13c0375037\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/01\/klein_Claudia_Malcus_Mitarbeiter_Bloggerraum_addi_MadeingermanyOP9_0818-1280x970.jpg\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/01\/klein_Claudia_Malcus_Mitarbeiter_Bloggerraum_addi_MadeingermanyOP9_0818-400x320.jpg\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                            <div class=\"carousel-item \">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_dc5fb3027854f5828b880f13c0375037\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Firmengeba\u0308ude-Produktion-2022OP9_0353Standort-Dahle-Altena-Selter-addi-1280x970.jpg\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Firmengeba\u0308ude-Produktion-2022OP9_0353Standort-Dahle-Altena-Selter-addi-400x320.jpg\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                    <\/div>\n                                                    <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                                                                                                                                        <div class=\"row gallery-headline-wrapper centered\">\n                                            <div class=\"col-12\">\n                                                                                                    <div class=\"scriptheadline hl-color\">\n                                                        Werden Sie teil des Teams                                                    <\/div>\n                                                                                                                                            <\/div>\n                                        <\/div>\n                                                                                                <\/div>\n                                                                                    <\/div>\n    <\/section>\n<\/div>\n\n            \n        <div class=\"modal fade modal-move-to-body gallery-modal company\" id=\"modal-text-gallery-video-block_dc5fb3027854f5828b880f13c0375037\" tabindex=\"-1\"\n             aria-labelledby=\"modal-text-gallery-video-block_dc5fb3027854f5828b880f13c0375037\" aria-hidden=\"true\">\n            <div class=\"modal-dialog modal-xl modal-dialog-centered\">\n                <div class=\"modal-content\">\n                    <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n                        <i class=\"fas fa-times\"><\/i>\n                    <\/button>\n                    <div class=\"modal-body\">\n                        <div class=\"container-fluid\">\n                                                            <div id=\"modal-carousel-text-gallery-video-block_dc5fb3027854f5828b880f13c0375037\" class=\"carousel slide keepsize\">\n                                    <div class=\"carousel-inner\" data-countslides=\"3\">\n                                                                                    <div class=\"carousel-item active\">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/Selter-Gebaeude-Beschriftung-Luftbild-addi-rot-scaled.jpg\" class=\"attachment-full size-full wpsmartcrop-image wpsmartcrop-image\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/Selter-Gebaeude-Beschriftung-Luftbild-addi-rot-scaled.jpg 2560w, https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/Selter-Gebaeude-Beschriftung-Luftbild-addi-rot-scaled-450x253.jpg 450w, https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/Selter-Gebaeude-Beschriftung-Luftbild-addi-rot-scaled-768x432.jpg 768w, https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/Selter-Gebaeude-Beschriftung-Luftbild-addi-rot-scaled-1536x864.jpg 1536w, https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/Selter-Gebaeude-Beschriftung-Luftbild-addi-rot-scaled-2048x1152.jpg 2048w, https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/Selter-Gebaeude-Beschriftung-Luftbild-addi-rot-scaled-1280x720.jpg 1280w, https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/Selter-Gebaeude-Beschriftung-Luftbild-addi-rot-scaled-1320x743.jpg 1320w, https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/Selter-Gebaeude-Beschriftung-Luftbild-addi-rot-scaled-600x338.jpg 600w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" data-smartcrop-focus=\"[59,37]\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                                    <div class=\"carousel-item \">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/01\/klein_Claudia_Malcus_Mitarbeiter_Bloggerraum_addi_MadeingermanyOP9_0818.jpg\" class=\"attachment-full size-full wpsmartcrop-image wpsmartcrop-image\" alt=\"Inhaberin und Gesch\u00e4ftsf\u00fchrerin Claudia Malcus\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/01\/klein_Claudia_Malcus_Mitarbeiter_Bloggerraum_addi_MadeingermanyOP9_0818.jpg 2000w, https:\/\/addi.de\/wp-content\/uploads\/2023\/01\/klein_Claudia_Malcus_Mitarbeiter_Bloggerraum_addi_MadeingermanyOP9_0818-450x300.jpg 450w, https:\/\/addi.de\/wp-content\/uploads\/2023\/01\/klein_Claudia_Malcus_Mitarbeiter_Bloggerraum_addi_MadeingermanyOP9_0818-768x512.jpg 768w, https:\/\/addi.de\/wp-content\/uploads\/2023\/01\/klein_Claudia_Malcus_Mitarbeiter_Bloggerraum_addi_MadeingermanyOP9_0818-1536x1024.jpg 1536w, https:\/\/addi.de\/wp-content\/uploads\/2023\/01\/klein_Claudia_Malcus_Mitarbeiter_Bloggerraum_addi_MadeingermanyOP9_0818-600x400.jpg 600w, https:\/\/addi.de\/wp-content\/uploads\/2023\/01\/klein_Claudia_Malcus_Mitarbeiter_Bloggerraum_addi_MadeingermanyOP9_0818-300x200.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2023\/01\/klein_Claudia_Malcus_Mitarbeiter_Bloggerraum_addi_MadeingermanyOP9_0818-1320x880.jpg 1320w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" data-smartcrop-focus=\"[69,30]\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                                    <div class=\"carousel-item \">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Firmengeba\u0308ude-Produktion-2022OP9_0353Standort-Dahle-Altena-Selter-addi.jpg\" class=\"attachment-full size-full wpsmartcrop-image wpsmartcrop-image\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Firmengeba\u0308ude-Produktion-2022OP9_0353Standort-Dahle-Altena-Selter-addi.jpg 2000w, https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Firmengeba\u0308ude-Produktion-2022OP9_0353Standort-Dahle-Altena-Selter-addi-450x300.jpg 450w, https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Firmengeba\u0308ude-Produktion-2022OP9_0353Standort-Dahle-Altena-Selter-addi-768x512.jpg 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Firmengeba\u0308ude-Produktion-2022OP9_0353Standort-Dahle-Altena-Selter-addi-1536x1024.jpg 1536w, https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Firmengeba\u0308ude-Produktion-2022OP9_0353Standort-Dahle-Altena-Selter-addi-600x400.jpg 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Firmengeba\u0308ude-Produktion-2022OP9_0353Standort-Dahle-Altena-Selter-addi-300x200.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Firmengeba\u0308ude-Produktion-2022OP9_0353Standort-Dahle-Altena-Selter-addi-1320x880.jpg 1320w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" data-smartcrop-focus=\"[50,50]\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                            <\/div>\n                                    <a class=\"carousel-control-prev\" href=\"#modal-carousel-text-gallery-video-block_dc5fb3027854f5828b880f13c0375037\" role=\"button\" data-slide=\"prev\">\n                                        <i class=\"fas fa-angle-left\"><\/i>\n                                    <\/a>\n                                    <a class=\"carousel-control-next\" href=\"#modal-carousel-text-gallery-video-block_dc5fb3027854f5828b880f13c0375037\" role=\"button\" data-slide=\"next\">\n                                        <i class=\"fas fa-angle-right\"><\/i>\n                                    <\/a>\n                                    <div class=\"carousel-indicators-wrapper\">\n                                        <ol class=\"carousel-indicators\">\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_dc5fb3027854f5828b880f13c0375037\" data-slide-to=\"0\"\n                                                    class=\"active\"><\/li>\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_dc5fb3027854f5828b880f13c0375037\" data-slide-to=\"1\"\n                                                    class=\"\"><\/li>\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_dc5fb3027854f5828b880f13c0375037\" data-slide-to=\"2\"\n                                                    class=\"\"><\/li>\n                                                                                    <\/ol>\n                                    <\/div>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    \n\n<div id=\"selection-teaser-block_0e8b97419802bf1030e006b14633e3f3\" class=\"selection-teaser \" >\n    <section>\n        <div class=\"container\">\n                            <div class=\"row\">\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper inherit\">\n                            <div class=\"image-wrapper \">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/addi_Philosophie-400x320.png\" class=\"attachment-400x320 size-400x320\" alt=\"Kostenlose Handarbeitsanleitungen\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Page                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        Philosophie                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        Made in Germany. Unser Versprechen.                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>addi-Nadeln sind f\u00fcr viele Strick- und H\u00e4kelfans auf der ganzen Welt zu einem Synonym f\u00fcr hohe Qualit\u00e4t geworden.<\/p>\n<p>Unsere addi Philosophie: Die Herkunft unserer Produkte ist jederzeit nachvollziehbar. Faire Arbeitsverh\u00e4ltnisse, regionale Materialien und Qualit\u00e4t liegen uns am Herzen.<\/p>\n<p>&nbsp;<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href=\"https:\/\/addi.de\/en\/philosophie\/\" target=\"_self\" class=\"buttonlink prio-2\">Mehr erfahren<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper company\">\n                            <div class=\"image-wrapper \">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/05\/Mitarbeiter_Azubis_Ullrich-Doerr-ColibriXL-400x320.jpg\" class=\"attachment-400x320 size-400x320\" alt=\"Ausbildung bei addi\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Page                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        Karriere                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        Deine Ausbildung bei addi.                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>addi bzw. die Firma Selter ist ein erfolgreiches Familienunternehmen mit mehr als 120 Mitarbeitern mitten im gr\u00fcnen Herzen von NRW, dem Sauerland. Hier trifft Innovation auf Tradition.<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href=\"https:\/\/addi.de\/en\/ausbildung-bei-addi\/\" target=\"_self\" class=\"buttonlink prio-2\">Mehr erfahren<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper company\">\n                            <div class=\"image-wrapper \">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/01\/addi-Mitarbeiter-Kundenservice-Firma-Selter-Altena-400x320.jpg\" class=\"attachment-400x320 size-400x320\" alt=\"Arbeiten bei addi, Ausbildung bei addi\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Page                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        Karriere                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        Arbeiten bei addi                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>addi bzw. die Firma Selter ist ein erfolgreiches Familienunternehmen mit mehr als 120 Mitarbeitern mitten im gr\u00fcnen Herzen von NRW, dem Sauerland. Hier trifft Innovation auf Tradition.<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href=\"https:\/\/addi.de\/en\/arbeiten-bei-addi\/\" target=\"_self\" class=\"buttonlink prio-2\">Mehr erfahren<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/section>\n<\/div>\n","protected":false},"template":"","kategorie_news":[40],"class_list":["post-19218","news","type-news","status-publish","hentry","kategorie_news-aktuelles"],"acf":[],"_links":{"self":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/news\/19218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/types\/news"}],"wp:attachment":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/media?parent=19218"}],"wp:term":[{"taxonomy":"kategorie_news","embeddable":true,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/kategorie_news?post=19218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}