{"id":1966,"date":"2022-03-14T10:53:41","date_gmt":"2022-03-14T09:53:41","guid":{"rendered":"https:\/\/addi.de\/?page_id=1966"},"modified":"2023-01-20T13:28:30","modified_gmt":"2023-01-20T12:28:30","slug":"online-merchants","status":"publish","type":"page","link":"https:\/\/addi.de\/en\/online-haendler\/","title":{"rendered":"Online retailer"},"content":{"rendered":"<div id=\"header-focus-block_0531ba168659503c7dca4c80da768602\" class=\"header-focus dark\" >\n    <section>\n        <div class=\"container\">\n            <div class=\"row align-items-center header-wrapper\">\n                <div class=\"col-12 col-lg-8 order-2\">\n                    <div class=\"text-wrapper\">\n                        <div class=\"color-area color-area-primary\"><\/div>\n                        <div class=\"row\">\n                            <div class=\"col-12 col-lg-8\">\n                                                                                                                                                            <h1>Our online retail partners.<br \/>\r\nAlways there for you.<\/h1>\n                                                                                                            <\/div>\n                        <\/div>\n                                                    <div class=\"row\">\n                                <div class=\"col-12 col-lg-9\">\n                                    <div class=\"text\">\n                                        <p>You will find a selection of professional addi retail partners here.<\/p>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n                <div class=\"col-12 col-lg-4 order-1\">\n                    <div class=\"image-wrapper\">\n                                                    <img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"693\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/05\/Cursor_Kontrast-e1651683724163-768x831.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/05\/Cursor_Kontrast-e1651683724163-768x831.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/05\/Cursor_Kontrast-e1651683724163-1419x1536.png 1419w, https:\/\/addi.de\/wp-content\/uploads\/2022\/05\/Cursor_Kontrast-e1651683724163-1893x2048.png 1893w, https:\/\/addi.de\/wp-content\/uploads\/2022\/05\/Cursor_Kontrast-e1651683724163-1320x1428.png 1320w, https:\/\/addi.de\/wp-content\/uploads\/2022\/05\/Cursor_Kontrast-e1651683724163-600x649.png 600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>                                            <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"row\">\n                <div class=\"col-12 col-lg-3 offset-lg-4\">\n                    <div class=\"share-links\">\n                        <span>Teilen:<\/span>\n                        <a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Faddi.de%2Fen%2Fonline-haendler%2F\" class=\"d-inline-block px-2\" onclick=\"window.open(this.href, 'mywin', 'left=20,top=20,width=500,height=500,toolbar=1,resizable=0'); return false;\"><i class=\"fab fa-facebook-f hl-color\"><\/i><\/a>\n                        <a href=\"https:\/\/twitter.com\/intent\/tweet?text=https%3A%2F%2Faddi.de%2Fen%2Fonline-haendler%2F\" class=\"d-inline-block px-2\" onclick=\"window.open(this.href, 'mywin', 'left=20,top=20,width=500,height=500,toolbar=1,resizable=0'); return false;\"><i class=\"fa-brands fa-x-twitter hl-color\"><\/i><\/a>\n                    <\/div>\n                <\/div>\n                <div class=\"col-12 col-lg-3 offset-lg-1\">\n                    <div class=\"toc-wrapper\">\n                        <div class=\"toc-title\">\n                            Inhaltsverzeichnis                        <\/div>\n                        <div class=\"toc-content\">\n\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<\/div>\n\n\n\n<div id=\"dealer-block_ff4856ca51274a13bb60bc59a5d41dc9\" class=\"dealer\" >\n    <section>\n        <div class=\"container\">\n\n                                <div class=\"row mb-4 justify-content-center\">                                                <div class=\"col-12 col-lg-9 order-2 order-lg-1\">\n                            <div class=\"dealer-search-wrapper\" data-variant=\"online\" data-search-alt=\"43215 USA\">\n                                <label for=\"dealer-dealer-block_ff4856ca51274a13bb60bc59a5d41dc9\">\n                                    <input class=\"dealer-search-input\" type=\"text\" id=\"dealer-dealer-block_ff4856ca51274a13bb60bc59a5d41dc9\" placeholder=\"H\u00e4ndlersuche f\u00fcr 43215\">\n                                <\/label>\n                                                                <div class=\"dealer-search\" data-target=\"#dealer-dealer-block_ff4856ca51274a13bb60bc59a5d41dc9\">\n                                    <i class=\"far fa-search\"><\/i>\n                                <\/div>\n                                <div class=\"dealer-search-reset ml-3\">\n                                    <i class=\"fa-solid fa-arrow-rotate-right\"><\/i>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"col-12 col-lg-3 order-1 order-lg-2 mb-4 mb-lg-0\">                                                            <a href='https:\/\/addi.de\/en\/haendlersuche\/' target='_self' class='buttonlink prio-1'>Retailer near you.<\/a>                                                    <\/div>\n                    <\/div>\n                    <div class=\"row\">\n                        <div class=\"col-12 dealer-wrapper\" data-target=\"#dealer-dealer-block_ff4856ca51274a13bb60bc59a5d41dc9\" data-no-translation=\"\">\n                                                            <div class=\"row\">\n                                <div id=\"post-23372\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                A\/s Villy Jensen                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                8270  H\u00f8jbjerg            <\/div>\n                            <div class=\"contact\">\n                Denmark, Sweden, Norway, Iceland, Faeroe Island, Greenland            <\/div>\n                            <div class=\"phone\">\n                +4586274711            <\/div>\n                            <div class=\"phone\">\n                Please contact the wholesaler.             <\/div>\n                            <div class=\"email\">\n                &#118;&#x69;llyjensen&#64;vi&#108;lyje&#x6e;se&#110;&#x2e;dk            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/villyjensen.dk\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+4586274711\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22836\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Alpaka                            <\/div>\n                \n                    <div class=\"contact\">\n                Birgit Hennes-Schaab            <\/div>\n                            <div class=\"city-zipcode\">\n                64646 Heppenheim            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                06252-2889            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.alpaka-online.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:06252-2889\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22937\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Ariadne Wolle                            <\/div>\n                \n                    <div class=\"contact\">\n                Brigitte Schulz            <\/div>\n                            <div class=\"city-zipcode\">\n                95632 Wunsiedel            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                09232-9158600            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/ssl.webpack.de\/ariadnewolle.de\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:09232-9158600\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-67788\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                ArtYarn UK                            <\/div>\n                \n                    <div class=\"contact\">\n                Richard Sparrow            <\/div>\n                            <div class=\"city-zipcode\">\n                LE67 8FB Coleorton            <\/div>\n                            <div class=\"contact\">\n                Gro\u00dfbritannien            <\/div>\n                                \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"www.artyarn.co.uk\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                            <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-24476\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                ASox\u2019n more                            <\/div>\n                \n                    <div class=\"contact\">\n                Anja Schneider            <\/div>\n                            <div class=\"city-zipcode\">\n                35685 Dillenburg            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0049 2771 812925            <\/div>\n                                    <div class=\"email\">\n                info&#64;&#97;s&#x6f;xnmore&#46;&#x64;e            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.asoxnmore.de\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0049 2771 812925\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-38770\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Atelier amiQs                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                03-431  Warszawa            <\/div>\n                            <div class=\"contact\">\n                Polen            <\/div>\n                            <div class=\"phone\">\n                +48 664 257 285            <\/div>\n                                    <div class=\"email\">\n                &#x6b;&#x6f;ntakt&#x40;amiq&#x73;&#46;pl            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.amiqs.pl\/category\/akcesoria-addi\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+48 664 257 285\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-57060\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Beijing Yinan Trading Co., Ltd.                             <\/div>\n                \n                    <div class=\"contact\">\n                Xiahua Qi             <\/div>\n                            <div class=\"city-zipcode\">\n                13636 Beijing            <\/div>\n                            <div class=\"contact\">\n                China            <\/div>\n                            <div class=\"phone\">\n                0086 010 60899272            <\/div>\n                            <div class=\"phone\">\n                0086 13683699070            <\/div>\n                            <div class=\"email\">\n                k&#x69;ngfi&#x73;h&#x65;rya&#x72;n&#x40;sina&#x2e;com            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"www.cuiniaosha.tmall.com\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0086 010 60899272\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22855\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                C-Fashion                            <\/div>\n                \n                    <div class=\"contact\">\n                Cornelia Schmidt            <\/div>\n                            <div class=\"city-zipcode\">\n                68723 Plankstadt            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                06202-924848            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.c-fashion.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:06202-924848\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22856\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                C-Fashion                            <\/div>\n                \n                    <div class=\"contact\">\n                Cornelia Schmidt            <\/div>\n                            <div class=\"city-zipcode\">\n                68782 Br\u00fchl            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                06202-1276446            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.c-fashion.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:06202-1276446\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22664\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Country-Creativ                            <\/div>\n                \n                    <div class=\"contact\">\n                Kosima Kr\u00fcger            <\/div>\n                            <div class=\"city-zipcode\">\n                16866 Kyritz            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                033971-32870            <\/div>\n                                    <div class=\"email\">\n                sh&#x6f;p&#x40;coun&#x74;ry-c&#114;eat&#105;v&#x2e;de            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/country-creativ.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:033971-32870\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-55265\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Dein-Wollshop   Emmerich &amp; Emmerich GbR                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                45894 Gelsenkirchen            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0049 209 51304583            <\/div>\n                                    <div class=\"email\">\n                in&#102;&#111;&#x40;dei&#110;-&#x77;ollsh&#111;&#x70;&#46;d&#101;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"www.dein-wollshop.de\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0049 209 51304583\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22713\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Dibadu alles in Wolle                            <\/div>\n                \n                    <div class=\"contact\">\n                Barbara Wolff            <\/div>\n                            <div class=\"city-zipcode\">\n                32805 Horn-Bad Meinberg            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                05234-2061841            <\/div>\n                                    <div class=\"email\">\n                kontakt&#x40;di&#x62;adu&#x2e;d&#x65;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.dibadu.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:05234-2061841\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22736\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Die Nadelzeile GmbH                            <\/div>\n                \n                    <div class=\"contact\">\n                Ulrike Germroth            <\/div>\n                            <div class=\"city-zipcode\">\n                37287 Wehretal            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                05651-740830            <\/div>\n                                    <div class=\"email\">\n                shop&#x40;n&#x61;de&#108;zeile&#x2e;d&#101;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.nadelzeile.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:05651-740830\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22708\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Die WollBox                            <\/div>\n                \n                    <div class=\"contact\">\n                Katja Manthey            <\/div>\n                            <div class=\"city-zipcode\">\n                30989 Gehrden            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                05108-6090942            <\/div>\n                                    <div class=\"email\">\n                inf&#111;&#64;wollbox&#46;&#x64;e            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wollbox.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:05108-6090942\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22991\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                e-dziewiarka                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                50-221 Wroclaw            <\/div>\n                            <div class=\"contact\">\n                Poland            <\/div>\n                            <div class=\"phone\">\n                +48 533 32 54 40            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.e-dziewiarka.pl\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+48 533 32 54 40\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22992\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                e-dziewiarka                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                90-743 Lodz            <\/div>\n                            <div class=\"contact\">\n                Poland            <\/div>\n                            <div class=\"phone\">\n                +48 422 88 11 18            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.e-dziewiarka.pl\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+48 422 88 11 18\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22993\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                e-dziewiarka                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                31-039 Krakow            <\/div>\n                            <div class=\"contact\">\n                Poland            <\/div>\n                            <div class=\"phone\">\n                +48 124 44 67 80            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.e-dziewiarka.pl\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+48 124 44 67 80\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-54546\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Elas Masche                            <\/div>\n                \n                    <div class=\"contact\">\n                Manuela Sapel            <\/div>\n                            <div class=\"city-zipcode\">\n                56242 Selter            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0049 176 74791795            <\/div>\n                                    <div class=\"email\">\n                i&#110;f&#111;&#x40;el&#x61;smasch&#x65;&#x2e;&#x64;e            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"www.elasmasche.de\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0049 176 74791795\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22789\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                elin-wolleundmehr                            <\/div>\n                \n                    <div class=\"contact\">\n                Elke Linke            <\/div>\n                            <div class=\"city-zipcode\">\n                53773 Hennef            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                02248-9005500            <\/div>\n                                    <div class=\"email\">\n                elk&#x65;&#x2e;linke&#64;we&#98;&#x2e;de            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.elin-wolleundmehr.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:02248-9005500\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-54321\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Espace Tricot                            <\/div>\n                \n                    <div class=\"contact\">\n                Naomi Endicott            <\/div>\n                            <div class=\"city-zipcode\">\n                H4A 1H2 Montreal, Quebec            <\/div>\n                            <div class=\"contact\">\n                Kanada            <\/div>\n                            <div class=\"phone\">\n                001 514 4865648            <\/div>\n                                    <div class=\"email\">\n                &#x63;o&#110;tac&#116;&#x40;&#x65;&#x73;&#x70;a&#99;etricot&#x2e;com            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"www.espacetricot.com\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:001 514 4865648\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22982\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                fabulousyarn                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                12583 Tivoli, New York            <\/div>\n                            <div class=\"contact\">\n                USA            <\/div>\n                            <div class=\"phone\">\n                (844)233-8163            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.fabulousyarn.com\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:(844)233-8163\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22910\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Filati Retail GmbH                            <\/div>\n                \n                    <div class=\"contact\">\n                Norbert Lutz            <\/div>\n                            <div class=\"city-zipcode\">\n                89257 Illertissen            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                07303-9291340            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.meinfilati.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:07303-9291340\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22629\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Fingerhut                            <\/div>\n                \n                    <div class=\"contact\">\n                Petra Scheibe            <\/div>\n                            <div class=\"city-zipcode\">\n                04275 Leipzig            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0341-3017680            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                                                    <a href=\"tel:0341-3017680\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22648\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Fitz&#038;Triefel Kreative Handarbeit                            <\/div>\n                \n                    <div class=\"contact\">\n                Antje Busse            <\/div>\n                            <div class=\"city-zipcode\">\n                09366 Stollberg            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                037296-939586            <\/div>\n                                    <div class=\"email\">\n                info&#x40;fit&#x7a;-und-tr&#105;efel&#46;&#100;e            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.fitz-und-triefel.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:037296-939586\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22669\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Garntante                            <\/div>\n                \n                    <div class=\"contact\">\n                Andreas Schmaddebeck            <\/div>\n                            <div class=\"city-zipcode\">\n                21031 Hamburg            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                040-52161312            <\/div>\n                                    <div class=\"email\">\n                kontak&#116;&#x40;gar&#x6e;tante&#46;&#100;e            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.garntante.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:040-52161312\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-34304\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                gemachtmitliebe \u2013 Yarns &amp; Colours                            <\/div>\n                \n                    <div class=\"contact\">\n                Daniela Warndorf            <\/div>\n                            <div class=\"city-zipcode\">\n                50939  K\u00f6ln            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0221-355 337 925            <\/div>\n                                    <div class=\"email\">\n                &#x68;allo&#64;ge&#109;achtmitliebe&#x2e;&#100;e            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.gemachtmitliebe.de\/produkt-kategorie\/zubehoer\/zubehoer-hersteller\/addi\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0221-355 337 925\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-34660\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                handarbeitswaren.de                             <\/div>\n                \n                            <div class=\"city-zipcode\">\n                28199 Bremen            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0421 8492500            <\/div>\n                                    <div class=\"email\">\n                m&#x61;il&#x40;&#x68;a&#x6e;&#x64;arb&#101;&#x69;&#x74;s&#119;aren&#46;&#100;&#x65;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.handarbeitswaren.de\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0421 8492500\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22978\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Handarbeitszentrum Blaufelden, Inh. Nora Sch\u00f6nemann                            <\/div>\n                \n                    <div class=\"contact\">\n                Volker Sch\u00f6nemann            <\/div>\n                            <div class=\"city-zipcode\">\n                74572 Blaufelden            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                07953-925150            <\/div>\n                                    <div class=\"email\">\n                &#110;o&#x72;a&#46;s&#x63;hoenemann&#64;&#x68;andarb&#101;itszentr&#117;m&#x2e;de            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.strumpfwolle.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:07953-925150\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22839\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                handgemacht                            <\/div>\n                \n                    <div class=\"contact\">\n                Annegret Stollenwerk            <\/div>\n                            <div class=\"city-zipcode\">\n                65191 Wiesbaden            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0611-1744133            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.handgemacht-wolle.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0611-1744133\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-53096\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Heritage Knits Australia                            <\/div>\n                \n                    <div class=\"contact\">\n                Tamhas Buchan            <\/div>\n                            <div class=\"city-zipcode\">\n                3437 Gisborne, Victoria            <\/div>\n                            <div class=\"contact\">\n                Australien            <\/div>\n                                            <div class=\"email\">\n                &#105;nfo&#x40;&#x68;eri&#x74;&#x61;geknits&#46;c&#111;m            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/heritageknits.com\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                            <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-53097\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Heritage Knits China                            <\/div>\n                \n                    <div class=\"contact\">\n                Tamhas Buchan            <\/div>\n                            <div class=\"city-zipcode\">\n                610213 Chengdu City            <\/div>\n                            <div class=\"contact\">\n                China            <\/div>\n                                            <div class=\"email\">\n                info&#x40;heritag&#x65;kn&#x69;&#116;s&#46;co&#x6d;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/heritageknits.com\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                            <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22645\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Hobby Welt Kreativ                            <\/div>\n                \n                    <div class=\"contact\">\n                Sabine G\u00f6thel            <\/div>\n                            <div class=\"city-zipcode\">\n                09111 Chemnitz            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0371-41440            <\/div>\n                                    <div class=\"email\">\n                &#x73;hop&#x40;ho&#98;&#98;y-we&#108;t-kre&#97;t&#105;v&#46;de            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.hobbyweltkreativ.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0371-41440\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22837\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Islandwolle                            <\/div>\n                \n                    <div class=\"contact\">\n                Tina Schivelbusch            <\/div>\n                            <div class=\"city-zipcode\">\n                64839 M\u00fcnster b. Dieburg            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                06071-66619            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.islandwolle.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:06071-66619\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-33777\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                JaWolle                            <\/div>\n                \n                    <div class=\"contact\">\n                Dominik Jan\u00dfen            <\/div>\n                            <div class=\"city-zipcode\">\n                66113 Saarbr\u00fccken            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0049 (0) 681 686 1975            <\/div>\n                                    <div class=\"email\">\n                service&#x40;jawol&#x6c;e&#46;com            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.jawolle.de\/addi\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0049 (0) 681 686 1975\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22960\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                KreativHotelB &amp; ArianeB OHG                            <\/div>\n                \n                    <div class=\"contact\">\n                Ariane Bott            <\/div>\n                            <div class=\"city-zipcode\">\n                23611 Sereetz            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0049 451 30489887            <\/div>\n                            <div class=\"phone\">\n                0049 176 3659826            <\/div>\n                            <div class=\"email\">\n                &#97;ri&#97;ne&#98;&#x40;a&#114;&#x69;aneb&#x2e;d&#101;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"www.kreativHotelB.de\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0049 451 30489887\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22871\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                La Socke                            <\/div>\n                \n                    <div class=\"contact\">\n                Laila Wagner            <\/div>\n                            <div class=\"city-zipcode\">\n                73098 Rechberghausen            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                07161-9163500            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/la-socke.eshop.t-online.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:07161-9163500\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-38768\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Lanatus d.o.o.                            <\/div>\n                \n                    <div class=\"contact\">\n                Barbara Wogrin            <\/div>\n                            <div class=\"city-zipcode\">\n                1000 Ljubljana            <\/div>\n                            <div class=\"contact\">\n                Slowenien            <\/div>\n                            <div class=\"phone\">\n                00386 41380353            <\/div>\n                                    <div class=\"email\">\n                infol&#97;natus&#64;gm&#x61;il&#x2e;com            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/lanatus.si\/page-all\/ \" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:00386 41380353\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-24064\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                LANG &#038; CO. AG                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                6260 Reiden            <\/div>\n                            <div class=\"contact\">\n                Switzerland            <\/div>\n                            <div class=\"phone\">\n                041 6274 90115            <\/div>\n                            <div class=\"phone\">\n                Please contact the wholesaler.             <\/div>\n                            <div class=\"email\">\n                &#105;&#x6e;fo&#x40;langya&#114;n&#x73;&#46;com            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.langyarns.com\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:041 6274 90115\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-36479\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Laughing Hens &#8211; Great Britain                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                Great Barrow Cheshire CH3 7JN, UK            <\/div>\n                            <div class=\"contact\">\n                Gro\u00dfbritannien            <\/div>\n                            <div class=\"phone\">\n                01829 740903            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.laughinghens.com\/ \" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:01829 740903\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-54308\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Leandros Vassiloglou S.A.                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                54625 Thessaloniki            <\/div>\n                            <div class=\"contact\">\n                Griechenland            <\/div>\n                            <div class=\"phone\">\n                0030 2310 530845            <\/div>\n                            <div class=\"phone\">\n                Please contact the wholesaler.            <\/div>\n                            <div class=\"email\">\n                va&#115;&#x73;iloglo&#x75;&#64;&#x61;&#x6c;lama&#110;is&#x2e;g&#114;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                                                    <a href=\"tel:0030 2310 530845\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-34361\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Liebste Wolle &#8211; (nur mit Termin)                            <\/div>\n                \n                    <div class=\"contact\">\n                Kerstin Noatzsch &#8211; bitte Besuchstermin manchen            <\/div>\n                            <div class=\"city-zipcode\">\n                99099 Erfurt            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0361 34199074            <\/div>\n                            <div class=\"phone\">\n                0152 01592191            <\/div>\n                            <div class=\"email\">\n                &#x6c;ieb&#x73;tewol&#108;e&#x40;f&#97;d&#x65;n&#102;re&#x75;&#x6e;&#x64;&#x2e;d&#101;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"www.fadenfreund.de\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0361 34199074\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22980\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Makers Mercantile                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                98032 Kent, WA            <\/div>\n                            <div class=\"contact\">\n                USA            <\/div>\n                            <div class=\"phone\">\n                (206) 747-7121            <\/div>\n                                    <div class=\"email\">\n                he&#108;&#x6c;o&#64;&#x6d;akersmer&#x63;&#97;nti&#108;&#101;&#x2e;&#x63;om            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.makersmercantile.com\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:(206) 747-7121\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22730\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Martinas Bastel- &amp; Hobbykiste                            <\/div>\n                \n                    <div class=\"contact\">\n                Martina Schimbach            <\/div>\n                            <div class=\"city-zipcode\">\n                35796 Blessenbach            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                06474-882816            <\/div>\n                                    <div class=\"email\">\n                inf&#111;&#x40;b&#97;stelun&#100;hobb&#121;k&#x69;s&#116;e&#46;de            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.bastelundhobbykiste.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:06474-882816\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22965\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Maschenprobe                            <\/div>\n                \n                    <div class=\"contact\">\n                Andrea Johanna R\u00f6sner            <\/div>\n                            <div class=\"city-zipcode\">\n                45525 Hattingen            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                02324 6845668            <\/div>\n                                    <div class=\"email\">\n                in&#102;o&#x40;maschen&#112;&#x72;obe-ha&#x74;tingen&#46;d&#101;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.maschenprobe-hattingen.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:02324 6845668\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-72122\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                MaterialShopHandwerk                            <\/div>\n                \n                    <div class=\"contact\">\n                Susanne Neuhaus-Schmitz            <\/div>\n                            <div class=\"city-zipcode\">\n                50169 Kerpen            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0049 1577 6650246            <\/div>\n                            <div class=\"phone\">\n                0049 1577 6650246            <\/div>\n                            <div class=\"email\">\n                inf&#111;&#x40;mat&#101;r&#x69;a&#108;s&#x68;op&#x68;a&#110;dwerk&#x2e;&#100;e            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"www.materialshophandwerk.de\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0049 1577 6650246\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-55455\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                McIntosh                            <\/div>\n                \n                    <div class=\"contact\">\n                James McIntosh            <\/div>\n                            <div class=\"city-zipcode\">\n                SE15 5NR London            <\/div>\n                            <div class=\"contact\">\n                England            <\/div>\n                                            <div class=\"email\">\n                cla&#110;&#64;knit&#x6d;cin&#116;&#x6f;&#115;h&#46;&#x63;om            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/shop.knitmcintosh.com\/?utm_source=addi&#038;utm_medium=referral&#038;utm_campaign=retailer_links\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                            <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-33934\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Mein Wollstudio                            <\/div>\n                \n                    <div class=\"contact\">\n                Andrea Klink            <\/div>\n                            <div class=\"city-zipcode\">\n                71522 Backnang            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                07191-911 1630            <\/div>\n                                    <div class=\"email\">\n                &#x69;nfo&#64;&#109;ein-wollstudi&#x6f;&#46;d&#101;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\\\\www.mein-wollstudio.de\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:07191-911 1630\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22832\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Mone&#8217;s Wolleparadies                            <\/div>\n                \n                    <div class=\"contact\">\n                Simone Otto            <\/div>\n                            <div class=\"city-zipcode\">\n                63834 Sulzbach            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                06028-8077949            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.moneswolleparadies.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:06028-8077949\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-51897\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                N\u00e4hoase                            <\/div>\n                \n                    <div class=\"contact\">\n                Nicole Neitzel            <\/div>\n                            <div class=\"city-zipcode\">\n                66780 Rehlingen &#8211; Siersburg            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0 6835 6087942            <\/div>\n                                    <div class=\"email\">\n                i&#110;f&#111;&#64;na&#101;ho&#97;&#x73;e&#46;&#100;e            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"www.n\u00e4hoase.de\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0 6835 6087942\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22643\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                N\u00e4hst\u00fcbel Bromnitz                            <\/div>\n                \n                    <div class=\"contact\">\n                Heike Bromnitz            <\/div>\n                            <div class=\"city-zipcode\">\n                08523 Plauen            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                03741-221316            <\/div>\n                                    <div class=\"email\">\n                s&#x65;r&#x76;ic&#x65;&#64;kurzwa&#114;en-pr&#111;f&#105;&#46;&#x64;e            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.kurzwaren-profi.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:03741-221316\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22767\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Nature\u00b4s Luxury                            <\/div>\n                \n                    <div class=\"contact\">\n                Danica M\u00e4der-Jully            <\/div>\n                            <div class=\"city-zipcode\">\n                48369 Saerbeck            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                02572-9239808            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.naturesluxury.com\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:02572-9239808\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-38769\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Pasmanteria amiQs                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                02-222  Warszawa            <\/div>\n                            <div class=\"contact\">\n                Polen            <\/div>\n                            <div class=\"phone\">\n                +48 606 203 820            <\/div>\n                                    <div class=\"email\">\n                kont&#x61;kt&#64;ami&#113;s&#x2e;&#x70;&#x6c;             <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.amiqs.pl\/category\/akcesoria-addi\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+48 606 203 820\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22696\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Philipp N\u00e4hmaschinen                            <\/div>\n                \n                    <div class=\"contact\">\n                Dirk Sturtz            <\/div>\n                            <div class=\"city-zipcode\">\n                27283 Verden            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                04231-3531            <\/div>\n                                    <div class=\"email\">\n                &#x4e;aehmaschin&#101;n-Philipp&#x2d;Ver&#100;en&#64;&#x74;-o&#110;li&#110;e&#x2e;de            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.naehplatz.de\/Stricknadeln\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:04231-3531\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-24060\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Pletu.cz                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                62400 Brno            <\/div>\n                            <div class=\"contact\">\n                Czech Republic            <\/div>\n                            <div class=\"phone\">\n                +420723411800            <\/div>\n                                    <div class=\"email\">\n                i&#x6e;fo&#64;ple&#116;u&#x2e;c&#122;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.pletu.cz\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+420723411800\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-23563\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Reginas N\u00e4hzubeh\u00f6r                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                1020 Wien            <\/div>\n                            <div class=\"contact\">\n                \u00d6sterreich            <\/div>\n                            <div class=\"phone\">\n                043 1 2148744            <\/div>\n                                    <div class=\"email\">\n                &#x6f;ffi&#x63;e&#64;reginas&#45;na&#x65;hzubeho&#x65;r&#46;at            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.reginas-naehzubehoer.at \" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:043 1 2148744\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22785\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Rias Laden GbR                            <\/div>\n                \n                    <div class=\"contact\">\n                Regina Schlimgen + Michael Schwarz-Winnekes            <\/div>\n                            <div class=\"city-zipcode\">\n                53424  Remagen            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                02642\/9919111            <\/div>\n                                    <div class=\"email\">\n                &#114;ia&#115;&#x2d;la&#100;en&#x40;direct&#x62;ox&#46;co&#x6d;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wolle-wachtberg.de\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:02642\/9919111\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22741\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Rikes Wollmaus                            <\/div>\n                \n                    <div class=\"contact\">\n                Ulrike J\u00f6decke            <\/div>\n                            <div class=\"city-zipcode\">\n                37431 Bad Lauterberg            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                05521-9978800            <\/div>\n                                    <div class=\"email\">\n                &#105;n&#x66;o&#x40;rikes-w&#x6f;&#108;&#108;m&#97;us&#x2e;d&#x65;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"www.rikes-wollmaus.de\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:05521-9978800\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-23395\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Sandnes Garn                             <\/div>\n                \n                            <div class=\"city-zipcode\">\n                4301  Sandnes            <\/div>\n                            <div class=\"contact\">\n                Norway            <\/div>\n                            <div class=\"phone\">\n                +47 51608628            <\/div>\n                            <div class=\"phone\">\n                Please have a look at the dealer directory of our wholesaler.            <\/div>\n                            <div class=\"email\">\n                pos&#x74;&#64;&#x73;and&#x6e;e&#115;g&#97;&#114;&#x6e;&#46;no            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.sandnesgarn.no\/forhandlere?lat=65.297237&#038;lng=18.016939&#038;zoom=3.68\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+47 51608628\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22966\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Selfmade Berlin                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                12103 Berlin            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                04101-6019050            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stoffundstil.de\/fraya\/zubehor\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:04101-6019050\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22866\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                SEW Shop                            <\/div>\n                \n                    <div class=\"contact\">\n                Olga Dunaeva            <\/div>\n                            <div class=\"city-zipcode\">\n                71088 Holzgerlingen            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                                \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"http:\/\/sew-shop.com\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                            <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-24063\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Skacel Collection, Inc.                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                98032 Kent WA            <\/div>\n                            <div class=\"contact\">\n                Canada, USA            <\/div>\n                            <div class=\"phone\">\n                (425) 291-9600            <\/div>\n                            <div class=\"phone\">\n                Please contact the wholesaler.             <\/div>\n                            <div class=\"email\">\n                i&#x6e;f&#111;&#x40;skacelknit&#x74;ing&#46;com            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.skacelknitting.com\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:(425) 291-9600\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-36480\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                SMD Knitting &#8211; Great Britain                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                Llay, Wrexham LL12 0PJ, UK            <\/div>\n                            <div class=\"contact\">\n                Great Britain            <\/div>\n                            <div class=\"phone\">\n                0800 622 6225            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.knittingwool.com\/ \" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0800 622 6225\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-32247\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Soul Wool                             <\/div>\n                \n                    <div class=\"contact\">\n                Britta Kremke            <\/div>\n                            <div class=\"city-zipcode\">\n                19372 Matzlow-Garwitz            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                +49-(0)38722-227-22            <\/div>\n                                    <div class=\"email\">\n                o&#114;der&#x40;sou&#x6c;-wo&#111;l&#46;com            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"www.soul-wool.com\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+49-(0)38722-227-22\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22987\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stof &#038; Stil\/Selfmade I Aalborg                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                9200 Aalborg SV            <\/div>\n                            <div class=\"contact\">\n                Denmark            <\/div>\n                            <div class=\"phone\">\n                +45 70 22 21 21            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stofogstil.dk\/fraya\/tilbehoer\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+45 70 22 21 21\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22986\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stof &#038; Stil\/Selfmade I Aarhus                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                8381 Tilst            <\/div>\n                            <div class=\"contact\">\n                Denmark            <\/div>\n                            <div class=\"phone\">\n                +45 70 22 21 21            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stofogstil.dk\/fraya\/tilbehoer\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+45 70 22 21 21\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22984\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stof &#038; Stil\/Selfmade I Esbjerg                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                6715 Esbjerg            <\/div>\n                            <div class=\"contact\">\n                Denmark            <\/div>\n                            <div class=\"phone\">\n                +45 70 22 21 21            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stofogstil.dk\/fraya\/tilbehoer\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+45 70 22 21 21\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22983\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stof &#038; Stil\/Selfmade I Herning                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                7400 Herning            <\/div>\n                            <div class=\"contact\">\n                Denmark            <\/div>\n                            <div class=\"phone\">\n                +45 70 22 21 21            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stofogstil.dk\/fraya\/tilbehoer\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+45 70 22 21 21\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22990\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stof &#038; Stil\/Selfmade I K\u00f8benhavn                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                1620 K\u00f8benhavn            <\/div>\n                            <div class=\"contact\">\n                Denmark            <\/div>\n                            <div class=\"phone\">\n                +45 70 22 21 21            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stofogstil.dk\/fraya\/tilbehoer\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+45 70 22 21 21\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22988\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stof &#038; Stil\/Selfmade I Odense                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                5000 Odense C            <\/div>\n                            <div class=\"contact\">\n                Denmark            <\/div>\n                            <div class=\"phone\">\n                +45 70 22 21 21            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stofogstil.dk\/fraya\/tilbehoer\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+45 70 22 21 21\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22989\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stof &#038; Stil\/Selfmade I Roskilde                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                4000 Roskilde            <\/div>\n                            <div class=\"contact\">\n                Denmark            <\/div>\n                            <div class=\"phone\">\n                +45 70 22 21 21            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stofogstil.dk\/fraya\/tilbehoer\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+45 70 22 21 21\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22985\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stof &#038; Stil\/Selfmade I S\u00f8nderborg                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                6400 S\u00f8nderborg            <\/div>\n                            <div class=\"contact\">\n                Denmark            <\/div>\n                            <div class=\"phone\">\n                +45 70 22 21 21            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stofogstil.dk\/fraya\/tilbehoer\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+45 70 22 21 21\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22968\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stoff &#038; Stil\/Selfmade Bremen                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                28816 Stuhr            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                04101-6019050            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stoffundstil.de\/fraya\/zubehor\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:04101-6019050\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22972\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stoff &#038; Stil\/Selfmade Hamburg                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                25469 Halstenbek            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                04101-6019050            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stoffundstil.de\/fraya\/zubehor\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:04101-6019050\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22967\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stoff &#038; Stil\/Selfmade Hannover                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                30519 Hannover            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                04101-6019050            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stoffundstil.de\/fraya\/zubehor\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:04101-6019050\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22970\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stoff &#038; Stil\/Selfmade K\u00f6ln                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                50667 K\u00f6ln            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                04101-6019050            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stoffundstil.de\/fraya\/zubehor\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:04101-6019050\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22971\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stoff &#038; Stil\/Selfmade L\u00fcbeck                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                23569 L\u00fcbeck            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                04101-6019050            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stoffundstil.de\/fraya\/zubehor\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:04101-6019050\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22973\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stoff &#038; Stil\/Selfmade M\u00fcnchen                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                80939 M\u00fcnchen            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                04101-6019050            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stoffundstil.de\/fraya\/zubehor\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:04101-6019050\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22969\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stoff &#038; Stil\/Selfmade Rhein-Main                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                64331 Weiterstadt            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                04101-6019050            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stoffundstil.de\/fraya\/zubehor\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:04101-6019050\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22974\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stoff &#038; Still\/Selfmade Dortmund                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                44149 Dortmund            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                04101-6019050            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.stoffundstil.de\/fraya\/zubehor\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:04101-6019050\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22768\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Stoff &#038; Wollparadies                            <\/div>\n                \n                    <div class=\"contact\">\n                Sven Wiggers            <\/div>\n                            <div class=\"city-zipcode\">\n                48703 Stadtlohn            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                02563-207070            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.s-w-stoffe.com\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:02563-207070\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22745\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Strick &#038; N\u00e4hcafe                            <\/div>\n                \n                    <div class=\"contact\">\n                Cornelia R\u00fcdiger            <\/div>\n                            <div class=\"city-zipcode\">\n                39104 Magdeburg            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0391-50387198            <\/div>\n                                    <div class=\"email\">\n                &#x69;n&#x66;o&#64;&#115;t&#114;&#105;ck&#45;naehca&#102;e&#46;de            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.strick-naehcafe.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0391-50387198\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22892\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Strickpunkt                            <\/div>\n                \n                    <div class=\"contact\">\n                Karin Leonhart            <\/div>\n                            <div class=\"city-zipcode\">\n                82418 Murnau            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                08841-4874597            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.strickpunkt.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:08841-4874597\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-30628\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Style and Concept GmbH Wolle und Mehr                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                73079  S\u00fcssen            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                07162 9305060             <\/div>\n                                    <div class=\"email\">\n                outle&#x74;&#64;s&#116;&#121;l&#101;-and-conce&#x70;&#116;&#x2e;d&#101;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/wolle-suessen.de\/zusatzsortiment\/stricknadeln\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:07162 9305060 \" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22627\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Textilst\u00fcbchen                            <\/div>\n                \n                    <div class=\"contact\">\n                Susanne Franke            <\/div>\n                            <div class=\"city-zipcode\">\n                04155 Leipzig            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0341-5648630            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                                                    <a href=\"tel:0341-5648630\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22753\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                tinkus-strickparadies.de                            <\/div>\n                \n                    <div class=\"contact\">\n                Martina Betz            <\/div>\n                            <div class=\"city-zipcode\">\n                44143 Dortmund            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0231-561942            <\/div>\n                                    <div class=\"email\">\n                wolle&#64;tin&#x6b;us-s&#116;ri&#x63;kpa&#114;&#x61;d&#105;&#101;s&#x2e;de            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.tinkus-strickparadies.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0231-561942\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22981\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Twitchy Hands Creative                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                97370 Philomath OR            <\/div>\n                            <div class=\"contact\">\n                USA            <\/div>\n                                            <div class=\"email\">\n                &#x68;el&#x6c;o&#64;twit&#x63;&#x68;yha&#x6e;ds&#46;com            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/twitchyhands.com\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                            <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22940\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                umgarnt                            <\/div>\n                \n                    <div class=\"contact\">\n                Kristina Hackert            <\/div>\n                            <div class=\"city-zipcode\">\n                96450 Coburg            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                09561-7958133            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.umgarnt.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:09561-7958133\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22750\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wernick Handarbeiten                            <\/div>\n                \n                    <div class=\"contact\">\n                Stefanie  Wernick            <\/div>\n                            <div class=\"city-zipcode\">\n                42275 Wuppertal            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0202-593402            <\/div>\n                                    <div class=\"email\">\n                kon&#x74;akt&#64;w&#x65;&#x72;ni&#99;k-wolle&#45;&#119;upper&#x74;al&#x2e;d&#101;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wernick-wolle-wuppertal.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0202-593402\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-37091\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Woli-Versand                            <\/div>\n                \n                    <div class=\"contact\">\n                Waldemar Weber            <\/div>\n                            <div class=\"city-zipcode\">\n                08527 Plauen            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                                    <div class=\"phone\">\n                01629214074            <\/div>\n                            <div class=\"email\">\n                &#x77;&#x6f;li&#x2e;ver&#x73;a&#x6e;d14&#64;gm&#97;i&#x6c;&#x2e;co&#x6d;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.woli-versand.de\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                            <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22899\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Woll-Oase und Otto Shop                            <\/div>\n                \n                    <div class=\"contact\">\n                Gabriele Hofmeister            <\/div>\n                            <div class=\"city-zipcode\">\n                83395 Freilassing            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                08654-66344            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.woll-oase-freilassing.com\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:08654-66344\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22921\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Woll-und Strickstudio                            <\/div>\n                \n                    <div class=\"contact\">\n                Ruth Kindla            <\/div>\n                            <div class=\"city-zipcode\">\n                90480 N\u00fcrnberg            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0911-400657            <\/div>\n                                    <div class=\"email\">\n                In&#x66;o&#x40;&#119;olle-k&#x69;&#x6e;dl&#x61;&#46;de            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wolle-kindla.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0911-400657\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22678\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wolland                            <\/div>\n                \n                    <div class=\"contact\">\n                Inge Zei\u00dfler            <\/div>\n                            <div class=\"city-zipcode\">\n                22880 Wedel            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                04103-180455            <\/div>\n                                    <div class=\"email\">\n                info&#64;wo&#108;land&#x2e;&#x64;e            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wolland.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:04103-180455\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22769\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wolle &#038; Design                            <\/div>\n                \n                    <div class=\"contact\">\n                Maria Weddewer            <\/div>\n                            <div class=\"city-zipcode\">\n                48703 Stadtlohn            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                02563-98208            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wolleunddesign.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:02563-98208\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-32254\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wolle im Hof                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                55218 Ingelheim            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                +49 (0)6132 718844            <\/div>\n                                    <div class=\"email\">\n                info&#64;&#119;&#111;lle&#x69;m&#104;&#111;&#x66;&#46;de            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"www.wolleimhof.de\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+49 (0)6132 718844\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-32255\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wolle im Quadrat                            <\/div>\n                \n                    <div class=\"contact\">\n                Astrid Kirch            <\/div>\n                            <div class=\"city-zipcode\">\n                68161 Mannheim            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                +49 (0)6021 18150133            <\/div>\n                                    <div class=\"email\">\n                i&#110;f&#x6f;&#64;wolle-im-&#x71;uadra&#116;&#x2e;de            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/wolle-im-quadrat.de\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+49 (0)6021 18150133\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22938\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wolle Pur GmbH                            <\/div>\n                \n                    <div class=\"contact\">\n                Birgit Bossling            <\/div>\n                            <div class=\"city-zipcode\">\n                96047 Bamberg            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0951-2084221            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wolle-pur.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0951-2084221\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22977\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wolle Willich                            <\/div>\n                \n                    <div class=\"contact\">\n                Elisabeth G\u00fctschow            <\/div>\n                            <div class=\"city-zipcode\">\n                47877 Willich            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                02154-8937962            <\/div>\n                                    <div class=\"email\">\n                info&#64;wo&#108;l-w&#105;l&#108;ich&#46;&#x64;e            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wolle-willich.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:02154-8937962\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22725\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wolle-L\u00e4dchen                            <\/div>\n                \n                    <div class=\"contact\">\n                Saskia Krieger            <\/div>\n                            <div class=\"city-zipcode\">\n                35039 Marburg            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                06421-34230            <\/div>\n                                    <div class=\"email\">\n                w&#111;&#x6c;l&#x65;-&#108;aedche&#x6e;&#64;t-&#111;nli&#x6e;e&#46;de            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wolle-laedchen.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:06421-34230\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22865\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wolle4you                            <\/div>\n                \n                    <div class=\"contact\">\n                Jochen Novodomsky            <\/div>\n                            <div class=\"city-zipcode\">\n                71083 Herrenberg            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                07032-24100            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/wolle4you.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:07032-24100\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-50450\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wollensittich                            <\/div>\n                \n                    <div class=\"contact\">\n                Inh. Manuela Sittig            <\/div>\n                            <div class=\"city-zipcode\">\n                65830 Kriftel            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0049 6192 9223133            <\/div>\n                                    <div class=\"email\">\n                &#105;n&#x66;o&#64;&#x77;ollensit&#x74;ic&#x68;&#46;&#100;e            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"www.wollensittich.de\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0049 6192 9223133\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22628\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wollewelten GmbH                            <\/div>\n                \n                    <div class=\"contact\">\n                Steffen K\u00f6hler            <\/div>\n                            <div class=\"city-zipcode\">\n                04229 Leipzig            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0341-22170440            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wollewelten.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0341-22170440\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-24475\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wollfugium                            <\/div>\n                \n                    <div class=\"contact\">\n                Renate Grunert Paul            <\/div>\n                            <div class=\"city-zipcode\">\n                71554 Weissach im Tal            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0049 7191 9069014            <\/div>\n                                    <div class=\"email\">\n                i&#x6e;fo&#x40;&#119;ollf&#x75;&#103;ium&#46;&#x64;e            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wollfugium.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0049 7191 9069014\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22850\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wollgredel                            <\/div>\n                \n                    <div class=\"contact\">\n                Petra Behles            <\/div>\n                            <div class=\"city-zipcode\">\n                66679 Losheim am See            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                06872-9221166            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wollgredel.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:06872-9221166\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22922\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wollkontor Nadelei und Genuss                            <\/div>\n                \n                    <div class=\"contact\">\n                Susanne Prei\u00dfler            <\/div>\n                            <div class=\"city-zipcode\">\n                91080 Uttenreuth            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                09131-204327            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wollkontor-erlangen.de\/wolle-online\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:09131-204327\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22958\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wollmaus                            <\/div>\n                \n                    <div class=\"contact\">\n                Steffi Lenhard            <\/div>\n                            <div class=\"city-zipcode\">\n                99826 Mihla            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                036926-99411            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wollmaus-wolle.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:036926-99411\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22944\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wollstar                            <\/div>\n                \n                    <div class=\"contact\">\n                Claudia Gatzka            <\/div>\n                            <div class=\"city-zipcode\">\n                97070 W\u00fcrzburg            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0931-46789890            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wollstar.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0931-46789890\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-42936\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wollstudio Kuhr                            <\/div>\n                \n                    <div class=\"contact\">\n                Christiane Kuhr            <\/div>\n                            <div class=\"city-zipcode\">\n                34576 Homberg-Efze            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                05681 93 11 93            <\/div>\n                                    <div class=\"email\">\n                i&#110;&#102;&#111;&#64;wol&#108;stud&#105;o&#x2e;c&#111;m            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"www.wollstudio.com\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:05681 93 11 93\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-22685\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wollsucht                            <\/div>\n                \n                    <div class=\"contact\">\n                Claus Greve            <\/div>\n                            <div class=\"city-zipcode\">\n                24937 Flensburg            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0461-3183454            <\/div>\n                                    <div class=\"email\">\n                inf&#111;&#64;&#119;o&#108;&#108;&#x73;&#x75;&#x63;ht&#46;de            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wollsucht.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0461-3183454\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22676\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wollvik                            <\/div>\n                \n                    <div class=\"contact\">\n                Viktoria Koch            <\/div>\n                            <div class=\"city-zipcode\">\n                22335 Hamburg-Fuhlsb\u00fcttel            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                040-41543767            <\/div>\n                                    <div class=\"email\">\n                wollv&#x69;&#x6b;&#64;we&#98;&#46;de            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wollvik-hamburg.de\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:040-41543767\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-34664\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wollywood                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                23843 Bad Oldesloe            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                04531 8980960            <\/div>\n                                    <div class=\"email\">\n                i&#x6e;fo&#x40;&#119;ollyw&#x6f;&#x6f;d&#x2e;d&#x65;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.wollywood.de\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:04531 8980960\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-36481\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Wool Stack &#8211; Great Britain                            <\/div>\n                \n                            <div class=\"city-zipcode\">\n                Churchill Rd Cheltenham GL53 7EG, UK            <\/div>\n                            <div class=\"contact\">\n                Great Britain            <\/div>\n                            <div class=\"phone\">\n                01242 300 280            <\/div>\n                        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.woolstack.co.uk\/brands\/Addi.html\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:01242 300 280\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-71818\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                WUNDERBAR! wollig und kreativ                            <\/div>\n                \n                    <div class=\"contact\">\n                Jana Burkhardt            <\/div>\n                            <div class=\"city-zipcode\">\n                99974 M\u00fchlhausen \/ Th\u00fcringen            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0049 3601 8713111            <\/div>\n                                    <div class=\"email\">\n                info&#x40;wunderba&#114;-mh&#108;&#46;de            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"www.wunderbar-wolle.de\" target=\"_blank\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0049 3601 8713111\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<\/div><div class=\"row\"><div id=\"post-22976\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Zauberwiese                            <\/div>\n                \n                    <div class=\"contact\">\n                Hassan Abu-Toboul            <\/div>\n                            <div class=\"city-zipcode\">\n                24955 Harrislee            <\/div>\n                            <div class=\"contact\">\n                Deutschland            <\/div>\n                            <div class=\"phone\">\n                0461-90498918            <\/div>\n                                    <div class=\"email\">\n                &#x69;nfo&#x40;zauberwie&#115;&#x65;&#x2e;co&#109;            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/www.zauberwiese.com\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:0461-90498918\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n<div id=\"post-23207\" class=\"col-12 col-lg-3\">\n    <div class=\"dealer-item\">\n        \n                            <div class=\"company\">\n                Zienka domaca,s.r.o                            <\/div>\n                \n                    <div class=\"contact\">\n                M\u00e1ria Tobi\u00e1\u0161ov\u00e1 Kuzmov\u00e1            <\/div>\n                            <div class=\"city-zipcode\">\n                96231 Silac            <\/div>\n                            <div class=\"contact\">\n                Slovakia            <\/div>\n                            <div class=\"phone\">\n                +421905251690            <\/div>\n                                    <div class=\"email\">\n                &#x6d;ari&#97;to&#98;i&#x61;s&#64;&#x7a;&#x69;enka&#x64;o&#109;a&#x63;a&#46;sk            <\/div>\n        \n        \n        <span class=\"links-wrapper\">\n                            <a href=\"https:\/\/eshop.zienkadomaca.sk\/Galanteria-c2_0_1.htm?filter_values%5B1689533%5D%5B220221161%5D=1\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-solid fa-globe\"><\/i><\/a>\n                                                    <a href=\"tel:+421905251690\" target=\"_blank\"><i class=\"fa-solid fa-phone\"><\/i><\/a>\n                    <\/span>\n    <\/div>\n<\/div>\n                                                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                            <\/div>\n    <\/section>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"kategorie_pages":[29],"class_list":["post-1966","page","type-page","status-publish","hentry","kategorie_pages-service"],"acf":[],"_links":{"self":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/pages\/1966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/comments?post=1966"}],"version-history":[{"count":0,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/pages\/1966\/revisions"}],"wp:attachment":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/media?parent=1966"}],"wp:term":[{"taxonomy":"kategorie_pages","embeddable":true,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/kategorie_pages?post=1966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}