{"id":2014,"date":"2022-03-14T15:45:25","date_gmt":"2022-03-14T14:45:25","guid":{"rendered":"https:\/\/addi.de\/?page_id=2014"},"modified":"2026-04-10T11:37:33","modified_gmt":"2026-04-10T09:37:33","slug":"magazin-precious","status":"publish","type":"page","link":"https:\/\/addi.de\/en\/magazin-edles\/","title":{"rendered":"Magazin Edles"},"content":{"rendered":"<style>\n\ni.fab.fa-x-twitter::before{\n    content: \"\"; \n    background-image: url(data:image\/svg+xml;base64,PD94bWwgdmVyc2lvbj0iMS4wIiBlbmNvZGluZz0iVVRGLTgiIHN0YW5kYWxvbmU9Im5vIj8+PCFET0NUWVBFIHN2ZyBQVUJMSUMgIi0vL1czQy8vRFREIFNWRyAxLjEvL0VOIiAiaHR0cDovL3d3dy53My5vcmcvR3JhcGhpY3MvU1ZHLzEuMS9EVEQvc3ZnMTEuZHRkIj48c3ZnIHdpZHRoPSIxMDAlIiBoZWlnaHQ9IjEwMCUiIHZpZXdCb3g9IjAgMCAyMTM0IDIxMzQiIHZlcnNpb249IjEuMSIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIiB4bWxuczp4bGluaz0iaHR0cDovL3d3dy53My5vcmcvMTk5OS94bGluayIgeG1sOnNwYWNlPSJwcmVzZXJ2ZSIgeG1sbnM6c2VyaWY9Imh0dHA6Ly93d3cuc2VyaWYuY29tLyIgc3R5bGU9ImZpbGwtcnVsZTpldmVub2RkO2NsaXAtcnVsZTpldmVub2RkO3N0cm9rZS1saW5lam9pbjpyb3VuZDtzdHJva2UtbWl0ZXJsaW1pdDoyOyI+PHBhdGggZD0iTTE2MjEuNjcsMjAwbDI5NC4xNjYsMGwtNjQyLjUsNzM0LjE2N2w3NTUuODM0LDk5OS4xNjZsLTU5MS42NjcsMGwtNDYzLjc1LC02MDUuODMzbC01MzAsNjA1LjgzM2wtMjk0LjU4MywwbDY4Ny4wODMsLTc4NS40MTZsLTcyNC41ODMsLTk0Ny45MTdsNjA2LjY2NiwwbDQxOC43NSw1NTMuNzVsNDg0LjU4NCwtNTUzLjc1Wm0tMTAzLjMzNCwxNTU3LjVsMTYyLjkxNywwbC0xMDUxLjY3LC0xMzkwLjgzbC0xNzUsLTBsMTA2My43NSwxMzkwLjgzWiIgc3R5bGU9ImZpbGw6I2ZmZjtmaWxsLXJ1bGU6bm9uemVybzsiLz48L3N2Zz4=);\n    text-align: center;\n    color: #fff;\n    display: inline-block !important;\n    height: 24px;\n    width: 24px;\n    background-repeat: no-repeat;\n}\n\n<\/style>\n<div id=\"header-block_51d346bb8f994a85e95435b0b8b4d2ec\" class=\"header variant-small\" >\n    <section>\n        <div class=\"container\">\n            <div class=\"stage-wrapper mb-5 position-relative\">\n                                            <div class=\"row stage-image-wrapper\">\n                                <div class=\"col-12\">\n                                    <div class=\"stage-image\">\n                                        <img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/edles_keyvisual_small-1280x400.png\" class=\"attachment-1280x400 size-1280x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/edles_keyvisual_small-1280x400.png 1280w, https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/edles_keyvisual_small-768x240.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/edles_keyvisual_small-1536x480.png 1536w, https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/edles_keyvisual_small-1320x413.png 1320w, https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/edles_keyvisual_small-600x188.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/edles_keyvisual_small.png 2000w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                            <div class=\"row stage-caption-wrapper mb-4 mb-lg-0\">\n                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                    <div class=\"stage-caption inherit\">\n                                        <div class=\"stage-caption-inner hl-color medium middle\">\n                                            Precious<br \/>\r\n&nbsp; for your hands.                                                                                    <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                                                    <\/div>\n            <div class=\"row\">\n                <div class=\"col-12 col-lg-7\">\n                    <h1>\n                        Only the best for your hands.                    <\/h1>\n                    <div class=\"share-links\">\n                        <span>Teilen:<\/span>\n                        <a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Faddi.de%2Fen%2Fmagazin-edles%2F\" class=\"d-inline-block px-2\" onclick=\"window.open(this.href, 'mywin', 'left=20,top=20,width=500,height=500,toolbar=1,resizable=0'); return false;\"><i class=\"fab fa-facebook-f hl-color\"><\/i><\/a>\n                        <a href=\"https:\/\/twitter.com\/intent\/tweet?text=https%3A%2F%2Faddi.de%2Fen%2Fmagazin-edles%2F\" class=\"d-inline-block px-2\" onclick=\"window.open(this.href, 'mywin', 'left=20,top=20,width=500,height=500,toolbar=1,resizable=0'); return false;\"><i class=\"fa-brands fa-x-twitter hl-color\"><\/i><\/a>\n                    <\/div>\n                    <div class=\"text\">\n                        <p><span style=\"font-weight: 400\">Knitting is also a sign of good taste. Here in addi magazine you will not only find instructions for stylish knitting and crochet, but also information about exclusive materials and ideas for accessories that are sure to get you one or two admiring glances.<\/span><\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"col-12 col-lg-3 offset-lg-1 toc-wrapper\">\n                                        <div class=\"toc-title\">\n                        Inhaltsverzeichnis                    <\/div>\n                    <div class=\"toc-content\">\n\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"teaser-block_6949d8256022de38ba764113c08d890e\" class=\"teaser toc alignment-right\"  data-toctitle=\"21 Schritte zur Premium Nadel\">\n    <section>\n        <div class=\"container\">\n                                                                                            <div class=\"row position-relative noble images-count-2\">\n                            <div class=\"color-area-secondary\"><\/div>\n                            <div class=\"col-12 col-lg-6\">\n                                                                    <div class=\"images-wrapper\">\n                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                    <div class=\"col-12 col-lg-10\">\n                                                        <picture>\n                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/03\/21-Schritte-addiPremium-520x300.jpg\">\n                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/03\/21-Schritte-addiPremium-520x300.jpg\" alt=\"\">\n                                                        <\/picture>\n                                                    <\/div>\n                                                <\/div>\n                                                <div class=\"row image-2-wrapper\">\n                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/03\/Polieren_Produktion-scaled-e1677865948502-400x400.jpeg\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/03\/Polieren_Produktion-scaled-e1677865948502-400x400.jpeg 400w, https:\/\/addi.de\/wp-content\/uploads\/2023\/03\/Polieren_Produktion-scaled-e1677865948502-800x800.jpeg 800w, https:\/\/addi.de\/wp-content\/uploads\/2023\/03\/Polieren_Produktion-scaled-e1677865948502-300x300.jpeg 300w, https:\/\/addi.de\/wp-content\/uploads\/2023\/03\/Polieren_Produktion-scaled-e1677865948502-100x100.jpeg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                    <\/div>\n                                                <\/div>\n                                                                                                                        <\/div>\n                                                            <\/div>\n                            <div class=\"col-12 col-lg-6\">\n                                <div class=\"text-wrapper\">\n                                                                            <div class=\"topline\">\n                                            Story - Production of a knitting needle                                         <\/div>\n                                                                                                                <div class=\"heading-tag\">\n                                        <h2>21 steps to the addiPremium circular knitting needle<\/h2>\n                                        <\/div>\n                                                                                                                <div class=\"text\">\n                                            <p><span data-offset-key=\"ed5kl-0-0\">How are our knitting needles produced and how many steps does it take to get to the finished needle? We are always happy to show our guests this during factory tours and summarised for you in this story.<\/span><\/p>\n                                        <\/div>\n                                                                                                                <div class=\"row link-wrapper\">\n                                                                                            <div class=\"col-12 col-lg-6\">\n                                                    <a href='https:\/\/addi.de\/en\/story\/produktion-einer-stricknadel\/' target='_self' class='buttonlink prio-1'>Read story<\/a>                                                <\/div>\n                                                                                                                                <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                                        <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"teaser-block_c10dbb639d794d1f6c63d053b60574bf\" class=\"teaser toc alignment-left\"  data-toctitle=\"Wickeljacke stricken\">\n    <section>\n        <div class=\"container\">\n                                                                                            <div class=\"row position-relative noble images-count-3\">\n                            <div class=\"color-area-secondary\"><\/div>\n                            <div class=\"col-12 col-lg-6 order-2 order-lg-1\">\n                                <div class=\"text-wrapper\">\n                                                                            <div class=\"topline\">\n                                            Knitting tutorial                                        <\/div>\n                                                                                                                <div class=\"heading-tag\">\n                                            <h2>Wrapover cardigan<\/h2>\n                                        <\/div>\n                                                                                                                <div class=\"text\">\n                                            <p>This wrap jacket impresses with its timeless design and cosy yarn \u2013 three strands of Lang Yarns LACE. It is knitted from the top down with a circular yoke. Instructions from Lang Yarns.<\/p>\n                                        <\/div>\n                                                                                                                <div class=\"row link-wrapper\">\n                                                                                            <div class=\"col-12 col-lg-6\">\n                                                    <a href='https:\/\/addi.de\/en\/story\/wickeljacke-stricken\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                <\/div>\n                                                                                                                                <\/div>\n                                                                    <\/div>\n                            <\/div>\n                            <div class=\"col-12 col-lg-6 order-1 order-lg-2\">\n                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                    <div class=\"col-12 col-lg-4 offset-lg-2\">\n                                                        <picture>\n                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Wickeljacke-stricken_lang-superkid-mohair-200x300.jpg\">\n                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Wickeljacke-stricken_lang-superkid-mohair-520x300.jpg\" alt=\"\">\n                                                        <\/picture>\n                                                    <\/div>\n                                                <\/div>\n                                                <div class=\"row image-2-wrapper\">\n                                                    <div class=\"col-12 col-lg-8 offset-lg-4\">\n                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/901_048_010_D1-400x400.jpg\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/901_048_010_D1-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/901_048_010_D1-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/901_048_010_D1-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                    <\/div>\n                                                <\/div>\n                                                <div class=\"row product\">\n                                                    <div class=\"col-12 col-lg-6\">\n                                                        <div class=\"product-wrapper\">\n                                                            <div class=\"square\"><\/div>\n                                                            <div class=\"color-area-primary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                                                        <\/div>\n                                                            <\/div>\n                        <\/div>\n                                                        <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"teaser-block_836993601379232112d92819b7438f66\" class=\"teaser toc alignment-right\"  data-toctitle=\"addiUnicorn\">\n    <section>\n        <div class=\"container\">\n                                                                                            <div class=\"row position-relative noble images-count-3\">\n                            <div class=\"color-area-secondary\"><\/div>\n                            <div class=\"col-12 col-lg-6\">\n                                                                    <div class=\"images-wrapper\">\n                                                                                    <div class=\"row image-1-wrapper\">\n                                                <div class=\"col-12 col-lg-4 offset-lg-6\">\n                                                    <picture>\n                                                        <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/addiUnicorn-EInhorn-FIngerspiel-200x300.jpg\">\n                                                        <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/addiUnicorn-EInhorn-FIngerspiel-520x300.jpg\" alt=\"\">\n                                                    <\/picture>\n                                                <\/div>\n                                            <\/div>\n                                            <div class=\"row image-2-wrapper\">\n                                                <div class=\"col-12 col-lg-8\">\n                                                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/03\/720-2_addiClick-Unicorn_Etui_case_Clicksystem_MadeinGermany_detail_stimmung1_rgb-400x400.jpg\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/03\/720-2_addiClick-Unicorn_Etui_case_Clicksystem_MadeinGermany_detail_stimmung1_rgb-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2023\/03\/720-2_addiClick-Unicorn_Etui_case_Clicksystem_MadeinGermany_detail_stimmung1_rgb-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2023\/03\/720-2_addiClick-Unicorn_Etui_case_Clicksystem_MadeinGermany_detail_stimmung1_rgb-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2023\/03\/720-2_addiClick-Unicorn_Etui_case_Clicksystem_MadeinGermany_detail_stimmung1_rgb-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                <\/div>\n                                            <\/div>\n                                            <div class=\"row image-3-wrapper\">\n                                                <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_cicular_knitting_needle_metall_2-8mm_60-150cm_US-1-11_2422-6022_madeinGermany_Stimmung_rgb-400x400.png\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_cicular_knitting_needle_metall_2-8mm_60-150cm_US-1-11_2422-6022_madeinGermany_Stimmung_rgb-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_cicular_knitting_needle_metall_2-8mm_60-150cm_US-1-11_2422-6022_madeinGermany_Stimmung_rgb-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_cicular_knitting_needle_metall_2-8mm_60-150cm_US-1-11_2422-6022_madeinGermany_Stimmung_rgb-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_cicular_knitting_needle_metall_2-8mm_60-150cm_US-1-11_2422-6022_madeinGermany_Stimmung_rgb-100x100.png 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                <\/div>\n                                            <\/div>\n                                                                            <\/div>\n                                                            <\/div>\n                            <div class=\"col-12 col-lg-6\">\n                                <div class=\"text-wrapper\">\n                                                                            <div class=\"topline\">\n                                            Tips and tricks                                        <\/div>\n                                                                                                                <div class=\"heading-tag\">\n                                        <h2>addiUnicorn - for magical knitting moments<\/h2>\n                                        <\/div>\n                                                                                                                <div class=\"text\">\n                                            <p>In this story we would like to introduce you to the fabulous addiUnicorn knitting needles, which not only convince with their quality, but also with a pinch of pink magic.<\/p>\n                                        <\/div>\n                                                                                                                <div class=\"row link-wrapper\">\n                                                                                            <div class=\"col-12 col-lg-6\">\n                                                    <a href='https:\/\/addi.de\/en\/story\/addiunicorn\/' target='_self' class='buttonlink prio-1'>Read story<\/a>                                                <\/div>\n                                                                                                                                <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                                        <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"teaser-block_e2cac4a5dffea371de44267e79a0f832\" class=\"teaser toc alignment-left\"  data-toctitle=\"addiExpress Kurbelanleitungen\">\n    <section>\n        <div class=\"container\">\n                                                <div id=\"teaserCarousel-block_e2cac4a5dffea371de44267e79a0f832\" class=\"carousel slide keepsize-responsive\">\n                        <div class=\"carousel-inner\" data-countslides=\"2\">\n                                                            <div class=\"carousel-item active\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6 order-2 order-lg-1\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            addiExpress instructions                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                        <h2>Casual addiExpress slipover knitting for beginners<h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <div class=\"text\">This pullunder combines style and comfort \u2013 casual, versatile and cosy and warm.<\/div>\n<div>It consists of simple rectangles that are quickly and easily cranked with a knitting machine. Available in 3 sizes, this project is ideal for beginners and advanced knitters alike. A tutorial by Judith Jelena.<\/div>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/addiexpress-pullunder-kurbeln\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                            <div class=\"col-12 col-lg-6 order-1 order-lg-2\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10 offset-lg-2\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/Pullunder_Anleitung_addiExpress_JudithJelena-05-520x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/Pullunder_Anleitung_addiExpress_JudithJelena-05-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-600x600.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-1536x1536.png 1536w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-1320x1320.png 1320w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-100x100.png 100w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1.png 2000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6 order-2 order-lg-1\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            addiExpress Kingsize tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                        <h2>Winding a headband with twist with the addiExpress Kingsize knitting machine<h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>Simply wind it with the addiExpress Kingsize, sew it together and it's ready to wear - a simple headband that even beginners can wind.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/addiexpress-anleitung-stirnband-mit-twist-kurbeln\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                            <div class=\"col-12 col-lg-6 order-1 order-lg-2\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10 offset-lg-2\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/03\/Stirnband-mit-Twist_addiExpress-kurbeln_01-scaled-520x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/03\/Stirnband-mit-Twist_addiExpress-kurbeln_01-scaled-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-600x600.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-1536x1536.png 1536w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-1320x1320.png 1320w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1-100x100.png 100w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/890-2_addiExpress_Kingsize_Strickmaschine_Knitting_machine_46_Nadeln_needles_O35cm_frei1_rgb-1.png 2000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                    <\/div>\n                        <div class=\"row\">\n                            <div class=\"col-12 col-lg-4 offset-lg-4\">\n                                <ol class=\"carousel-indicators\">\n                                                                            <li data-target=\"#teaserCarousel-block_e2cac4a5dffea371de44267e79a0f832\" data-slide-to=\"0\"\n                                            class=\"active\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_e2cac4a5dffea371de44267e79a0f832\" data-slide-to=\"1\"\n                                            class=\"\"><\/li>\n                                                                    <\/ol>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"teaser-block_e430838d67f9c2bacc4d6d8355603a19\" class=\"teaser toc alignment-right\"  data-toctitle=\"Olivenholznadeln\">\n    <section>\n        <div class=\"container\">\n                                                                                            <div class=\"row position-relative noble images-count-2\">\n                            <div class=\"color-area-secondary\"><\/div>\n                            <div class=\"col-12 col-lg-6\">\n                                                                    <div class=\"images-wrapper\">\n                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                    <div class=\"col-12 col-lg-10\">\n                                                        <picture>\n                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/08\/576-7-addiClick-Nature-Olive-Wood-Nachhaltigkeit-Olivenholz1-520x300.jpg\">\n                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/08\/576-7-addiClick-Nature-Olive-Wood-Nachhaltigkeit-Olivenholz1-520x300.jpg\" alt=\"\">\n                                                        <\/picture>\n                                                    <\/div>\n                                                <\/div>\n                                                <div class=\"row image-2-wrapper\">\n                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/08\/pexels-gary-barnes-6231898-400x400.jpg\" class=\"attachment-400x400 size-400x400\" alt=\"Olivenholz, Olivenbaum mit Fr\u00fcchten\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/08\/pexels-gary-barnes-6231898-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2023\/08\/pexels-gary-barnes-6231898-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2023\/08\/pexels-gary-barnes-6231898-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2023\/08\/pexels-gary-barnes-6231898-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                    <\/div>\n                                                <\/div>\n                                                                                                                        <\/div>\n                                                            <\/div>\n                            <div class=\"col-12 col-lg-6\">\n                                <div class=\"text-wrapper\">\n                                                                            <div class=\"topline\">\n                                            Tips and tricks                                        <\/div>\n                                                                                                                <div class=\"heading-tag\">\n                                        <h2>The Olive Wood for the Finest Needles<\/h2>\n                                        <\/div>\n                                                                                                                <div class=\"text\">\n                                            <p>A beautiful wood with a unique grain is processed by us in Germany into fine and durable needles for knitting and crocheting. In this story, you can find out about the special features of the raw material and how it is obtained.<\/p>\n                                        <\/div>\n                                                                                                                <div class=\"row link-wrapper\">\n                                                                                            <div class=\"col-12 col-lg-6\">\n                                                    <a href='https:\/\/addi.de\/en\/story\/olivenholz-strick-und-haekelnadeln\/' target='_self' class='buttonlink prio-1'>Read story<\/a>                                                <\/div>\n                                                                                                                                <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                                        <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"teaser-block_3c4237e8c275219add8e19e9ccfeb563\" class=\"teaser toc alignment-left\"  data-toctitle=\"Chashmere Pullunder\">\n    <section>\n        <div class=\"container\">\n                                                <div id=\"teaserCarousel-block_3c4237e8c275219add8e19e9ccfeb563\" class=\"carousel slide keepsize-responsive\">\n                        <div class=\"carousel-inner\" data-countslides=\"2\">\n                                                            <div class=\"carousel-item active\">\n                                                                                                                <div class=\"row position-relative noble images-count-3\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6 order-2 order-lg-1\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Knitting tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                        <h2>Knit a slipover made of cashmere<h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>Soft and classic with this 100% cashmere sweater with a timeless shape and V-neck. A tutorial from Lang Yarns.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/herrenpullunder-stricken-cashmere\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                            <div class=\"col-12 col-lg-6 order-1 order-lg-2\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-4 offset-lg-2\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Lang-yarns-Pullunder-stricken-cashmere_addi-01-200x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Lang-yarns-Pullunder-stricken-cashmere_addi-01-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row image-2-wrapper\">\n                                                                    <div class=\"col-12 col-lg-8 offset-lg-4\">\n                                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Lang-yarns-Pullunder-stricken-cashmere_addi-03-400x400.jpg\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Lang-yarns-Pullunder-stricken-cashmere_addi-03-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Lang-yarns-Pullunder-stricken-cashmere_addi-03-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Lang-yarns-Pullunder-stricken-cashmere_addi-03-768x768.jpg 768w, https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Lang-yarns-Pullunder-stricken-cashmere_addi-03-12x12.jpg 12w, https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Lang-yarns-Pullunder-stricken-cashmere_addi-03-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Lang-yarns-Pullunder-stricken-cashmere_addi-03-600x600.jpg 600w, https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Lang-yarns-Pullunder-stricken-cashmere_addi-03-100x100.jpg 100w, https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Lang-yarns-Pullunder-stricken-cashmere_addi-03.jpg 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-3\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6 order-2 order-lg-1\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Knitting tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                        <h2>Cashmere Pullunder stricken &#8222;Arianne&#8220;<h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>The elegant cashmere slipover is knitted in one piece from top down. This means that no subsequent sewing is necessary.<\/p>\n<p>An everyday companion in a timeless cut, perfect for spring and autumn. A pattern by Lang Yarns.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/cashmere-pullunder-stricken\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                            <div class=\"col-12 col-lg-6 order-1 order-lg-2\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-4 offset-lg-2\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/11\/ANL-Pullunder-Ariane-01-200x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/11\/ANL-Pullunder-Ariane-01-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row image-2-wrapper\">\n                                                                    <div class=\"col-12 col-lg-8 offset-lg-4\">\n                                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/11\/ANL-Pullunder-Ariane-03-400x400.jpg\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/11\/ANL-Pullunder-Ariane-03-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2024\/11\/ANL-Pullunder-Ariane-03-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2024\/11\/ANL-Pullunder-Ariane-03-768x768.jpg 768w, https:\/\/addi.de\/wp-content\/uploads\/2024\/11\/ANL-Pullunder-Ariane-03-12x12.jpg 12w, https:\/\/addi.de\/wp-content\/uploads\/2024\/11\/ANL-Pullunder-Ariane-03-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2024\/11\/ANL-Pullunder-Ariane-03-600x600.jpg 600w, https:\/\/addi.de\/wp-content\/uploads\/2024\/11\/ANL-Pullunder-Ariane-03-100x100.jpg 100w, https:\/\/addi.de\/wp-content\/uploads\/2024\/11\/ANL-Pullunder-Ariane-03.jpg 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                    <\/div>\n                        <div class=\"row\">\n                            <div class=\"col-12 col-lg-4 offset-lg-4\">\n                                <ol class=\"carousel-indicators\">\n                                                                            <li data-target=\"#teaserCarousel-block_3c4237e8c275219add8e19e9ccfeb563\" data-slide-to=\"0\"\n                                            class=\"active\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_3c4237e8c275219add8e19e9ccfeb563\" data-slide-to=\"1\"\n                                            class=\"\"><\/li>\n                                                                    <\/ol>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"teaser-block_2c1d3b1d4f4c550fe559c4a2c7aa42ec\" class=\"teaser toc alignment-right\"  data-toctitle=\"Stricken mit der H\u00e4kelnadel\">\n    <section>\n        <div class=\"container\">\n                                                                                            <div class=\"row position-relative noble images-count-2\">\n                            <div class=\"color-area-secondary\"><\/div>\n                            <div class=\"col-12 col-lg-6\">\n                                                                    <div class=\"images-wrapper\">\n                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                    <div class=\"col-12 col-lg-10\">\n                                                        <picture>\n                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/12\/Stefanie-MohrKette-mit-Anha\u0308nger-aus-Draht-gestrickt-520x300.jpg\">\n                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/12\/Stefanie-MohrKette-mit-Anha\u0308nger-aus-Draht-gestrickt-520x300.jpg\" alt=\"\">\n                                                        <\/picture>\n                                                    <\/div>\n                                                <\/div>\n                                                <div class=\"row image-2-wrapper\">\n                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/11\/Edelstahlarmband-einfach-doppelt-gestrickt-002-400x400.jpeg\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/11\/Edelstahlarmband-einfach-doppelt-gestrickt-002-400x400.jpeg 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/11\/Edelstahlarmband-einfach-doppelt-gestrickt-002-300x300.jpeg 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/11\/Edelstahlarmband-einfach-doppelt-gestrickt-002-100x100.jpeg 100w, https:\/\/addi.de\/wp-content\/uploads\/2022\/11\/Edelstahlarmband-einfach-doppelt-gestrickt-002.jpeg 480w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                    <\/div>\n                                                <\/div>\n                                                                                                                        <\/div>\n                                                            <\/div>\n                            <div class=\"col-12 col-lg-6\">\n                                <div class=\"text-wrapper\">\n                                                                            <div class=\"topline\">\n                                            Story                                        <\/div>\n                                                                                                                <div class=\"heading-tag\">\n                                        <h2>Knitting with a crochet hook<\/h2>\n                                        <\/div>\n                                                                                                                <div class=\"text\">\n                                            <p>\u2026and not only that, but with wire! Have you ever heard of this? We interviewed the expert and designer, Stefanie Mohr, on this topic and learned a lot.<\/p>\n                                        <\/div>\n                                                                                                                <div class=\"row link-wrapper\">\n                                                                                            <div class=\"col-12 col-lg-6\">\n                                                    <a href='https:\/\/addi.de\/en\/story\/stricken-mit-der-haekelnadel\/' target='_self' class='buttonlink prio-1'>Read story<\/a>                                                <\/div>\n                                                                                                                                <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                                        <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"teaser-block_3db582f886655d672a1c103c3c41e1ea\" class=\"teaser alignment-left\" >\n    <section>\n        <div class=\"container\">\n                                                <div id=\"teaserCarousel-block_3db582f886655d672a1c103c3c41e1ea\" class=\"carousel slide keepsize-responsive\">\n                        <div class=\"carousel-inner\" data-countslides=\"2\">\n                                                            <div class=\"carousel-item active\">\n                                                                                                                <div class=\"row position-relative noble images-count-3\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6 order-2 order-lg-1\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Story                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                        <h2>No compromise \u2013 part 2.<h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>Creating something ourselves is only really fun if what we are working with is of good quality.<\/p>\n<p>In an interview with Jakob Lang (Lang Yarns) and Sebastian Hermann (Schulana), we find out what this means<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/lieber-gleich-erstklassig-teil-2\/' target='_self' class='buttonlink prio-1'>Read story<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                            <div class=\"col-12 col-lg-6 order-1 order-lg-2\">\n                                                                                                    <div class=\"images-wrapper\">\n                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                <div class=\"col-12 col-lg-4 offset-lg-2\">\n                                                                    <picture>\n                                                                        <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2021\/05\/575-7-addiNature-Olive-Wood-Rundstricknadel-cicular-knitting-needle-Walnussholz-3-12mm-40-150cm-US-2-17-1622-6022-madeinGermany-Sideshot1-rgb-200x300.png\">\n                                                                        <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2021\/05\/575-7-addiNature-Olive-Wood-Rundstricknadel-cicular-knitting-needle-Walnussholz-3-12mm-40-150cm-US-2-17-1622-6022-madeinGermany-Sideshot1-rgb-520x300.png\" alt=\"\">\n                                                                    <\/picture>\n                                                                <\/div>\n                                                            <\/div>\n                                                            <div class=\"row image-2-wrapper\">\n                                                                <div class=\"col-12 col-lg-8 offset-lg-4\">\n                                                                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/09\/Jakob-Lang-400x400.png\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/09\/Jakob-Lang-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/09\/Jakob-Lang-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/09\/Jakob-Lang-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/09\/Jakob-Lang-100x100.png 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                <\/div>\n                                                            <\/div>\n                                                            <div class=\"row image-3-wrapper\">\n                                                                <div class=\"col-12 col-lg-6\">\n                                                                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/09\/Sebastian-Hermann-400x400.jpg\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/09\/Sebastian-Hermann-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/09\/Sebastian-Hermann-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/09\/Sebastian-Hermann-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/09\/Sebastian-Hermann-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                <\/div>\n                                                            <\/div>\n                                                                                                            <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-3\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6 order-2 order-lg-1\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Story                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                        <h2>No compromise.<h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>The material we use is, of course, a central consideration in all our projects. Quality is key.<\/p>\n<p><strong>Today, we are talking to Britta Kremke from Selected Yarns.\u00a0<\/strong><\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/lieber-gleich-erstklassig\/' target='_self' class='buttonlink prio-1'>Read story<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                            <div class=\"col-12 col-lg-6 order-1 order-lg-2\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-4 offset-lg-2\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/000-addi-Sideshot5-Schal-stricken-200x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/000-addi-Sideshot5-Schal-stricken-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row image-2-wrapper\">\n                                                                    <div class=\"col-12 col-lg-8 offset-lg-4\">\n                                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/Britta-Kremke-400x400.png\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/Britta-Kremke-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/Britta-Kremke-11x12.png 11w, https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/Britta-Kremke-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/Britta-Kremke-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/Britta-Kremke-100x100.png 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                    <\/div>\n                        <div class=\"row\">\n                            <div class=\"col-12 col-lg-4 offset-lg-4\">\n                                <ol class=\"carousel-indicators\">\n                                                                            <li data-target=\"#teaserCarousel-block_3db582f886655d672a1c103c3c41e1ea\" data-slide-to=\"0\"\n                                            class=\"active\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_3db582f886655d672a1c103c3c41e1ea\" data-slide-to=\"1\"\n                                            class=\"\"><\/li>\n                                                                    <\/ol>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"teaser-block_a53f8d3c416f4db87b187c6df6bd8658\" class=\"teaser toc alignment-right\"  data-toctitle=\"Strickanleitungen\">\n    <section>\n        <div class=\"container\">\n                                                <div id=\"teaserCarousel-block_a53f8d3c416f4db87b187c6df6bd8658\" class=\"carousel slide keepsize-responsive\">\n                        <div class=\"carousel-inner\" data-countslides=\"10\">\n                                                            <div class=\"carousel-item active\">\n                                                                                                                <div class=\"row position-relative noble images-count-3\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-4 offset-lg-6\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Balaklava-fur-Kinder-gestrickt_Langyarns_addi01-200x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Balaklava-fur-Kinder-gestrickt_Langyarns_addi01-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row image-2-wrapper\">\n                                                                    <div class=\"col-12 col-lg-8\">\n                                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Balaklava-fur-Kinder-gestrickt_Langyarns_addi02-400x400.jpg\" class=\"attachment-400x400 size-400x400\" alt=\"\u2714\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Balaklava-fur-Kinder-gestrickt_Langyarns_addi02-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Balaklava-fur-Kinder-gestrickt_Langyarns_addi02-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Balaklava-fur-Kinder-gestrickt_Langyarns_addi02-768x768.jpg 768w, https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Balaklava-fur-Kinder-gestrickt_Langyarns_addi02-12x12.jpg 12w, https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Balaklava-fur-Kinder-gestrickt_Langyarns_addi02-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Balaklava-fur-Kinder-gestrickt_Langyarns_addi02-600x600.jpg 600w, https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Balaklava-fur-Kinder-gestrickt_Langyarns_addi02-100x100.jpg 100w, https:\/\/addi.de\/wp-content\/uploads\/2025\/08\/Balaklava-fur-Kinder-gestrickt_Langyarns_addi02.jpg 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Knitting tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Balaklava for Babies<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p><span data-offset-key=\"4m3cj-0-0\">This cuddly Balaklava for Babies, a hat and scarf combination with a beautiful color gradient is knitted in double yarn from soft merino wool. It keeps every baby's head nice and warm. A pattern from Lang Yarns.<\/span><\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/balaklava-fur-babys-stricken\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/09\/Austermann-Schal-stricken-Maxin-520x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/09\/Austermann-Schal-stricken-Maxin-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/575-7_addiNature_Olive_Wood_90mm_frei_4c-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Knitting tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Knit a scarf in a zigzag pattern<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>In the mood for a light and airy, cozy scarf with a gentle knit pattern? This merino and silk scarf with a delicate zigzag pattern has a sophisticated look thanks to its simple yet effective pattern. A tutorial by Austermann.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/schal-stricken-zackenmuster-maxin\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/12\/12-520x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/12\/12-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/775-7_addiPremium-Lace_5mm-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Knitting tutorial                                                         <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Knit cable knit sweater for women - free pattern<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>Master cable knitting with this exclusive, free pattern from ONline. Perfect for knitting enthusiasts who want to discover new techniques. Start your next knitting project now!<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/zopfmuster-pullover-stricken\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/08\/Kinderpullover-Unicorn-stricken-AnleitungIMG_7427-520x300.png\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/08\/Kinderpullover-Unicorn-stricken-AnleitungIMG_7427-520x300.png\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Knitting tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Magical children's jumper \"Unicorn\"<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>Now it's getting magical - when a unicorn jumper is needled on with the addiUnicorn circular knitting needle, unicorn happiness is perfect! The result is a cuddly Unicorn children's jumper that will make the hearts of every little unicorn fan beat faster.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/kinderpullover-unicorn\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/11\/02-Stulpen-Pulswa\u0308rmer-handwarmer-Tilda-Alexstrickt-addi-520x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/11\/02-Stulpen-Pulswa\u0308rmer-handwarmer-Tilda-Alexstrickt-addi-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row image-2-wrapper\">\n                                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/11\/04-Stulpen-Pulswa\u0308rmer-handwarmer-Tilda-Alexstrickt-addi-400x400.jpg\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/11\/04-Stulpen-Pulswa\u0308rmer-handwarmer-Tilda-Alexstrickt-addi-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/11\/04-Stulpen-Pulswa\u0308rmer-handwarmer-Tilda-Alexstrickt-addi-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/11\/04-Stulpen-Pulswa\u0308rmer-handwarmer-Tilda-Alexstrickt-addi-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/11\/04-Stulpen-Pulswa\u0308rmer-handwarmer-Tilda-Alexstrickt-addi-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Knitting tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Knitting wrist warmers \u201cTilda\u201d<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>These small and very stylish wrist warmers are an ideal in-between project for every knitter. A simple design with a very effective spiral pattern that is easily worked with right and left stitches. Knitted in one piece, they are finished very quickly. In addition, yarn scraps from the stash can be used up wonderfully. Also ideal as a gift!<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/pulswaermer-stricken-tilda\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ME8_8360-520x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ME8_8360-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/717-7_addiNovel_Rundstricknadel_50_frei1_4c-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Knitting instruction                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Triangle scarf<br \/>\r\n&#8222;Streifenpaule&#8220;<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>To relax today there is once again a stylish scarf for you. A tutorial from CraSy \u2013 Sylvie Rasch.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/dreieckstuch-streifenpaule\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/m1-3_edle_krawatte-520x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/m1-3_edle_krawatte-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row image-2-wrapper\">\n                                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/addi-Krawatte-stricken-perlmuster-Anleitung-400x400.png\" class=\"attachment-400x400 size-400x400\" alt=\"How it works:\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/addi-Krawatte-stricken-perlmuster-Anleitung-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/addi-Krawatte-stricken-perlmuster-Anleitung-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/addi-Krawatte-stricken-perlmuster-Anleitung.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/addi-Krawatte-stricken-perlmuster-Anleitung-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/addi-Krawatte-stricken-perlmuster-Anleitung-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/addi-Krawatte-stricken-perlmuster-Anleitung-100x100.png 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Knitting tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Knit Tie \u201cKnitting cult\u201d<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>The casual knitted tie is a special highlight that can be knitted quickly and is perfect as a gift.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/krawatte-stricken-im-perlmuster\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/ANL-Yogasocken-520x300.png\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/ANL-Yogasocken-520x300.png\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/710-7_addiSockenwunder_addiSockwonder__Rundstricknadel_cicular_knitting_needle_kleine_Durchmesser_LACE_metall_2-5mm_25cm_US-0-8_100_madeinGermany_frei1_rgb-600x600.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/710-7_addiSockenwunder_addiSockwonder__Rundstricknadel_cicular_knitting_needle_kleine_Durchmesser_LACE_metall_2-5mm_25cm_US-0-8_100_madeinGermany_frei1_rgb-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/710-7_addiSockenwunder_addiSockwonder__Rundstricknadel_cicular_knitting_needle_kleine_Durchmesser_LACE_metall_2-5mm_25cm_US-0-8_100_madeinGermany_frei1_rgb-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/710-7_addiSockenwunder_addiSockwonder__Rundstricknadel_cicular_knitting_needle_kleine_Durchmesser_LACE_metall_2-5mm_25cm_US-0-8_100_madeinGermany_frei1_rgb-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/710-7_addiSockenwunder_addiSockwonder__Rundstricknadel_cicular_knitting_needle_kleine_Durchmesser_LACE_metall_2-5mm_25cm_US-0-8_100_madeinGermany_frei1_rgb-1536x1536.png 1536w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/710-7_addiSockenwunder_addiSockwonder__Rundstricknadel_cicular_knitting_needle_kleine_Durchmesser_LACE_metall_2-5mm_25cm_US-0-8_100_madeinGermany_frei1_rgb-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/710-7_addiSockenwunder_addiSockwonder__Rundstricknadel_cicular_knitting_needle_kleine_Durchmesser_LACE_metall_2-5mm_25cm_US-0-8_100_madeinGermany_frei1_rgb-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/710-7_addiSockenwunder_addiSockwonder__Rundstricknadel_cicular_knitting_needle_kleine_Durchmesser_LACE_metall_2-5mm_25cm_US-0-8_100_madeinGermany_frei1_rgb-1320x1320.png 1320w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/710-7_addiSockenwunder_addiSockwonder__Rundstricknadel_cicular_knitting_needle_kleine_Durchmesser_LACE_metall_2-5mm_25cm_US-0-8_100_madeinGermany_frei1_rgb-100x100.png 100w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/710-7_addiSockenwunder_addiSockwonder__Rundstricknadel_cicular_knitting_needle_kleine_Durchmesser_LACE_metall_2-5mm_25cm_US-0-8_100_madeinGermany_frei1_rgb.png 1600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Knitting tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Yoga Socks with addi sock wonder<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>The yoga socks are stretchable and very easy to knit, as there is neither heel nor toe. They fit both men and women from\nsizes 6 to 11. These socks can easily be made larger or smaller by increasing or reducing the number of stitches.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/yoga-socken-stricken-addisockenwunder\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/09\/09-520x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/09\/09-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/04\/105-7_addiClassic_Rundstricknadel2_125-6mm_frei_rgb.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/04\/105-7_addiClassic_Rundstricknadel2_125-6mm_frei_rgb.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2023\/04\/105-7_addiClassic_Rundstricknadel2_125-6mm_frei_rgb-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2023\/04\/105-7_addiClassic_Rundstricknadel2_125-6mm_frei_rgb-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2023\/04\/105-7_addiClassic_Rundstricknadel2_125-6mm_frei_rgb-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2023\/04\/105-7_addiClassic_Rundstricknadel2_125-6mm_frei_rgb-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2023\/04\/105-7_addiClassic_Rundstricknadel2_125-6mm_frei_rgb-100x100.png 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Knitting tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Knitting tunic<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>A beautiful tunic that is not only fashionable but also comfortable to wear. With this tutorial and high-quality yarn from ONline, you can show off your knitting skills and create a timeless garment for your wardrobe.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/tunika-stricken\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/06\/maschenreise_Strickanleitung_modell_23_Shirt_Limone-520x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/06\/maschenreise_Strickanleitung_modell_23_Shirt_Limone-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/115-7_addiUnicorn_Rundstricknadel_55_frei_4c-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Knitting tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Summer Shirt Lime<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>A breezy tutorial for a raglan summer shirt in combination with a light and airy cotton yarn with cooling and comfortable wearing properties. Perfect for warm days.<\/p>\n<p>The instructions are customisable and can be knitted as a shirt or jumper of any length.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/limone-sommershirt-stricken\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                    <\/div>\n                        <div class=\"row\">\n                            <div class=\"col-12 col-lg-4 offset-lg-4\">\n                                <ol class=\"carousel-indicators\">\n                                                                            <li data-target=\"#teaserCarousel-block_a53f8d3c416f4db87b187c6df6bd8658\" data-slide-to=\"0\"\n                                            class=\"active\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_a53f8d3c416f4db87b187c6df6bd8658\" data-slide-to=\"1\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_a53f8d3c416f4db87b187c6df6bd8658\" data-slide-to=\"2\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_a53f8d3c416f4db87b187c6df6bd8658\" data-slide-to=\"3\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_a53f8d3c416f4db87b187c6df6bd8658\" data-slide-to=\"4\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_a53f8d3c416f4db87b187c6df6bd8658\" data-slide-to=\"5\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_a53f8d3c416f4db87b187c6df6bd8658\" data-slide-to=\"6\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_a53f8d3c416f4db87b187c6df6bd8658\" data-slide-to=\"7\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_a53f8d3c416f4db87b187c6df6bd8658\" data-slide-to=\"8\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_a53f8d3c416f4db87b187c6df6bd8658\" data-slide-to=\"9\"\n                                            class=\"\"><\/li>\n                                                                    <\/ol>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"teaser-block_b876102c9b3e407c7e489280d5a106ff\" class=\"teaser alignment-left\" >\n    <section>\n        <div class=\"container\">\n                                                <div id=\"teaserCarousel-block_b876102c9b3e407c7e489280d5a106ff\" class=\"carousel slide keepsize-responsive\">\n                        <div class=\"carousel-inner\" data-countslides=\"2\">\n                                                            <div class=\"carousel-item active\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6 order-2 order-lg-1\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Story                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                        <h2>The colour theory.<h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>In the last article you learned a lot about combining colours. With the right choice of colours, you can create atmosphere and strongly influence how things appear. Perhaps you have already discovered a colour contrast that you particularly like?<\/p>\n<p>In addition, you can read more about the theory of colour theory below.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/die-farbenlehre\/' target='_self' class='buttonlink prio-1'>Read story<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                            <div class=\"col-12 col-lg-6 order-1 order-lg-2\">\n                                                                                                    <div class=\"images-wrapper\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10 offset-lg-2\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/08\/farbenlehre-farbkontraste-harmonien-520x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/08\/farbenlehre-farbkontraste-harmonien-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row image-2-wrapper\">\n                                                                    <div class=\"col-12 col-lg-6\">\n                                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/08\/farbenlehre-kontraste-und-harmonienpexels-anni-roenkae-3625632-400x400.jpg\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/08\/farbenlehre-kontraste-und-harmonienpexels-anni-roenkae-3625632-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/08\/farbenlehre-kontraste-und-harmonienpexels-anni-roenkae-3625632-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/08\/farbenlehre-kontraste-und-harmonienpexels-anni-roenkae-3625632-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/08\/farbenlehre-kontraste-und-harmonienpexels-anni-roenkae-3625632-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-1\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6 order-2 order-lg-1\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Story                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                        <h2>Trust your eye.<h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>Colours are a part of us, and have a role in our individual wellbeing. For example, choosing the right colours creates a positive atmosphere \u2013 most importantly in the home.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/farben-kombinieren-das-auge-strickt-mit\/' target='_self' class='buttonlink prio-1'>Read story<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                            <div class=\"col-12 col-lg-6 order-1 order-lg-2\">\n                                                                                                    <div class=\"images-wrapper\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10 offset-lg-2\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/06\/Sommergarne-Kurtenbach_Materialkunde_Bild-Nr.-4-520x400.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/06\/Sommergarne-Kurtenbach_Materialkunde_Bild-Nr.-4-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                    <\/div>\n                        <div class=\"row\">\n                            <div class=\"col-12 col-lg-4 offset-lg-4\">\n                                <ol class=\"carousel-indicators\">\n                                                                            <li data-target=\"#teaserCarousel-block_b876102c9b3e407c7e489280d5a106ff\" data-slide-to=\"0\"\n                                            class=\"active\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_b876102c9b3e407c7e489280d5a106ff\" data-slide-to=\"1\"\n                                            class=\"\"><\/li>\n                                                                    <\/ol>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"teaser-block_bfb1523d3fda6be374ce5d5db8705fff\" class=\"teaser toc alignment-right\"  data-toctitle=\"H\u00e4kelanleitungen\">\n    <section>\n        <div class=\"container\">\n                                                <div id=\"teaserCarousel-block_bfb1523d3fda6be374ce5d5db8705fff\" class=\"carousel slide keepsize-responsive\">\n                        <div class=\"carousel-inner\" data-countslides=\"8\">\n                                                            <div class=\"carousel-item active\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/06\/Irina-Hut-520x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/06\/Irina-Hut-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row image-2-wrapper\">\n                                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/06\/Irina-Hut-hakeln-02-400x400.jpg\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" data-srcset=\"\" \/>                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Crochet tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Crochet summer hat<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>An individual summer hat in the right size protects your head from the sun and is a beautiful accessory. Made from strong yarn, it is quick to crochet and keeps its shape well.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/sommerhut-haekeln-irina\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-1\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/07\/addiPealrls-Halskette-hakeln-mit-Draht-und-Perlen-Anleitung10-520x400.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/07\/addiPealrls-Halskette-hakeln-mit-Draht-und-Perlen-Anleitung10-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Crochet tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Crochet necklace with beads<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>These crochet instructions were part of a popular set from our addiPearls collection a few years ago. Today, we are bringing the instructions back in a fresh new form because we believe that trends always come back, and crocheted pearl necklaces are currently enjoying a comeback.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/haekelkette-mit-perlen-haekeln\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-3\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-4 offset-lg-6\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/05\/Hakeldecke_Granny-Squares_Mille-Colori_Lang-01-200x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/05\/Hakeldecke_Granny-Squares_Mille-Colori_Lang-01-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row image-2-wrapper\">\n                                                                    <div class=\"col-12 col-lg-8\">\n                                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/05\/Hakeldecke_Granny-Squares_Mille-Colori_Lang-02-400x400.jpg\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/05\/Hakeldecke_Granny-Squares_Mille-Colori_Lang-02-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2025\/05\/Hakeldecke_Granny-Squares_Mille-Colori_Lang-02-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2025\/05\/Hakeldecke_Granny-Squares_Mille-Colori_Lang-02-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2025\/05\/Hakeldecke_Granny-Squares_Mille-Colori_Lang-02-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Crochet tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Crochet granny square blanket \u201cMille Colori\u201d<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>Colorful Granny Squares make you want to create colorful projects. Here they are used to make the cozy Granny Square blanket in soft merino yarn. A design from Lang Yarns.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/granny-square-decke-mille-colori-lang\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/06\/Kiwi-Tasche_4-520x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/06\/Kiwi-Tasche_4-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2024\/02\/597-2_addiNature-Purple_Unicorn-Haekelnadel_045mm-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Crochet tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Crochet kiwi bag<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <div class=\"text\">\n<p>Crochet a fruity, fresh kiwi bag - for fruit lovers and trendsetters. Made from cotton yarn, it is soft and washable and therefore ready for any use.<\/p>\n<p>An absolute highlight for every outfit.<\/p>\n<\/div>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/kiwi-tasche-hakeln\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/addi-Granny-Rucksack-02-520x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/addi-Granny-Rucksack-02-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Crochet tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Backpack crochet from Granny Squares<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>A wonderful summer project that offers enough space for your current crochet work. The basic instructions for Granny Squares can also be found on our website.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/rucksack-grannysquares\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Einhorn-Anstecker-Titelbild-520x300.png\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Einhorn-Anstecker-Titelbild-520x300.png\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6 offset-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Crochet tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Unicorn pin crochet<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>Something to dream about, something glittery or something colorful - design your individual unicorn pin<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/einhorn-haekeln-anstecker\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-1\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Ha\u0308kelanleitung-Untersetzer-Bloggerbox-1-rosa-520x400.png\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Ha\u0308kelanleitung-Untersetzer-Bloggerbox-1-rosa-520x300.png\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Crochet tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Unicorn coaster <br \/>\r\ncrochet with elegant spiral structure<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>Simple and effective: a circular coaster with a sophisticated spiral structure.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/untersetzer-unicorn-haekeln\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-1\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                                                                    <div class=\"images-wrapper\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/Friedensbaum-Haekelanleitungen1-520x400.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/02\/Friedensbaum-Haekelanleitungen1-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                            <div class=\"col-12 col-lg-6\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Crochet tutorial                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                            <h2>Crochet heart<\/h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>A quick crochet heart - perfect for lovely greetings that are understood in any language and don't need words. An instruction by Sylvie Rasch.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/herz-haekeln\/' target='_self' class='buttonlink prio-1'>Read tutorial<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                    <\/div>\n                        <div class=\"row\">\n                            <div class=\"col-12 col-lg-4 offset-lg-4\">\n                                <ol class=\"carousel-indicators\">\n                                                                            <li data-target=\"#teaserCarousel-block_bfb1523d3fda6be374ce5d5db8705fff\" data-slide-to=\"0\"\n                                            class=\"active\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_bfb1523d3fda6be374ce5d5db8705fff\" data-slide-to=\"1\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_bfb1523d3fda6be374ce5d5db8705fff\" data-slide-to=\"2\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_bfb1523d3fda6be374ce5d5db8705fff\" data-slide-to=\"3\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_bfb1523d3fda6be374ce5d5db8705fff\" data-slide-to=\"4\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_bfb1523d3fda6be374ce5d5db8705fff\" data-slide-to=\"5\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_bfb1523d3fda6be374ce5d5db8705fff\" data-slide-to=\"6\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_bfb1523d3fda6be374ce5d5db8705fff\" data-slide-to=\"7\"\n                                            class=\"\"><\/li>\n                                                                    <\/ol>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"teaser-block_3083a34fa3edb8a0234c3e0f8918f197\" class=\"teaser alignment-left\" >\n    <section>\n        <div class=\"container\">\n                                                <div id=\"teaserCarousel-block_3083a34fa3edb8a0234c3e0f8918f197\" class=\"carousel slide keepsize-responsive\">\n                        <div class=\"carousel-inner\" data-countslides=\"4\">\n                                                            <div class=\"carousel-item active\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6 order-2 order-lg-1\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Stine&amp;Stitch &#8211; Kerstin Balke                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                        <h2>Her big love: colorful socks with jacquard patterns and stripes<h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>Starting in 2010 as a small blog for sewn and knitted things, Stine&amp;Stitchis now an online store for sock knitters who are just as addicted to soxx as Kerstin is.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/stinestitch-kerstin-balke\/' target='_self' class='buttonlink prio-1'>Stine&amp;Stitch &#8211; Kerstin Balke<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                            <div class=\"col-12 col-lg-6 order-1 order-lg-2\">\n                                                                                                    <div class=\"images-wrapper\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10 offset-lg-2\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/10\/Stine-Stitch_Kerstin-Balke_addi-520x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/10\/Stine-Stitch_Kerstin-Balke_addi-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row image-2-wrapper\">\n                                                                    <div class=\"col-12 col-lg-6\">\n                                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/10\/Profilbild-Kerstin-Balke-scaled-400x400.jpg\" class=\"attachment-400x400 size-400x400\" alt=\"Kerstin Balke - Stine&amp;Stitch addi\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/10\/Profilbild-Kerstin-Balke-scaled-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2023\/10\/Profilbild-Kerstin-Balke-scaled-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2023\/10\/Profilbild-Kerstin-Balke-scaled-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2023\/10\/Profilbild-Kerstin-Balke-scaled-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6 order-2 order-lg-1\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            CraSy \u2013 Sylvie Rasch                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                        <h2>\u201cCraSy\u201d is the program<h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>Sylvie Rasch is simply a creative jack-of-all-trades. For her, being creative is like breathing \u2013 she just can\u2019t do any other way! Whether knitting, sewing, crocheting or cooking, new techniques and creative ideas just bubble out of her.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/crasy-sylvie-rasch\/' target='_self' class='buttonlink prio-1'>Read story<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                            <div class=\"col-12 col-lg-6 order-1 order-lg-2\">\n                                                                                                    <div class=\"images-wrapper\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10 offset-lg-2\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/CraSy-Sylvie-Rasch-Logo-addi-influencer-520x300.png\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/CraSy-Sylvie-Rasch-Logo-addi-influencer-520x300.png\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row image-2-wrapper\">\n                                                                    <div class=\"col-12 col-lg-6\">\n                                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/crasy-sylvie-rasch-foto-influencerin-bei-addi-scaled-400x400.jpeg\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/crasy-sylvie-rasch-foto-influencerin-bei-addi-scaled-400x400.jpeg 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/crasy-sylvie-rasch-foto-influencerin-bei-addi-scaled-800x800.jpeg 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/crasy-sylvie-rasch-foto-influencerin-bei-addi-scaled-300x300.jpeg 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/crasy-sylvie-rasch-foto-influencerin-bei-addi-scaled-100x100.jpeg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative inherit images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6 order-2 order-lg-1\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Woolly Hugs - Veronika Hug                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                        <h2>As simple as possible, as good as possible.<h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>For crochet and knitting fans there is no way around her: Veronika Hug is a Youtube star, successful on Facebook and of course also analog on the go ;-). She has published countless books on various needlework techniques and as an editor is responsible for the success of many magazines.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/woolly-hugs-veronika-hug\/' target='_self' class='buttonlink prio-1'>Read story<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                            <div class=\"col-12 col-lg-6 order-1 order-lg-2\">\n                                                                                                    <div class=\"images-wrapper\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10 offset-lg-2\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Veronika-Hug-Woolly-Hugs-Logo-Influencer-Blogger-520x300.png\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Veronika-Hug-Woolly-Hugs-Logo-Influencer-Blogger-520x300.png\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row image-2-wrapper\">\n                                                                    <div class=\"col-12 col-lg-6\">\n                                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Veronica-Hug-Blogger-InfluencerVeronika-Hug-17-scaled-400x400.jpg\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Veronica-Hug-Blogger-InfluencerVeronika-Hug-17-scaled-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Veronica-Hug-Blogger-InfluencerVeronika-Hug-17-scaled-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Veronica-Hug-Blogger-InfluencerVeronika-Hug-17-scaled-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/Veronica-Hug-Blogger-InfluencerVeronika-Hug-17-scaled-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item\">\n                                                                                                                <div class=\"row position-relative noble images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6 order-2 order-lg-1\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                             Yarn around the world - Fanny Mitula                                                         <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                        <h2>Fanny travels around the world with addi<h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>In summer 2019 addi started the project \u201cwith addi around the world\u201d with Fanny from yarn around the world. DIY &amp; crochet book author Fanny has constant wanderlust. She started her trip around the world at the beginning of August 2019. With her was a little backpack full of yarn as well as a selection of addi tools. In foreign countries she met other handicraft enthusiasts as well as addi products in local yarn stores.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/yarn-around-the-world-fanny-mitula\/' target='_self' class='buttonlink prio-1'>Read story<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                            <div class=\"col-12 col-lg-6 order-1 order-lg-2\">\n                                                                                                    <div class=\"images-wrapper\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10 offset-lg-2\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/yarnaroundtheworld-Fanni-Mitula-Logo-addi-influencer-520x300.png\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/yarnaroundtheworld-Fanni-Mitula-Logo-addi-influencer-520x300.png\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row image-2-wrapper\">\n                                                                    <div class=\"col-12 col-lg-6\">\n                                                                        <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/1_Fanny_HelloWorld-768x702yarnaroundtheworld_Blogbeitrag-400x400.jpg\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/1_Fanny_HelloWorld-768x702yarnaroundtheworld_Blogbeitrag-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/1_Fanny_HelloWorld-768x702yarnaroundtheworld_Blogbeitrag-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/1_Fanny_HelloWorld-768x702yarnaroundtheworld_Blogbeitrag-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                    <\/div>\n                        <div class=\"row\">\n                            <div class=\"col-12 col-lg-4 offset-lg-4\">\n                                <ol class=\"carousel-indicators\">\n                                                                            <li data-target=\"#teaserCarousel-block_3083a34fa3edb8a0234c3e0f8918f197\" data-slide-to=\"0\"\n                                            class=\"active\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_3083a34fa3edb8a0234c3e0f8918f197\" data-slide-to=\"1\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_3083a34fa3edb8a0234c3e0f8918f197\" data-slide-to=\"2\"\n                                            class=\"\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_3083a34fa3edb8a0234c3e0f8918f197\" data-slide-to=\"3\"\n                                            class=\"\"><\/li>\n                                                                    <\/ol>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"cta-block_07cd3a545f159d73ef7ef35f050eae07\" class=\"cta\" >\n    <section>\n        <div class=\"container\">\n                            <div class=\"row\">\n                    <div class=\"col-12 col-lg-6 offset-lg-3\">\n                        <h2 class=\"script\">Show all stories<\/h2>\n                    <\/div>\n                <\/div>\n                                                                    <div class=\"row\">\n                                                            <div class=\"col-12 col-lg-4 offset-lg-4\">\n                                    <a href='https:\/\/addi.de\/en\/story\/' target='_self' class='buttonlink prio-1'>Go to blog<\/a>                                <\/div>\n                                                    <\/div>\n                                                <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"selection-teaser-block_3a354fec1b5b536bd3e0eaba99f9f0da\" class=\"selection-teaser\" >\n    <section>\n        <div class=\"container\">\n                            <div class=\"row\">\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper inherit\">\n                            <div class=\"image-wrapper\">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/addi_Philosophie-400x320.png\" class=\"attachment-400x320 size-400x320\" alt=\"Free instructions\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Page                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        Philosophy                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        Made in Germany. Our promise.                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>addi needles and hooks are synonymous with excellence for knitting and crochet fans around the world.<\/p>\n<p>Our addi philosophy: the origin of our products is always traceable. Fair working conditions, regional materials and quality are important to us.<\/p>\n<p>&nbsp;<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href='https:\/\/addi.de\/en\/philosophie\/' target='_self' class='buttonlink prio-2'>Learn more<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper inspiration\">\n                            <div class=\"image-wrapper\">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/inspiration_keyvisual_small-400x320.png\" class=\"attachment-400x320 size-400x320\" alt=\"\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Page                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        Magazin                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        Inspiration for your hands.                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>Looking for new ideas or want to find out what\u2019s going on in our community? You\u2019ve come to the right place.<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href='https:\/\/addi.de\/en\/magazin-inspiration\/' target='_self' class='buttonlink prio-2'>Read Magazin<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper balance\">\n                            <div class=\"image-wrapper\">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/balance_keyvisual_small-400x320.png\" class=\"attachment-400x320 size-400x320\" alt=\"\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Page                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        Magazin                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        Balance for your hands.                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>This addi Magazine regularly features new reports on topics such as the therapeutic effect of knitting, plus (of course) great knitting and crochet patterns.<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href='https:\/\/addi.de\/en\/magazin-balance\/' target='_self' class='buttonlink prio-2'>Read Magazin<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/section>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"kategorie_pages":[25],"class_list":["post-2014","page","type-page","status-publish","hentry","kategorie_pages-noble"],"acf":[],"_links":{"self":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/pages\/2014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/comments?post=2014"}],"version-history":[{"count":11,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/pages\/2014\/revisions"}],"predecessor-version":[{"id":74691,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/pages\/2014\/revisions\/74691"}],"wp:attachment":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/media?parent=2014"}],"wp:term":[{"taxonomy":"kategorie_pages","embeddable":true,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/kategorie_pages?post=2014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}