{"id":24015,"date":"2022-06-10T12:00:00","date_gmt":"2022-06-10T10:00:00","guid":{"rendered":"https:\/\/addi.de\/?post_type=story&#038;p=24015"},"modified":"2024-11-18T18:43:44","modified_gmt":"2024-11-18T17:43:44","slug":"grannysquares","status":"publish","type":"story","link":"https:\/\/addi.de\/en\/story\/grannysquares\/","title":{"rendered":"Granny Square &#8222;Kreis&#8220; Grundanleitung"},"content":{"rendered":"<div id=\"header-text-block_23547834b5cb889cc2041374e15f9573\" class=\"header-text\" >\n    <section>\n        <div class=\"container\">\n            <div class=\"row position-relative\">\n                <div class=\"col-12 col-lg-3 offset-lg-1 order-2 order-lg-1\">\n                    <div class=\"text-wrapper\">\n                        <div class=\"color-area-secondary\"><\/div>\n                                                    <div class=\"topline hl-color\">\n                                Grundanleitung                            <\/div>\n                                                                                                    <h1>Granny Square &#8222;Kreis&#8220; h\u00e4keln<\/h1>\n                                                <div class=\"share-links\">\n                            <span>Teilen:<\/span>\n                            <a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Faddi.de%2Fen%2Fstory%2Fgrannysquares%2F\" class=\"d-inline-block px-2\" onclick=\"window.open(this.href, 'mywin', 'left=20,top=20,width=500,height=500,toolbar=1,resizable=0'); return false;\"><i class=\"fab fa-facebook-f hl-color\"><\/i><\/a>\n                            <a href=\"https:\/\/twitter.com\/intent\/tweet?text=https%3A%2F%2Faddi.de%2Fen%2Fstory%2Fgrannysquares%2F\" class=\"d-inline-block px-2\" onclick=\"window.open(this.href, 'mywin', 'left=20,top=20,width=500,height=500,toolbar=1,resizable=0'); return false;\"><i class=\"fa-brands fa-x-twitter hl-color\"><\/i><\/a>\n                        <\/div>\n                        <div class=\"text\">\n                            <p>Ein einfaches Granny Square, das rundes und eckiges in Einklang bringt. Die Granny Squares lassen sich zu gro\u00dfen Objekten, wie Taschen, Decken und vielen weiteren Accessoires zusammensetzen.<\/p>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                <div class=\"col-12 col-lg-7 offset-lg-1 mb-3 mb-lg-0 order-1 order-lg-2\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"970\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Granny-Square-aus-Kreis-ha\u0308keln-1-1080x970.jpg\" class=\"attachment-1280x970 size-1280x970\" alt=\"Kostenlose H\u00e4kelanleitungen Granny Squares\" \/>                                        <div class=\"row toc-wrapper\">\n                        <div class=\"col-12 col-lg-6 offset-lg-5\">\n                            <div class=\"toc-title\">\n                                Inhaltsverzeichnis                            <\/div>\n                            <div class=\"toc-content\">\n\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<\/div>\n\n\n\n<div id=\"infobox-block_4ac3849447292eca72b7e62b25728ea6\" class=\"infobox\" >\n    <section>\n        <div class=\"container-fluid container-md\">\n            <div class=\"row\">\n                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                    <div class=\"infobox-wrapper\">\n                        \n                        <div class=\"row\">\n                            <div class=\"col-7 col-sm-5 col-md-2 col-lg-2 col-xl-2\">\n                                <div class=\"difficulty-wrapper color-area-primary\" style=\"position:relative; z-index:1;\">\n                                                                                <i class=\"fa-solid fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-solid fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-regular fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-regular fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-regular fa-heart d-inline-block d-md-block\"><\/i>\n                                                                            <\/div>\n                            <\/div>\n                            <div class=\"col-12 col-md-6 col-lg-6 col-xl-7\">\n                            <div class=\"color-area-secondary\" style=\"right: 5%;\"><\/div>\n                                <div class=\"text-wrapper\">\n                                                                            <div class=\"topline hl-color\" style=\"position:relative; z-index:1;\">\n                                            Was ben\u00f6tigt wird:                                        <\/div>\n                                                                                                                <div class=\"text\">\n                                            <div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"evdfu-0-0\">\n<ul>\n<li class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"evdfu-0-0\"><span data-offset-key=\"evdfu-0-0\">Baumwollgarn (105m\/50g) in 2 Farben <\/span>\n<ul>\n<li class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"evdfu-0-0\"><span data-offset-key=\"evdfu-0-0\">z.B. Essentials organic cotton dk von Rico Design (100% Baumwolle) <\/span><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"15t34-0-0\">\n<ul>\n<li><span data-offset-key=\"cnktc-0-0\">addiNature Olivenholz H\u00e4kelnadel in 3,5mm<\/span><\/li>\n<li><span data-offset-key=\"cnktc-0-0\">Wollnadel <\/span><\/li>\n<li><span data-offset-key=\"352to-0-0\">Schere<\/span><\/li>\n<\/ul>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"352to-0-0\"><\/div>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                            <div class=\"col-7 col-offset-3 col-md-3 col-lg-4 col-xl-3\">\n                                <a href=\"https:\/\/addi.de\/en\/produkt\/addinature-olive-wood-wollhaekelnadel\/\">\n                                <div class=\"wrapper-nk\">\n                                    <div class=\"color-area-primary\"><\/div>\n                                        <div class=\"produkt-wraper-nk\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/577-7_addiNature_Olive_Wood_45mm_frei_4c-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                        <\/div>\n                                    <\/div>\n                                    <div class=\"headline-rodukt-nk hl-color\">\n                                        <p><\/p>\n                                        <p>addiNature Olive Wood Wollh\u00e4kelnadel<\/p>\n                                    <\/div>\n                                <\/div>\n                                <\/a>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<\/div>\n\n\n\n            \n<div id=\"text-gallery-video-block_aa9c63e11163fc0b90ab34ccd11e7bc0\" class=\"text-gallery-video toc alignment-left noble\"  data-toctitle=\"Abk\u00fcrzungen\">\n    <section>\n        <div class=\"container position-relative\">\n            \n\n                                                                                <div class=\"gallery-wrapper  d-lg-block\">\n                                                                                                                        <div class=\"text-wrapper mb-5\">\n                                                                                                                                                                                                    <div class=\"row\">\n                                                        <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                            \n                                                            <div class=\"heading-tag\">\n                                                                <h2> Abk\u00fcrzungen <\/h2>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                                                                    <div class=\"row\">\n                                                        <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                            <div class=\"text\">\n                                                                <div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"ftesv-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"ftesv-0-0\"><span data-offset-key=\"ftesv-0-0\"><strong>Lfm<\/strong> = Luftmasche(n)<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"2flg7-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2flg7-0-0\"><span data-offset-key=\"2flg7-0-0\"><strong>MR<\/strong> = Fadenring\/Magischer Ring<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"1gisl-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"1gisl-0-0\"><span data-offset-key=\"1gisl-0-0\"><strong>fM<\/strong> = Feste Masche(n)<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"dnov3-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"dnov3-0-0\"><span data-offset-key=\"dnov3-0-0\"><strong>Stb<\/strong> = St\u00e4bchen<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"dc8cs-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"dc8cs-0-0\"><span data-offset-key=\"dc8cs-0-0\"><strong>hStb<\/strong> = halbe(s) St\u00e4bchen<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"aonpg-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"aonpg-0-0\"><span data-offset-key=\"aonpg-0-0\"><strong>Km<\/strong> = Kettmasche(n)<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"8b00t-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"8b00t-0-0\"><span data-offset-key=\"8b00t-0-0\"><strong>Rd<\/strong> = Runde(n)<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"e7aj8-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"e7aj8-0-0\"><span data-offset-key=\"e7aj8-0-0\"><strong>wdh<\/strong> = wiederholen<\/span><\/div>\n<\/div>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                                                                                                            <\/div>\n                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                                                                                    <\/div>\n                                            <\/div>\n                                                                                                                                                        <\/div>\n                               \n                                 \n                            <div class=\"gallery-wrapper d-block d-lg-none\">\n                                                                    <div class=\"text-wrapper mb-5\">\n                                                                                                                                                                    <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                              \n                                                    <div class=\"heading-tag\">\n                                                        <h2>Abk\u00fcrzungen<\/h2>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                    <div class=\"text\">\n                                                        <div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"ftesv-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"ftesv-0-0\"><span data-offset-key=\"ftesv-0-0\"><strong>Lfm<\/strong> = Luftmasche(n)<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"2flg7-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2flg7-0-0\"><span data-offset-key=\"2flg7-0-0\"><strong>MR<\/strong> = Fadenring\/Magischer Ring<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"1gisl-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"1gisl-0-0\"><span data-offset-key=\"1gisl-0-0\"><strong>fM<\/strong> = Feste Masche(n)<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"dnov3-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"dnov3-0-0\"><span data-offset-key=\"dnov3-0-0\"><strong>Stb<\/strong> = St\u00e4bchen<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"dc8cs-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"dc8cs-0-0\"><span data-offset-key=\"dc8cs-0-0\"><strong>hStb<\/strong> = halbe(s) St\u00e4bchen<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"aonpg-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"aonpg-0-0\"><span data-offset-key=\"aonpg-0-0\"><strong>Km<\/strong> = Kettmasche(n)<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"8b00t-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"8b00t-0-0\"><span data-offset-key=\"8b00t-0-0\"><strong>Rd<\/strong> = Runde(n)<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"1peqt\" data-offset-key=\"e7aj8-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"e7aj8-0-0\"><span data-offset-key=\"e7aj8-0-0\"><strong>wdh<\/strong> = wiederholen<\/span><\/div>\n<\/div>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                                                            <\/div>\n                                                                            <div class=\"row mb-4\">\n                                            <div class=\"col-12\">\n                                                                                            <\/div>\n                                        <\/div>\n                                                                                                                                                                                                            <\/div>\n                                                                                    <\/div>\n    <\/section>\n<\/div>\n\n            \n        <div class=\"modal fade modal-move-to-body gallery-modal noble\" id=\"modal-text-gallery-video-block_aa9c63e11163fc0b90ab34ccd11e7bc0\" tabindex=\"-1\"\n             aria-labelledby=\"modal-text-gallery-video-block_aa9c63e11163fc0b90ab34ccd11e7bc0\" aria-hidden=\"true\">\n            <div class=\"modal-dialog modal-xl modal-dialog-centered\">\n                <div class=\"modal-content\">\n                    <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n                        <i class=\"fas fa-times\"><\/i>\n                    <\/button>\n                    <div class=\"modal-body\">\n                        <div class=\"container-fluid\">\n                                                            <div class=\"row\">\n                                    <div class=\"col-12\">\n                                        <div class=\"row carousel-item-image-wrapper\">\n                                            <div class=\"col-12\">\n                                                <div class=\"carousel-item-image\">\n                                                    <div class=\"color-area-secondary\"><\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                            <\/div>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    \n\n\n            \n<div id=\"text-gallery-video-block_939696c82d11a6887355493f15d8b3cf\" class=\"text-gallery-video toc alignment-left noble\"  data-toctitle=\"So wird es gemacht\">\n    <section>\n        <div class=\"container position-relative\">\n            \n\n                                                                                <div class=\"gallery-wrapper  d-lg-block\">\n                                                                                                                        <div class=\"row align-items-end\">\n                                                <div class=\"col-12 col-lg-6 offset-lg-1\">\n                                                    <div class=\"text-wrapper mb-3\">\n                                                                                                                                                                                                                                    <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    \n                                                                    <div class=\"heading-tag\">\n                                                                        <h2> So wird es gemacht: <\/h2>\n                                                                    <\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                            <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    <div class=\"text\">\n                                                                        <p><span data-offset-key=\"5378l-0-0\">Das Granny Square wird zweifarbig in Runden geh\u00e4kelt. Du startest mit der ersten Farbe in der Mitte mit einem Fadenring und h\u00e4kelst zun\u00e4chst einen Kreis. Ist dieser fertig, beendest Du die H\u00e4kelarbeit und setzt den neuen Faden in der zweiten Farbe neu an, um aus dem Kreis ein Quadrat zu machen.<\/span><\/p>\n                                                                    <\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                                                                            <\/div>\n                                                    <div class=\"row\">\n                                                        <div class=\"col-12 col-lg-8 offset-lg-4\">\n                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_939696c82d11a6887355493f15d8b3cf\">\n                                                                    <img loading=\"lazy\" decoding=\"async\" width=\"520\" height=\"300\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-01-520x300.jpg\" class=\"attachment-520x300 size-520x300\" alt=\"\" \/>                                                                <\/div>\n                                                                                                                    <\/div>\n                                                    <\/div>\n                                                                                                            <div class=\"scriptheadlinespacer\"><\/div>\n                                                                                                                    <div class=\"buttonspacer\"><\/div>\n                                                                                                                                                            <\/div>\n                                                <div class=\"col-12 col-lg-4\">\n                                                    <div class=\"row mb-3\">\n                                                        <div class=\"col-12 col-lg-9\">\n                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_939696c82d11a6887355493f15d8b3cf\">\n                                                                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Granny-Square-aus-Kreis-ha\u0308keln-4-400x320.jpg\" class=\"attachment-400x320 size-400x320\" alt=\"\" \/>                                                                <\/div>\n                                                                                                                    <\/div>\n                                                    <\/div>\n                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_939696c82d11a6887355493f15d8b3cf\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-02-DE-400x320.jpg\" class=\"attachment-400x320 size-400x320\" alt=\"\" \/>                                                        <\/div>\n                                                                                                                                                        <\/div>\n                                            <\/div>\n                                                                                                            <\/div>\n                               \n                                 \n                            <div class=\"gallery-wrapper d-block d-lg-none\">\n                                                                    <div class=\"text-wrapper mb-5\">\n                                                                                                                                                                    <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                              \n                                                    <div class=\"heading-tag\">\n                                                        <h2>So wird es gemacht:<\/h2>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                    <div class=\"text\">\n                                                        <p><span data-offset-key=\"5378l-0-0\">Das Granny Square wird zweifarbig in Runden geh\u00e4kelt. Du startest mit der ersten Farbe in der Mitte mit einem Fadenring und h\u00e4kelst zun\u00e4chst einen Kreis. Ist dieser fertig, beendest Du die H\u00e4kelarbeit und setzt den neuen Faden in der zweiten Farbe neu an, um aus dem Kreis ein Quadrat zu machen.<\/span><\/p>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                                                            <\/div>\n                                                                            <div class=\"row mb-4\">\n                                            <div class=\"col-12\">\n                                                                                                    <div id=\"galleryCarousel-block_939696c82d11a6887355493f15d8b3cf\" class=\"carousel slide\" data-ride=\"carousel\" data-interval=\"2500\" data-pause=\"false\" data-keyboard=\"false\">\n                                                        <div class=\"carousel-inner\" data-countslides=\"3\">\n                                                                                                                            <div class=\"carousel-item active\">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_939696c82d11a6887355493f15d8b3cf\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Granny-Square-aus-Kreis-ha\u0308keln-4-1280x970.jpg\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Granny-Square-aus-Kreis-ha\u0308keln-4-400x320.jpg\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                            <div class=\"carousel-item \">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_939696c82d11a6887355493f15d8b3cf\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-02-DE-1280x970.jpg\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-02-DE-400x320.jpg\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                            <div class=\"carousel-item \">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_939696c82d11a6887355493f15d8b3cf\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-01-1280x970.jpg\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-01-400x320.jpg\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                    <\/div>\n                                                    <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                                                                                                                                                            <\/div>\n                                                                                    <\/div>\n    <\/section>\n<\/div>\n\n            \n        <div class=\"modal fade modal-move-to-body gallery-modal noble\" id=\"modal-text-gallery-video-block_939696c82d11a6887355493f15d8b3cf\" tabindex=\"-1\"\n             aria-labelledby=\"modal-text-gallery-video-block_939696c82d11a6887355493f15d8b3cf\" aria-hidden=\"true\">\n            <div class=\"modal-dialog modal-xl modal-dialog-centered\">\n                <div class=\"modal-content\">\n                    <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n                        <i class=\"fas fa-times\"><\/i>\n                    <\/button>\n                    <div class=\"modal-body\">\n                        <div class=\"container-fluid\">\n                                                            <div id=\"modal-carousel-text-gallery-video-block_939696c82d11a6887355493f15d8b3cf\" class=\"carousel slide keepsize\">\n                                    <div class=\"carousel-inner\" data-countslides=\"3\">\n                                                                                    <div class=\"carousel-item active\">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Granny-Square-aus-Kreis-ha\u0308keln-4.jpg\" class=\"attachment-full size-full wpsmartcrop-image wpsmartcrop-image\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Granny-Square-aus-Kreis-ha\u0308keln-4.jpg 1080w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Granny-Square-aus-Kreis-ha\u0308keln-4-768x768.jpg 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Granny-Square-aus-Kreis-ha\u0308keln-4-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Granny-Square-aus-Kreis-ha\u0308keln-4-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Granny-Square-aus-Kreis-ha\u0308keln-4-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Granny-Square-aus-Kreis-ha\u0308keln-4-600x600.jpg 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/Granny-Square-aus-Kreis-ha\u0308keln-4-100x100.jpg 100w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" data-smartcrop-focus=\"[53,25]\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                                    <div class=\"carousel-item \">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1600\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-02-DE.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-02-DE.jpg 1600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-02-DE-768x768.jpg 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-02-DE-1536x1536.jpg 1536w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-02-DE-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-02-DE-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-02-DE-1320x1320.jpg 1320w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-02-DE-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-02-DE-600x600.jpg 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-02-DE-100x100.jpg 100w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                                    <div class=\"carousel-item \">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1600\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-01.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-01.jpg 1600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-01-768x768.jpg 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-01-1536x1536.jpg 1536w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-01-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-01-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-01-1320x1320.jpg 1320w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-01-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-01-600x600.jpg 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/06\/ANL-GrannySquares-01-100x100.jpg 100w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                            <\/div>\n                                    <a class=\"carousel-control-prev\" href=\"#modal-carousel-text-gallery-video-block_939696c82d11a6887355493f15d8b3cf\" role=\"button\" data-slide=\"prev\">\n                                        <i class=\"fas fa-angle-left\"><\/i>\n                                    <\/a>\n                                    <a class=\"carousel-control-next\" href=\"#modal-carousel-text-gallery-video-block_939696c82d11a6887355493f15d8b3cf\" role=\"button\" data-slide=\"next\">\n                                        <i class=\"fas fa-angle-right\"><\/i>\n                                    <\/a>\n                                    <div class=\"carousel-indicators-wrapper\">\n                                        <ol class=\"carousel-indicators\">\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_939696c82d11a6887355493f15d8b3cf\" data-slide-to=\"0\"\n                                                    class=\"active\"><\/li>\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_939696c82d11a6887355493f15d8b3cf\" data-slide-to=\"1\"\n                                                    class=\"\"><\/li>\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_939696c82d11a6887355493f15d8b3cf\" data-slide-to=\"2\"\n                                                    class=\"\"><\/li>\n                                                                                    <\/ol>\n                                    <\/div>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    \n\n\n            \n<div id=\"text-gallery-video-block_d57684d6f5b471f3b32f511bf8eb344a\" class=\"text-gallery-video alignment-left noble\" >\n    <section>\n        <div class=\"container position-relative\">\n            \n\n                                                                                <div class=\"gallery-wrapper  d-lg-block\">\n                                                                                                                        <div class=\"text-wrapper mb-5\">\n                                                                                                                                                                                                                                                    <div class=\"row\">\n                                                        <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                            <div class=\"text\">\n                                                                <div data-block=\"true\" data-editor=\"2e8e2\" data-offset-key=\"5gc0u-0-0\">\n<table style=\"width: 100%;border-collapse: collapse;background-color: #faeae9;border-color: #000000;height: 416px\" border=\"1\">\n<tbody>\n<tr style=\"height: 48px\">\n<td style=\"width: 22.8699%;height: 48px\"><strong>Runde 1<\/strong><\/td>\n<td style=\"width: 77.1301%;height: 48px\"><span data-offset-key=\"5gc0u-0-0\">3 Lfm (= 1. Stb) und 11 Stb in MR h\u00e4keln (= 12 Stb), <\/span><span data-offset-key=\"5gc0u-0-0\">mit einer Km in das 1. echte Stb schlie\u00dfen.<\/span><\/td>\n<\/tr>\n<tr style=\"height: 184px\">\n<td style=\"width: 22.8699%;height: 184px\"><strong>Runde 2<\/strong><\/td>\n<td style=\"width: 77.1301%;height: 184px\"><span data-offset-key=\"64njh-0-0\">3 Lfm (= 1. Stb), 1 Stb in dieselbe Stelle wie die Km der Vor-Rd, <\/span><\/p>\n<p><span data-offset-key=\"64njh-0-0\">je <strong>2 Stb in jede weitere M<\/strong> der Rd, 2 Stb in die 3. Lfm vom Beginn der 1. Rd (= 24 Stb), <\/span><\/p>\n<p><span data-offset-key=\"64njh-0-0\">Km in das 1. echte Stb.<\/span><\/td>\n<\/tr>\n<tr style=\"height: 184px\">\n<td style=\"width: 22.8699%;height: 184px\"><strong>Runde 3<br \/>\n<\/strong><\/td>\n<td style=\"width: 77.1301%;height: 184px\"><span data-offset-key=\"b68fr-0-0\">3 Lfm (= 1. Stb), 1 Stb in dieselbe Stelle wie die Km der Vor-Rd, <\/span><\/p>\n<p><span data-offset-key=\"b68fr-0-0\"><strong>*1 Stb, 2 Stb in die folgende M<\/strong>; ab * bis 1 M vor Rd-Ende wdh, <\/span><\/p>\n<p><span data-offset-key=\"b68fr-0-0\">1 Stb in die 3. Lfm vom Beginn der 2. Rd.<\/span><\/p>\n<p>Faden abschneiden und die Runde unsichtbar verbinden &#8211; alternativ eine Km h\u00e4keln. F\u00e4den vern\u00e4hen.<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 22.8699%\"><strong>Runde 4<\/strong><\/td>\n<td style=\"width: 77.1301%\"><span data-offset-key=\"b68fr-0-0\">Neue Farbe an einer beliebigen Stelle ansetzen. <\/span><\/p>\n<p><span data-offset-key=\"b68fr-0-0\">3 Lfm (= 1. Stb), 1 Stb in dieselbe Stelle, * 2 Stb, 1 HStb, 2 fM, 1 HStb, 2 Stb **; (2 Stb, 2 Lfm, 2 Stb) in die folgende M *; von * bis * noch 2 Mal wdh, von * bis ** noch 1 Mal wdh, 2 Stb in dieselbe Stelle, wie das 1. Stb der Rd, 1 Lfm, 1 fM in die 3. Lfm vom Rd.-Start.<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 22.8699%\"><strong>Runde 5<\/strong><\/td>\n<td style=\"width: 77.1301%\"><span data-offset-key=\"b68fr-0-0\">3 Lfm (= 1. Stb), 1 Stb um die fM, * je 1 Stb in jedes St\u00e4bchen bis zur n\u00e4chsten Ecke **, (2 Stb, 2 Lfm, 2 Stb) in die 2-Lfm-Ecke *; von * bis * noch 2 Mal wdh, von * bis ** noch 1 Mal wdh, 2 Stb um die Lfm der letzten Ecke, 1 Lfm, Faden abschneiden und die Runde unsichtbar verbinden &#8211; alternativ Km in das 1. Stb.<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div data-block=\"true\" data-editor=\"2e8e2\" data-offset-key=\"5gc0u-0-0\"><\/div>\n<div data-block=\"true\" data-editor=\"2e8e2\" data-offset-key=\"5gc0u-0-0\"><\/div>\n<p><span data-offset-key=\"b68fr-0-0\">F\u00e4den vern\u00e4hen. <\/span><\/p>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                                                                                                            <\/div>\n                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                                                                                    <\/div>\n                                            <\/div>\n                                                                                                                                                        <\/div>\n                               \n                                 \n                            <div class=\"gallery-wrapper d-block d-lg-none\">\n                                                                    <div class=\"text-wrapper mb-5\">\n                                                                                                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                    <div class=\"text\">\n                                                        <div data-block=\"true\" data-editor=\"2e8e2\" data-offset-key=\"5gc0u-0-0\">\n<table style=\"width: 100%;border-collapse: collapse;background-color: #faeae9;border-color: #000000;height: 416px\" border=\"1\">\n<tbody>\n<tr style=\"height: 48px\">\n<td style=\"width: 22.8699%;height: 48px\"><strong>Runde 1<\/strong><\/td>\n<td style=\"width: 77.1301%;height: 48px\"><span data-offset-key=\"5gc0u-0-0\">3 Lfm (= 1. Stb) und 11 Stb in MR h\u00e4keln (= 12 Stb), <\/span><span data-offset-key=\"5gc0u-0-0\">mit einer Km in das 1. echte Stb schlie\u00dfen.<\/span><\/td>\n<\/tr>\n<tr style=\"height: 184px\">\n<td style=\"width: 22.8699%;height: 184px\"><strong>Runde 2<\/strong><\/td>\n<td style=\"width: 77.1301%;height: 184px\"><span data-offset-key=\"64njh-0-0\">3 Lfm (= 1. Stb), 1 Stb in dieselbe Stelle wie die Km der Vor-Rd, <\/span><\/p>\n<p><span data-offset-key=\"64njh-0-0\">je <strong>2 Stb in jede weitere M<\/strong> der Rd, 2 Stb in die 3. Lfm vom Beginn der 1. Rd (= 24 Stb), <\/span><\/p>\n<p><span data-offset-key=\"64njh-0-0\">Km in das 1. echte Stb.<\/span><\/td>\n<\/tr>\n<tr style=\"height: 184px\">\n<td style=\"width: 22.8699%;height: 184px\"><strong>Runde 3<br \/>\n<\/strong><\/td>\n<td style=\"width: 77.1301%;height: 184px\"><span data-offset-key=\"b68fr-0-0\">3 Lfm (= 1. Stb), 1 Stb in dieselbe Stelle wie die Km der Vor-Rd, <\/span><\/p>\n<p><span data-offset-key=\"b68fr-0-0\"><strong>*1 Stb, 2 Stb in die folgende M<\/strong>; ab * bis 1 M vor Rd-Ende wdh, <\/span><\/p>\n<p><span data-offset-key=\"b68fr-0-0\">1 Stb in die 3. Lfm vom Beginn der 2. Rd.<\/span><\/p>\n<p>Faden abschneiden und die Runde unsichtbar verbinden &#8211; alternativ eine Km h\u00e4keln. F\u00e4den vern\u00e4hen.<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 22.8699%\"><strong>Runde 4<\/strong><\/td>\n<td style=\"width: 77.1301%\"><span data-offset-key=\"b68fr-0-0\">Neue Farbe an einer beliebigen Stelle ansetzen. <\/span><\/p>\n<p><span data-offset-key=\"b68fr-0-0\">3 Lfm (= 1. Stb), 1 Stb in dieselbe Stelle, * 2 Stb, 1 HStb, 2 fM, 1 HStb, 2 Stb **; (2 Stb, 2 Lfm, 2 Stb) in die folgende M *; von * bis * noch 2 Mal wdh, von * bis ** noch 1 Mal wdh, 2 Stb in dieselbe Stelle, wie das 1. Stb der Rd, 1 Lfm, 1 fM in die 3. Lfm vom Rd.-Start.<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 22.8699%\"><strong>Runde 5<\/strong><\/td>\n<td style=\"width: 77.1301%\"><span data-offset-key=\"b68fr-0-0\">3 Lfm (= 1. Stb), 1 Stb um die fM, * je 1 Stb in jedes St\u00e4bchen bis zur n\u00e4chsten Ecke **, (2 Stb, 2 Lfm, 2 Stb) in die 2-Lfm-Ecke *; von * bis * noch 2 Mal wdh, von * bis ** noch 1 Mal wdh, 2 Stb um die Lfm der letzten Ecke, 1 Lfm, Faden abschneiden und die Runde unsichtbar verbinden &#8211; alternativ Km in das 1. Stb.<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div data-block=\"true\" data-editor=\"2e8e2\" data-offset-key=\"5gc0u-0-0\"><\/div>\n<div data-block=\"true\" data-editor=\"2e8e2\" data-offset-key=\"5gc0u-0-0\"><\/div>\n<p><span data-offset-key=\"b68fr-0-0\">F\u00e4den vern\u00e4hen. <\/span><\/p>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                                                            <\/div>\n                                                                            <div class=\"row mb-4\">\n                                            <div class=\"col-12\">\n                                                                                            <\/div>\n                                        <\/div>\n                                                                                                                                                                                                            <\/div>\n                                                                                    <\/div>\n    <\/section>\n<\/div>\n\n            \n        <div class=\"modal fade modal-move-to-body gallery-modal noble\" id=\"modal-text-gallery-video-block_d57684d6f5b471f3b32f511bf8eb344a\" tabindex=\"-1\"\n             aria-labelledby=\"modal-text-gallery-video-block_d57684d6f5b471f3b32f511bf8eb344a\" aria-hidden=\"true\">\n            <div class=\"modal-dialog modal-xl modal-dialog-centered\">\n                <div class=\"modal-content\">\n                    <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n                        <i class=\"fas fa-times\"><\/i>\n                    <\/button>\n                    <div class=\"modal-body\">\n                        <div class=\"container-fluid\">\n                                                            <div class=\"row\">\n                                    <div class=\"col-12\">\n                                        <div class=\"row carousel-item-image-wrapper\">\n                                            <div class=\"col-12\">\n                                                <div class=\"carousel-item-image\">\n                                                    <div class=\"color-area-secondary\"><\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                            <\/div>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    \n\n\n\n<div id=\"text-gallery-video-block_208b1a4ad0849698152fcf7a43c79d2c\" class=\"text-gallery-video alignment-left inherit\" >\n    <section>\n        <div class=\"container position-relative\">\n            \n\n                                                                                <div class=\"gallery-wrapper\">\n                                    <div class=\"text-wrapper mb-5\">\n                                                                                                                                                                    <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                    <div class=\"heading-tag\">\n                                                        \n                                                        <h4> Videoanleitung Granny Square Kreis h\u00e4keln <\/h4>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                                                                                                    <\/div>\n                                    <div class=\"row\">\n                                        <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                            <div class=\"video-wrapper\">\n                                                <iframe loading=\"lazy\" title=\"So geht&#039;s! Granny Square Kreis h\u00e4keln!\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/TVCdPfmmWIc?feature=oembed&#038;rel=0&#038;autoplay=0&#038;loop=0&#038;mute=0&#038;controls=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen frameborder=\"0\"><\/iframe>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                                                    <\/div>\n                                                                                    <\/div>\n    <\/section>\n<\/div>\n\n\n\n<div id=\"headline-block_8ecb7d2ec6ac5a710956e20c05cf2c07\" class=\"headline\" >\n    <section>\n        <div class=\"container\">\n                        <div class=\"row\">\n                <div class=\"col-12 col-md-6\">\n                                                                <h2 class=\"medium script\">\n                            Viel Spa\u00df beim Nutzen oder Verschenken!                        <\/h2>\n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"selection-teaser-block_0e4d7b23f2f8d372236676bb6770bc74\" class=\"selection-teaser \" >\n    <section>\n        <div class=\"container\">\n                            <div class=\"row\">\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper service\">\n                            <div class=\"image-wrapper \">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/05\/00-addi-Haekelnadeln-crochet-hooksmade_in_germany-400x320.jpg\" class=\"attachment-400x320 size-400x320\" alt=\"addi-Garnhaekelnadeln-Wollhaekelndeln\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        H\u00e4keln                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        addi Sortiment                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        Das perfekte H\u00e4kelnadel Sortiment f\u00fcr Ihr Handarbeitsprojekt!                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Erleben Sie die Leichtigkeit des H\u00e4kelns mit hochwertigen H\u00e4kelnadeln, die speziell f\u00fcr Ihre Bed\u00fcrfnisse entwickelt wurden.&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:14785,&quot;3&quot;:{&quot;1&quot;:0,&quot;3&quot;:1},&quot;9&quot;:0,&quot;10&quot;:0,&quot;11&quot;:4,&quot;14&quot;:{&quot;1&quot;:3,&quot;3&quot;:1},&quot;15&quot;:&quot;Poppins&quot;,&quot;16&quot;:11}\">Erleben Sie die Leichtigkeit des H\u00e4keln mit hochwertigen H\u00e4kelnadeln, die speziell f\u00fcr Ihre Bed\u00fcrfnisse entwickelt wurden.<\/span><\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href='https:\/\/addi.de\/c\/haekeln\/haekelnadeln\/' target='_blank' class='buttonlink prio-2'>addi H\u00e4kelnadeln<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper noble\">\n                            <div class=\"image-wrapper \">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/monochrom_fashion-400x320.png\" class=\"attachment-400x320 size-400x320\" alt=\"Strick - Farben kombinieren\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Edles                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        Story                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        Monochrom und Farbverwandtschaft                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>Durch eine monochrome Farbkombination verleihen Sie mehr Tiefe, durch Farbverwandtschaft erreichen Sie ruhige und harmonische Farbkombinationen.<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href='https:\/\/addi.de\/en\/story\/monochrom-und-farbverwandtschaft\/' target='_self' class='buttonlink prio-2'>Story lesen<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper inspiration\">\n                            <div class=\"image-wrapper \">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/03\/header_haeufigste_haekel-fehler-400x320.png\" class=\"attachment-400x320 size-400x320\" alt=\"\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Inspiration                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        Story                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        H\u00e4ufigste Fehler beim H\u00e4keln und wie man sie vermeidet.                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>Aller Anfang ist schwer. Aber keine Angst, mit diesen einfachen Tipps kommt der Spa\u00df am fig\u00fcrlichen H\u00e4keln schneller, als Sie denken.<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href='https:\/\/addi.de\/en\/story\/haekeln-fehler-vermeiden\/' target='_self' class='buttonlink prio-2'>Story lesen<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/section>\n<\/div>\n","protected":false},"parent":0,"menu_order":0,"template":"","kategorie_sy":[30],"kategorie_blog":[571,36,563,548,566,573,553],"class_list":["post-24015","story","type-story","status-publish","hentry","kategorie_sy-noble","kategorie_blog-accessoires","kategorie_blog-anleitung","kategorie_blog-fortgeschrittene-anfaenger","kategorie_blog-fruehling","kategorie_blog-haekeln","kategorie_blog-home-deko","kategorie_blog-sommer"],"acf":[],"_links":{"self":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/story\/24015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/types\/story"}],"wp:attachment":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/media?parent=24015"}],"wp:term":[{"taxonomy":"kategorie_sy","embeddable":true,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/kategorie_sy?post=24015"},{"taxonomy":"kategorie_blog","embeddable":true,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/kategorie_blog?post=24015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}