{"id":53606,"date":"2024-10-02T10:00:00","date_gmt":"2024-10-02T08:00:00","guid":{"rendered":"https:\/\/addi.de\/?post_type=story&#038;p=53606"},"modified":"2024-07-22T15:42:52","modified_gmt":"2024-07-22T13:42:52","slug":"addiexpress-fred-fledermaus-stricken","status":"publish","type":"story","link":"https:\/\/addi.de\/en\/story\/addiexpress-fred-fledermaus-stricken\/","title":{"rendered":"addiExpress Fred bat"},"content":{"rendered":"<div id=\"header-text-block_95c24903cf950d257fb613c98131326d\" class=\"header-text\" >\n    <section>\n        <div class=\"container\">\n            <div class=\"row position-relative\">\n                <div class=\"col-12 col-lg-3 offset-lg-1 order-2 order-lg-1\">\n                    <div class=\"text-wrapper\">\n                        <div class=\"color-area-secondary\"><\/div>\n                                                    <div class=\"topline hl-color\">\n                                Kurbeln                             <\/div>\n                                                                                                    <h1>addiExpress Fred Fledermaus stricken<\/h1>\n                                                <div class=\"share-links\">\n                            <span>Teilen:<\/span>\n                            <a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Faddi.de%2Fen%2Fstory%2Faddiexpress-fred-fledermaus-stricken%2F\" class=\"d-inline-block px-2\" onclick=\"window.open(this.href, 'mywin', 'left=20,top=20,width=500,height=500,toolbar=1,resizable=0'); return false;\"><i class=\"fab fa-facebook-f hl-color\"><\/i><\/a>\n                            <a href=\"https:\/\/twitter.com\/intent\/tweet?text=https%3A%2F%2Faddi.de%2Fen%2Fstory%2Faddiexpress-fred-fledermaus-stricken%2F\" class=\"d-inline-block px-2\" onclick=\"window.open(this.href, 'mywin', 'left=20,top=20,width=500,height=500,toolbar=1,resizable=0'); return false;\"><i class=\"fa-brands fa-x-twitter hl-color\"><\/i><\/a>\n                        <\/div>\n                        <div class=\"text\">\n                            <p>Und so entschloss sich Fred Fledermaus, auf immer seine n\u00e4chtliche Schattenwelt zu verlassen und von nun an nur noch mit seinem neuen Kumpel Mike Monster abzuh\u00e4ngen.<\/p>\n<p>Die Fledermus als Halloween-Dekoration einfach mit der Strickmaschine kurbeln.<\/p>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                <div class=\"col-12 col-lg-7 offset-lg-1 mb-3 mb-lg-0 order-1 order-lg-2\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"970\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/small_ANL_Fred_Fledermaus_36_04e943108c-1280x970.png\" class=\"attachment-1280x970 size-1280x970\" alt=\"Fledermaus\" \/>                                        <div class=\"row toc-wrapper\">\n                        <div class=\"col-12 col-lg-6 offset-lg-5\">\n                            <div class=\"toc-title\">\n                                Inhaltsverzeichnis                            <\/div>\n                            <div class=\"toc-content\">\n\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<\/div>\n\n\n\n<div id=\"infobox-block_022b0a141d5633b55ff4a1f151147fec\" class=\"infobox\" >\n    <section>\n        <div class=\"container-fluid container-md\">\n            <div class=\"row\">\n                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                    <div class=\"infobox-wrapper\">\n                        \n                        <div class=\"row\">\n                            <div class=\"col-7 col-sm-5 col-md-2 col-lg-2 col-xl-2\">\n                                <div class=\"difficulty-wrapper color-area-primary\" style=\"position:relative; z-index:1;\">\n                                                                                <i class=\"fa-solid fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-regular fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-regular fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-regular fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-regular fa-heart d-inline-block d-md-block\"><\/i>\n                                                                            <\/div>\n                            <\/div>\n                            <div class=\"col-12 col-md-6 col-lg-6 col-xl-7\">\n                            <div class=\"color-area-secondary\" style=\"right: 5%;\"><\/div>\n                                <div class=\"text-wrapper\">\n                                                                            <div class=\"topline hl-color\" style=\"position:relative; z-index:1;\">\n                                             Was du brauchst:                                        <\/div>\n                                                                                                                <div class=\"text\">\n                                            <div data-block=\"true\" data-editor=\"fhih0\" data-offset-key=\"e16e6-0-0\">\n<ul>\n<li><span data-offset-key=\"e16e6-0-0\">\u00a0addiExpress Strickmaschine (alternativ Nadelspiel)<\/span><\/li>\n<li>1 Kn\u00e4uele schwarze Wolle deiner Wahl (Nadelst\u00e4rken 4 \u2013 8 mm)<\/li>\n<li>1 Plexiglas-Ei, teilbar, 16 cm<\/li>\n<li>250 g Quarzsand,\u2029abgef\u00fcllt in einem Plastikbeutel<\/li>\n<li>Schwarze Federn<\/li>\n<li>8 Streifen schwarzer Karton (220 g\/qm),\u2029 je 1,5 cm breit und 30 cm lang<\/li>\n<li>1 DIN-A4-Blatt schwarzer Karton\u2029(220 g\/qm)<\/li>\n<li>1 DIN-A4-Blatt wei\u00dfer Karton\u2029(220 g\/qm)<\/li>\n<li>1 Paar Augen<\/li>\n<li>1 Pompon<\/li>\n<li>1 Zugfeder<\/li>\n<\/ul>\n<\/div>\n<div data-block=\"true\" data-editor=\"fhih0\" data-offset-key=\"542g1-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"542g1-0-0\"><\/div>\n<\/div>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                            <div class=\"col-7 col-offset-3 col-md-3 col-lg-4 col-xl-3\">\n                                <a href=\"https:\/\/addi.de\/en\/produkt\/addiexpress-professional-strickmaschine\/\">\n                                <div class=\"wrapper-nk\">\n                                    <div class=\"color-area-primary\"><\/div>\n                                        <div class=\"produkt-wraper-nk\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"2000\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2.png 2000w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-1536x1536.png 1536w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-1320x1320.png 1320w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-100x100.png 100w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/>                                        <\/div>\n                                    <\/div>\n                                    <div class=\"headline-rodukt-nk hl-color\">\n                                        <p><\/p>\n                                        <p>addiExpress Professional Strickmaschine<\/p>\n                                    <\/div>\n                                <\/div>\n                                <\/a>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<\/div>\n\n\n<div id=\"teaser-block_3a9cc2a78d30d345cbbf7cab848712a7\" class=\"teaser alignment-left\" >\n    <section>\n        <div class=\"container\">\n                                                <div id=\"teaserCarousel-block_3a9cc2a78d30d345cbbf7cab848712a7\" class=\"carousel slide keepsize-responsive\">\n                        <div class=\"carousel-inner\" data-countslides=\"2\">\n                                                            <div class=\"carousel-item active\">\n                                                                                                                <div class=\"row position-relative inherit images-count-2\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6 order-2 order-lg-1\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Produktanleitung                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                        <h2>addiExpress Grundanleitung <h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <div data-block=\"true\" data-editor=\"85qk5\" data-offset-key=\"dfi36-0-0\"><strong>Mit der addiExpress wird Stricken kinderleicht und bequem: Stricken Sie schnell in Runden oder gerade \u2013 einfach an der Kurbel drehen!<\/strong> Selbst Anf\u00e4nger werden binnen Minuten stolz auf ihre Werke sein. In der folgenden Anleitung zeigen wir alle Grundlagen und Tipps zum kurbeln mit der Strickmaschine addiExpress Professional und Kingsize.<\/div>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/grundanleitung-addiexpress\/' target='_self' class='buttonlink prio-1'>Anleitung anschauen<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                            <div class=\"col-12 col-lg-6 order-1 order-lg-2\">\n                                                                                                    <div class=\"images-wrapper product\">\n                                                                                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                    <div class=\"col-12 col-lg-10 offset-lg-2\">\n                                                                        <picture>\n                                                                            <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/890-2990-2-addiExpress-Srickmaschinen-520x300.jpg\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/07\/890-2990-2-addiExpress-Srickmaschinen-520x300.jpg\" alt=\"\">\n                                                                        <\/picture>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                <div class=\"row product\">\n                                                                    <div class=\"col-12 col-lg-6\">\n                                                                        <div class=\"product-wrapper\">\n                                                                            <div class=\"square\"><\/div>\n                                                                            <div class=\"color-area-primary\"><\/div>\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-600x600.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-1536x1536.png 1536w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-1320x1320.png 1320w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2-100x100.png 100w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/990-2_addiExpress_Professional_Strickmaschine_knitting_machine_22_Nadeln_neeldes_O10-15cm_frei1_rgb-2.png 2000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                                        <\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                            <div class=\"carousel-item \">\n                                                                                                                <div class=\"row position-relative inspiration images-count-3\">\n                                            <div class=\"color-area-secondary\"><\/div>\n                                            <div class=\"col-12 col-lg-6 order-2 order-lg-1\">\n                                                <div class=\"text-wrapper\">\n                                                                                                            <div class=\"topline\">\n                                                            Tipps und Tricks                                                        <\/div>\n                                                                                                                                                                <div class=\"heading-tag\">\n                                                        <h2>Welche Wolle f\u00fcr die addiExpress Strickmaschinen geeignet ist<h2>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"text\">\n                                                            <p>Nicht jedes Garn eignet sich gut zur Verarbeitung mit unseren addiExpress Strickmaschinen. Garnst\u00e4rke, Material und Faserigkeit sollten passen, damit das Ganr gleichm\u00e4\u00dfige und sch\u00f6ne Ergebnisse liefert.<\/p>\n<p>Welche Garne sich besonder eignen und worauf Sie achten sollten, erfahren Sie in diesem Artikel.<\/p>\n                                                        <\/div>\n                                                                                                                                                                <div class=\"row link-wrapper\">\n                                                                                                                            <div class=\"col-12 col-lg-6\">\n                                                                    <a href='https:\/\/addi.de\/en\/story\/welche-wolle-fuer-die-addiexpress-strickmaschinen\/' target='_self' class='buttonlink prio-1'>Tipp anschauen<\/a>                                                                <\/div>\n                                                                                                                                                                                <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                            <div class=\"col-12 col-lg-6 order-1 order-lg-2\">\n                                                                                                    <div class=\"images-wrapper \">\n                                                                                                                    <div class=\"row image-1-wrapper\">\n                                                                <div class=\"col-12 col-lg-4 offset-lg-2\">\n                                                                    <picture>\n                                                                        <source media=\"(min-width: 991px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/12\/welche-Wolle-fuer-addiExpress-Strickmaschine-200x300.jpg\">\n                                                                        <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/12\/welche-Wolle-fuer-addiExpress-Strickmaschine-520x300.jpg\" alt=\"\">\n                                                                    <\/picture>\n                                                                <\/div>\n                                                            <\/div>\n                                                            <div class=\"row image-2-wrapper\">\n                                                                <div class=\"col-12 col-lg-8 offset-lg-4\">\n                                                                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/10\/addiExpress-Professional-Strickstu\u0308ck-gerade-Anleitung-Zugluftstopper-400x400.png\" class=\"attachment-400x400 size-400x400\" alt=\"addiExpress stricken -kurbeln\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/10\/addiExpress-Professional-Strickstu\u0308ck-gerade-Anleitung-Zugluftstopper-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/10\/addiExpress-Professional-Strickstu\u0308ck-gerade-Anleitung-Zugluftstopper-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/10\/addiExpress-Professional-Strickstu\u0308ck-gerade-Anleitung-Zugluftstopper-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/10\/addiExpress-Professional-Strickstu\u0308ck-gerade-Anleitung-Zugluftstopper-100x100.png 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                <\/div>\n                                                            <\/div>\n                                                            <div class=\"row image-3-wrapper\">\n                                                                <div class=\"col-12 col-lg-6\">\n                                                                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/12\/Schoeller-Lania-01-400x400.jpg\" class=\"attachment-400x400 size-400x400\" alt=\"Welche Wolle f\u00fcr die addiExpress Strickmaschinen\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2023\/12\/Schoeller-Lania-01-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2023\/12\/Schoeller-Lania-01-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2023\/12\/Schoeller-Lania-01-768x768.jpg 768w, https:\/\/addi.de\/wp-content\/uploads\/2023\/12\/Schoeller-Lania-01-12x12.jpg 12w, https:\/\/addi.de\/wp-content\/uploads\/2023\/12\/Schoeller-Lania-01-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2023\/12\/Schoeller-Lania-01-600x600.jpg 600w, https:\/\/addi.de\/wp-content\/uploads\/2023\/12\/Schoeller-Lania-01-100x100.jpg 100w, https:\/\/addi.de\/wp-content\/uploads\/2023\/12\/Schoeller-Lania-01.jpg 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                <\/div>\n                                                            <\/div>\n                                                                                                            <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                    <\/div>\n                        <div class=\"row\">\n                            <div class=\"col-12 col-lg-4 offset-lg-4\">\n                                <ol class=\"carousel-indicators\">\n                                                                            <li data-target=\"#teaserCarousel-block_3a9cc2a78d30d345cbbf7cab848712a7\" data-slide-to=\"0\"\n                                            class=\"active\"><\/li>\n                                                                            <li data-target=\"#teaserCarousel-block_3a9cc2a78d30d345cbbf7cab848712a7\" data-slide-to=\"1\"\n                                            class=\"\"><\/li>\n                                                                    <\/ol>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <\/div>\n    <\/section>\n<\/div>\n\n\n\n            \n<div id=\"text-gallery-video-block_33c0d63945d23cc7523f726ec31ece62\" class=\"text-gallery-video toc alignment-left inspiration\"  data-toctitle=\"Strickschlauch und\u2029 Grundk\u00f6rper\">\n    <section>\n        <div class=\"container position-relative\">\n            \n\n                                                                                <div class=\"gallery-wrapper  d-lg-block\">\n                                                                                                                        <div class=\"row align-items-end\">\n                                                <div class=\"col-12 col-lg-6 offset-lg-1\">\n                                                    <div class=\"text-wrapper mb-3\">\n                                                                                                                                                                            <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    <div class=\"topline\">Schritt 1 &#8211; Fred Fledermaus stricken<\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                            <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    \n                                                                    <div class=\"heading-tag\">\n                                                                        <h2> Strickschlauch und\u2029 Grundk\u00f6rper <\/h2>\n                                                                    <\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                            <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    <div class=\"text\">\n                                                                        <p><strong>Mit der addiExpress Professional kurbeln:<\/strong><\/p>\n<ul>\n<li>Mit der addiExpress Professional Strickmaschine einen Schlauch mit etwas 45 Reihen kurbeln.<\/li>\n<li>F\u00fcr ein dichtes Ergebnis d\u00fcnnere Garne doppelf\u00e4dig verstricken (Nadelst\u00e4rke 4-6), dickere Garne einfach verkurbeln (Nadelst\u00e4rke 7-8)<\/li>\n<\/ul>\n<p><strong>Von Hand stricken:<\/strong><\/p>\n<ul>\n<li>Mit dem Nadelspiel oder den addiCraSyTrio einen Strickschlauch aus der wei\u00dfen Wolle und dem Goldfaden zweif\u00e4dig mit 32 Maschen anschlagen.<\/li>\n<li>Den Schlauch \u00fcber ca. 30 Runden glatt rechts stricken, bis er etwas l\u00e4nger als 20 cm ist.<\/li>\n<\/ul>\n                                                                    <\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                                                                            <\/div>\n                                                    <div class=\"row\">\n                                                        <div class=\"col-12 col-lg-8 offset-lg-4\">\n                                                                                                                    <\/div>\n                                                    <\/div>\n                                                                                                            <div class=\"scriptheadlinespacer\"><\/div>\n                                                                                                                    <div class=\"buttonspacer\"><\/div>\n                                                                                                                                                            <\/div>\n                                                <div class=\"col-12 col-lg-4\">\n                                                    <div class=\"row\">\n                                                        <div class=\"col-12 col-lg-9\">\n                                                            <div class=\"product-wrapper\">\n                                                                <div class=\"square\"><\/div>\n                                                                                                                                <a href=\"https:\/\/addi.de\/en\/produkt\/the-woolly-family\/\">\n                                                                    <div class=\"color-area-primary\"><\/div>\n                                                                    <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-600x600.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-1536x1536.png 1536w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-1320x1320.png 1320w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-100x100.png 100w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb.png 1800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                                <\/a>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_33c0d63945d23cc7523f726ec31ece62\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/12\/FamilieWolli-addiExpress-Anleitung-basteln-mit-Kindern-400x320.jpg\" class=\"attachment-400x320 size-400x320\" alt=\"Strickmaschine-fuer-Zuhause-addiExpress\" \/>                                                        <\/div>\n                                                                                                                                                        <\/div>\n                                            <\/div>\n                                                                                                            <\/div>\n                               \n                                 \n                            <div class=\"gallery-wrapper d-block d-lg-none\">\n                                                                    <div class=\"text-wrapper mb-5\">\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                                    <div class=\"topline\">Schritt 1 &#8211; Fred Fledermaus stricken<\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                              \n                                                    <div class=\"heading-tag\">\n                                                        <h2>Strickschlauch und\u2029 Grundk\u00f6rper<\/h2>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                    <div class=\"text\">\n                                                        <p><strong>Mit der addiExpress Professional kurbeln:<\/strong><\/p>\n<ul>\n<li>Mit der addiExpress Professional Strickmaschine einen Schlauch mit etwas 45 Reihen kurbeln.<\/li>\n<li>F\u00fcr ein dichtes Ergebnis d\u00fcnnere Garne doppelf\u00e4dig verstricken (Nadelst\u00e4rke 4-6), dickere Garne einfach verkurbeln (Nadelst\u00e4rke 7-8)<\/li>\n<\/ul>\n<p><strong>Von Hand stricken:<\/strong><\/p>\n<ul>\n<li>Mit dem Nadelspiel oder den addiCraSyTrio einen Strickschlauch aus der wei\u00dfen Wolle und dem Goldfaden zweif\u00e4dig mit 32 Maschen anschlagen.<\/li>\n<li>Den Schlauch \u00fcber ca. 30 Runden glatt rechts stricken, bis er etwas l\u00e4nger als 20 cm ist.<\/li>\n<\/ul>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                                                            <\/div>\n                                                                            <div class=\"row mb-4\">\n                                            <div class=\"col-9\">\n                                                                                                    <div id=\"galleryCarousel-block_33c0d63945d23cc7523f726ec31ece62\" class=\"carousel slide\" data-ride=\"carousel\" data-interval=\"2500\" data-pause=\"false\" data-keyboard=\"false\">\n                                                        <div class=\"carousel-inner\" data-countslides=\"2\">\n                                                                                                                            <div class=\"carousel-item active\">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_33c0d63945d23cc7523f726ec31ece62\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/12\/FamilieWolli-addiExpress-Anleitung-basteln-mit-Kindern-1280x970.jpg\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/12\/FamilieWolli-addiExpress-Anleitung-basteln-mit-Kindern-400x320.jpg\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                            <div class=\"carousel-item \">\n                                                                                                                                    <\/div>\n                                                                                                                    <\/div>\n                                                    <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                                                                <div class=\"row mb-4\">\n                                            <div class=\"col-9 offset-3\">\n                                                <div class=\"product-wrapper\">\n                                                    <div class=\"square\"><\/div>\n                                                                                                        <a href=\"https:\/\/addi.de\/en\/produkt\/the-woolly-family\/\">\n                                                        <div class=\"color-area-primary\"><\/div>\n                                                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-600x600.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-1536x1536.png 1536w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-1320x1320.png 1320w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb-100x100.png 100w, https:\/\/addi.de\/wp-content\/uploads\/2022\/04\/976-0_addiExpress_FamilieWolli_Cover_EN_rgb.png 1800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                    <\/a>\n                                                <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                                                                                                                        <\/div>\n                                                                                    <\/div>\n    <\/section>\n<\/div>\n\n            \n        <div class=\"modal fade modal-move-to-body gallery-modal inspiration\" id=\"modal-text-gallery-video-block_33c0d63945d23cc7523f726ec31ece62\" tabindex=\"-1\"\n             aria-labelledby=\"modal-text-gallery-video-block_33c0d63945d23cc7523f726ec31ece62\" aria-hidden=\"true\">\n            <div class=\"modal-dialog modal-xl modal-dialog-centered\">\n                <div class=\"modal-content\">\n                    <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n                        <i class=\"fas fa-times\"><\/i>\n                    <\/button>\n                    <div class=\"modal-body\">\n                        <div class=\"container-fluid\">\n                                                            <div id=\"modal-carousel-text-gallery-video-block_33c0d63945d23cc7523f726ec31ece62\" class=\"carousel slide keepsize\">\n                                    <div class=\"carousel-inner\" data-countslides=\"2\">\n                                                                                    <div class=\"carousel-item active\">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"2000\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/12\/FamilieWolli-addiExpress-Anleitung-basteln-mit-Kindern.jpg\" class=\"attachment-full size-full wpsmartcrop-image wpsmartcrop-image\" alt=\"Strickmaschine-fuer-Zuhause-addiExpress\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/12\/FamilieWolli-addiExpress-Anleitung-basteln-mit-Kindern.jpg 1333w, https:\/\/addi.de\/wp-content\/uploads\/2022\/12\/FamilieWolli-addiExpress-Anleitung-basteln-mit-Kindern-200x300.jpg 200w, https:\/\/addi.de\/wp-content\/uploads\/2022\/12\/FamilieWolli-addiExpress-Anleitung-basteln-mit-Kindern-768x1152.jpg 768w, https:\/\/addi.de\/wp-content\/uploads\/2022\/12\/FamilieWolli-addiExpress-Anleitung-basteln-mit-Kindern-1024x1536.jpg 1024w, https:\/\/addi.de\/wp-content\/uploads\/2022\/12\/FamilieWolli-addiExpress-Anleitung-basteln-mit-Kindern-8x12.jpg 8w, https:\/\/addi.de\/wp-content\/uploads\/2022\/12\/FamilieWolli-addiExpress-Anleitung-basteln-mit-Kindern-1320x1980.jpg 1320w, https:\/\/addi.de\/wp-content\/uploads\/2022\/12\/FamilieWolli-addiExpress-Anleitung-basteln-mit-Kindern-600x900.jpg 600w\" sizes=\"auto, (max-width: 1333px) 100vw, 1333px\" data-smartcrop-focus=\"[47,36]\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                                    <div class=\"carousel-item \">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                                                                                    <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                            <\/div>\n                                    <a class=\"carousel-control-prev\" href=\"#modal-carousel-text-gallery-video-block_33c0d63945d23cc7523f726ec31ece62\" role=\"button\" data-slide=\"prev\">\n                                        <i class=\"fas fa-angle-left\"><\/i>\n                                    <\/a>\n                                    <a class=\"carousel-control-next\" href=\"#modal-carousel-text-gallery-video-block_33c0d63945d23cc7523f726ec31ece62\" role=\"button\" data-slide=\"next\">\n                                        <i class=\"fas fa-angle-right\"><\/i>\n                                    <\/a>\n                                    <div class=\"carousel-indicators-wrapper\">\n                                        <ol class=\"carousel-indicators\">\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_33c0d63945d23cc7523f726ec31ece62\" data-slide-to=\"0\"\n                                                    class=\"active\"><\/li>\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_33c0d63945d23cc7523f726ec31ece62\" data-slide-to=\"1\"\n                                                    class=\"\"><\/li>\n                                                                                    <\/ol>\n                                    <\/div>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    \n\n\n            \n<div id=\"text-gallery-video-block_8d1160433f7bcea546c1bb94ffa408fd\" class=\"text-gallery-video toc alignment-right inspiration\"  data-toctitle=\"Fertigstellung\">\n    <section>\n        <div class=\"container position-relative\">\n            \n\n                                                                                <div class=\"gallery-wrapper d-lg-block\">\n                                                                                                                        <div class=\"text-wrapper mb-5\">\n                                                                                                                                                    <div class=\"row\">\n                                                        <div class=\"col-12 col-lg-9 offset-lg-3\">\n                                                            <div class=\"topline\">Schritt 2 &#8211; Fledermaus stricken<\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                                                                    <div class=\"row\">\n                                                        <div class=\"col-12 col-lg-8 offset-lg-3\">\n                                                            \n                                                            <div class=\"heading-tag\">\n                                                                <h2> Fertigstellung <\/h2>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                                                                    <div class=\"row\">\n                                                        <div class=\"col-12 col-lg-8 offset-lg-3\">\n                                                            <div class=\"text\">\n                                                                <div data-block=\"true\" data-editor=\"2gfv7\" data-offset-key=\"2eeq3-0-0\">\n<ul>\n<li class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2eeq3-0-0\"><span data-offset-key=\"2eeq3-0-0\">Den mit Sand gef\u00fcllten Beutel in das Plexiglas-\u2029Ei legen und anschlie\u00dfend das Ei mit Tesafilm\u2029 zukleben.\u2029<\/span>\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"ffghs-0-0\"><\/div>\n<\/li>\n<li class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2eeq3-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"ffghs-0-0\"><span data-offset-key=\"ffghs-0-0\">Strickschlauch gem\u00e4\u00df Anleitung herstellen,\u2029 \u00fcber das Ei ziehen und Enden zuziehen und zun\u00e4hen.\u2029 Die Zugfeder in die Aufh\u00e4ngung des Plexiglas-Eies einh\u00e4ngen.\u2029 <\/span><\/div>\n<\/li>\n<li class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2eeq3-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"ffghs-0-0\"><span data-offset-key=\"ffghs-0-0\">Fl\u00fcgel, F\u00fc\u00dfe und Ohren gem\u00e4\u00df <a href=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/06\/ANL_Fred-Fledermaus-addiExpress_36.pdf\">Vorlage<\/a> aus dem schwarzen Karton zuschneiden.\u2029 Den Mund aus dem wei\u00dfen Karton schneiden\u2029 und wie in der Abbildung anmalen.\u2029<\/span><\/div>\n<\/li>\n<li class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2eeq3-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"ffghs-0-0\"><span data-offset-key=\"ffghs-0-0\">Arme und Beine werden aus je 2 Papierstreifen gebastelt: am Ende im rechten Winkel aufeinanderkleben und abwechselnd in Rich\u2029tung der Klebefl\u00e4che an der Kante des jeweils\u2029 anderen Papierstreifens falten. Nun die F\u00fc\u00dfe \u2029und Fl\u00fcgel ankleben.\u2029 <\/span><\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div data-block=\"true\" data-editor=\"2gfv7\" data-offset-key=\"2hsk5-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2hsk5-0-0\"><span data-offset-key=\"2hsk5-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"2gfv7\" data-offset-key=\"c6hav-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"c6hav-0-0\"><span data-offset-key=\"c6hav-0-0\">Alle Teile, mit dem Gesicht beginnend, an das \u2029Ei ankleben.\u2029 Die Fl\u00fcgel mit den Federn schm\u00fccken. <\/span><\/div>\n<\/div>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                                                                                                            <\/div>\n                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                                                                                    <\/div>\n                                            <\/div>\n                                                                                                                                                        <\/div>\n                               \n                                 \n                            <div class=\"gallery-wrapper d-block d-lg-none\">\n                                                                    <div class=\"text-wrapper mb-5\">\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                                    <div class=\"topline\">Schritt 2 &#8211; Fledermaus stricken<\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                              \n                                                    <div class=\"heading-tag\">\n                                                        <h2>Fertigstellung<\/h2>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                    <div class=\"text\">\n                                                        <div data-block=\"true\" data-editor=\"2gfv7\" data-offset-key=\"2eeq3-0-0\">\n<ul>\n<li class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2eeq3-0-0\"><span data-offset-key=\"2eeq3-0-0\">Den mit Sand gef\u00fcllten Beutel in das Plexiglas-\u2029Ei legen und anschlie\u00dfend das Ei mit Tesafilm\u2029 zukleben.\u2029<\/span>\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"ffghs-0-0\"><\/div>\n<\/li>\n<li class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2eeq3-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"ffghs-0-0\"><span data-offset-key=\"ffghs-0-0\">Strickschlauch gem\u00e4\u00df Anleitung herstellen,\u2029 \u00fcber das Ei ziehen und Enden zuziehen und zun\u00e4hen.\u2029 Die Zugfeder in die Aufh\u00e4ngung des Plexiglas-Eies einh\u00e4ngen.\u2029 <\/span><\/div>\n<\/li>\n<li class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2eeq3-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"ffghs-0-0\"><span data-offset-key=\"ffghs-0-0\">Fl\u00fcgel, F\u00fc\u00dfe und Ohren gem\u00e4\u00df <a href=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/06\/ANL_Fred-Fledermaus-addiExpress_36.pdf\">Vorlage<\/a> aus dem schwarzen Karton zuschneiden.\u2029 Den Mund aus dem wei\u00dfen Karton schneiden\u2029 und wie in der Abbildung anmalen.\u2029<\/span><\/div>\n<\/li>\n<li class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2eeq3-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"ffghs-0-0\"><span data-offset-key=\"ffghs-0-0\">Arme und Beine werden aus je 2 Papierstreifen gebastelt: am Ende im rechten Winkel aufeinanderkleben und abwechselnd in Rich\u2029tung der Klebefl\u00e4che an der Kante des jeweils\u2029 anderen Papierstreifens falten. Nun die F\u00fc\u00dfe \u2029und Fl\u00fcgel ankleben.\u2029 <\/span><\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div data-block=\"true\" data-editor=\"2gfv7\" data-offset-key=\"2hsk5-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2hsk5-0-0\"><span data-offset-key=\"2hsk5-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"2gfv7\" data-offset-key=\"c6hav-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"c6hav-0-0\"><span data-offset-key=\"c6hav-0-0\">Alle Teile, mit dem Gesicht beginnend, an das \u2029Ei ankleben.\u2029 Die Fl\u00fcgel mit den Federn schm\u00fccken. <\/span><\/div>\n<\/div>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                                                            <\/div>\n                                                                            <div class=\"row mb-4\">\n                                            <div class=\"col-12\">\n                                                                                            <\/div>\n                                        <\/div>\n                                                                                                                                                                                                            <\/div>\n                                                                                    <\/div>\n    <\/section>\n<\/div>\n\n            \n        <div class=\"modal fade modal-move-to-body gallery-modal inspiration\" id=\"modal-text-gallery-video-block_8d1160433f7bcea546c1bb94ffa408fd\" tabindex=\"-1\"\n             aria-labelledby=\"modal-text-gallery-video-block_8d1160433f7bcea546c1bb94ffa408fd\" aria-hidden=\"true\">\n            <div class=\"modal-dialog modal-xl modal-dialog-centered\">\n                <div class=\"modal-content\">\n                    <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n                        <i class=\"fas fa-times\"><\/i>\n                    <\/button>\n                    <div class=\"modal-body\">\n                        <div class=\"container-fluid\">\n                                                            <div class=\"row\">\n                                    <div class=\"col-12\">\n                                        <div class=\"row carousel-item-image-wrapper\">\n                                            <div class=\"col-12\">\n                                                <div class=\"carousel-item-image\">\n                                                    <div class=\"color-area-secondary\"><\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                        <\/div>\n                                                                            <\/div>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    \n\n<div id=\"headline-block_4a34a4c0f95a53afe5894772af8b9368\" class=\"headline\" >\n    <section>\n        <div class=\"container\">\n                        <div class=\"row\">\n                <div class=\"col-12 col-md-6\">\n                                                                <h2 class=\"medium script\">\n                            Viel Spa\u00df beim Stricken und Dekorieren!                        <\/h2>\n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<\/div>\n\n\n\n            \n<div id=\"text-gallery-video-block_3a68ca04fd1eab745d99f1f5758aa337\" class=\"text-gallery-video toc alignment-left inspiration\"  data-toctitle=\"Mehr addiExpress Anleitungen\">\n    <section>\n        <div class=\"container position-relative\">\n            \n\n                                                                                <div class=\"gallery-wrapper  d-lg-block\">\n                                                                                                                        <div class=\"row align-items-end\">\n                                                <div class=\"col-12 col-lg-6 offset-lg-1\">\n                                                    <div class=\"text-wrapper mb-3\">\n                                                                                                                                                                                                                                    <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    \n                                                                    <div class=\"heading-tag\">\n                                                                        <h2> Mehr addiExpress Anleitungen <\/h2>\n                                                                    <\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                            <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    <div class=\"text\">\n                                                                        <div data-block=\"true\" data-editor=\"8bb3\" data-offset-key=\"8c60n-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"8c60n-0-0\"><span data-offset-key=\"8c60n-0-0\">Anleitung aus dem Buch &#8222;<a href=\"https:\/\/shop.addi.de\/de\/buecher\/buch-wollis\">Familie Wolli<\/a>&#8222;<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"8bb3\" data-offset-key=\"2gbmn-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2gbmn-0-0\"><span data-offset-key=\"2gbmn-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"8bb3\" data-offset-key=\"1vdmt-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"1vdmt-0-0\"><span data-offset-key=\"1vdmt-0-0\">Im Anleitungsbuch f\u00fcr die addiExpress geht es um Familie Wolli. Es ist ein Bastel- und Vorlesebuch f\u00fcr die ganze Familie, denn die addiExpress kann schon von Kindern ab 3 Jahren bedient werden. In Zusammenarbeit mit der Bastelkiste in Luxemburg ist ein Buch voll mit sympathischen und lustigen kleinen Kerlen entstanden, die alle eine eigene Geschichte zum Vorlesen erz\u00e4hlen. Insgesamt 20 Familienmitglieder warten darauf, aus der Maschine gekurbelt zu werden. Mit 20 Anleitungen inklusive Schnittvorlage zum Stricken und Basteln.<\/span><\/div>\n<\/div>\n                                                                    <\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                                                                            <\/div>\n                                                    <div class=\"row\">\n                                                        <div class=\"col-12 col-lg-8 offset-lg-4\">\n                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_3a68ca04fd1eab745d99f1f5758aa337\">\n                                                                    <img loading=\"lazy\" decoding=\"async\" width=\"520\" height=\"300\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/975-0_addiExpress_FamilieWolli_Cover_DE_4c-1-520x300.jpg\" class=\"attachment-520x300 size-520x300\" alt=\"Stricktiere Bastel- und Vorlesebuch\" \/>                                                                <\/div>\n                                                                                                                    <\/div>\n                                                    <\/div>\n                                                                                                            <div class=\"scriptheadlinespacer\"><\/div>\n                                                                                                                    <div class=\"buttonspacer\"><\/div>\n                                                                                                                                                            <\/div>\n                                                <div class=\"col-12 col-lg-4\">\n                                                    <div class=\"row mb-3\">\n                                                        <div class=\"col-12 col-lg-9\">\n                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_3a68ca04fd1eab745d99f1f5758aa337\">\n                                                                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/small_ANL_Fred_Fledermaus_36_04e943108c-400x320.png\" class=\"attachment-400x320 size-400x320\" alt=\"Fledermaus\" \/>                                                                <\/div>\n                                                                                                                    <\/div>\n                                                    <\/div>\n                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_3a68ca04fd1eab745d99f1f5758aa337\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/ANL_Hubert-Hase2_35-400x320.png\" class=\"attachment-400x320 size-400x320\" alt=\"Stricken mit Kindern addiExpress\" \/>                                                        <\/div>\n                                                                                                                                                        <\/div>\n                                            <\/div>\n                                                                                                            <\/div>\n                               \n                                 \n                            <div class=\"gallery-wrapper d-block d-lg-none\">\n                                                                    <div class=\"text-wrapper mb-5\">\n                                                                                                                                                                    <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                              \n                                                    <div class=\"heading-tag\">\n                                                        <h2>Mehr addiExpress Anleitungen<\/h2>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                    <div class=\"text\">\n                                                        <div data-block=\"true\" data-editor=\"8bb3\" data-offset-key=\"8c60n-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"8c60n-0-0\"><span data-offset-key=\"8c60n-0-0\">Anleitung aus dem Buch &#8222;<a href=\"https:\/\/shop.addi.de\/de\/buecher\/buch-wollis\">Familie Wolli<\/a>&#8222;<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"8bb3\" data-offset-key=\"2gbmn-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2gbmn-0-0\"><span data-offset-key=\"2gbmn-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div data-block=\"true\" data-editor=\"8bb3\" data-offset-key=\"1vdmt-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"1vdmt-0-0\"><span data-offset-key=\"1vdmt-0-0\">Im Anleitungsbuch f\u00fcr die addiExpress geht es um Familie Wolli. Es ist ein Bastel- und Vorlesebuch f\u00fcr die ganze Familie, denn die addiExpress kann schon von Kindern ab 3 Jahren bedient werden. In Zusammenarbeit mit der Bastelkiste in Luxemburg ist ein Buch voll mit sympathischen und lustigen kleinen Kerlen entstanden, die alle eine eigene Geschichte zum Vorlesen erz\u00e4hlen. Insgesamt 20 Familienmitglieder warten darauf, aus der Maschine gekurbelt zu werden. Mit 20 Anleitungen inklusive Schnittvorlage zum Stricken und Basteln.<\/span><\/div>\n<\/div>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                                                            <\/div>\n                                                                            <div class=\"row mb-4\">\n                                            <div class=\"col-12\">\n                                                                                                    <div id=\"galleryCarousel-block_3a68ca04fd1eab745d99f1f5758aa337\" class=\"carousel slide\" data-ride=\"carousel\" data-interval=\"2500\" data-pause=\"false\" data-keyboard=\"false\">\n                                                        <div class=\"carousel-inner\" data-countslides=\"3\">\n                                                                                                                            <div class=\"carousel-item active\">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_3a68ca04fd1eab745d99f1f5758aa337\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/small_ANL_Fred_Fledermaus_36_04e943108c-1280x970.png\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/small_ANL_Fred_Fledermaus_36_04e943108c-400x320.png\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                            <div class=\"carousel-item \">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_3a68ca04fd1eab745d99f1f5758aa337\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/ANL_Hubert-Hase2_35-1280x970.png\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/ANL_Hubert-Hase2_35-400x320.png\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                            <div class=\"carousel-item \">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_3a68ca04fd1eab745d99f1f5758aa337\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/975-0_addiExpress_FamilieWolli_Cover_DE_4c-1-1131x970.jpg\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/975-0_addiExpress_FamilieWolli_Cover_DE_4c-1-400x320.jpg\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                    <\/div>\n                                                    <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                                                                                                                                                            <\/div>\n                                                                                    <\/div>\n    <\/section>\n<\/div>\n\n            \n        <div class=\"modal fade modal-move-to-body gallery-modal inspiration\" id=\"modal-text-gallery-video-block_3a68ca04fd1eab745d99f1f5758aa337\" tabindex=\"-1\"\n             aria-labelledby=\"modal-text-gallery-video-block_3a68ca04fd1eab745d99f1f5758aa337\" aria-hidden=\"true\">\n            <div class=\"modal-dialog modal-xl modal-dialog-centered\">\n                <div class=\"modal-content\">\n                    <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n                        <i class=\"fas fa-times\"><\/i>\n                    <\/button>\n                    <div class=\"modal-body\">\n                        <div class=\"container-fluid\">\n                                                            <div id=\"modal-carousel-text-gallery-video-block_3a68ca04fd1eab745d99f1f5758aa337\" class=\"carousel slide keepsize\">\n                                    <div class=\"carousel-inner\" data-countslides=\"3\">\n                                                                                    <div class=\"carousel-item active\">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/small_ANL_Fred_Fledermaus_36_04e943108c.png\" class=\"attachment-full size-full wpsmartcrop-image wpsmartcrop-image\" alt=\"Fledermaus\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/small_ANL_Fred_Fledermaus_36_04e943108c.png 500w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/small_ANL_Fred_Fledermaus_36_04e943108c-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/small_ANL_Fred_Fledermaus_36_04e943108c-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/small_ANL_Fred_Fledermaus_36_04e943108c-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/small_ANL_Fred_Fledermaus_36_04e943108c-100x100.png 100w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" data-smartcrop-focus=\"[42,61]\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                                    <div class=\"carousel-item \">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1600\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/ANL_Hubert-Hase2_35.png\" class=\"attachment-full size-full\" alt=\"Stricken mit Kindern addiExpress\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/ANL_Hubert-Hase2_35.png 1600w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/ANL_Hubert-Hase2_35-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/ANL_Hubert-Hase2_35-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/ANL_Hubert-Hase2_35-1536x1536.png 1536w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/ANL_Hubert-Hase2_35-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/ANL_Hubert-Hase2_35-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/ANL_Hubert-Hase2_35-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/ANL_Hubert-Hase2_35-1320x1320.png 1320w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/ANL_Hubert-Hase2_35-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/ANL_Hubert-Hase2_35-100x100.png 100w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                                    <div class=\"carousel-item \">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1131\" height=\"1602\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/975-0_addiExpress_FamilieWolli_Cover_DE_4c-1.jpg\" class=\"attachment-full size-full\" alt=\"Stricktiere Bastel- und Vorlesebuch\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/975-0_addiExpress_FamilieWolli_Cover_DE_4c-1.jpg 1131w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/975-0_addiExpress_FamilieWolli_Cover_DE_4c-1-212x300.jpg 212w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/975-0_addiExpress_FamilieWolli_Cover_DE_4c-1-768x1088.jpg 768w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/975-0_addiExpress_FamilieWolli_Cover_DE_4c-1-1084x1536.jpg 1084w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/975-0_addiExpress_FamilieWolli_Cover_DE_4c-1-8x12.jpg 8w, https:\/\/addi.de\/wp-content\/uploads\/2024\/04\/975-0_addiExpress_FamilieWolli_Cover_DE_4c-1-600x850.jpg 600w\" sizes=\"auto, (max-width: 1131px) 100vw, 1131px\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                            <\/div>\n                                    <a class=\"carousel-control-prev\" href=\"#modal-carousel-text-gallery-video-block_3a68ca04fd1eab745d99f1f5758aa337\" role=\"button\" data-slide=\"prev\">\n                                        <i class=\"fas fa-angle-left\"><\/i>\n                                    <\/a>\n                                    <a class=\"carousel-control-next\" href=\"#modal-carousel-text-gallery-video-block_3a68ca04fd1eab745d99f1f5758aa337\" role=\"button\" data-slide=\"next\">\n                                        <i class=\"fas fa-angle-right\"><\/i>\n                                    <\/a>\n                                    <div class=\"carousel-indicators-wrapper\">\n                                        <ol class=\"carousel-indicators\">\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_3a68ca04fd1eab745d99f1f5758aa337\" data-slide-to=\"0\"\n                                                    class=\"active\"><\/li>\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_3a68ca04fd1eab745d99f1f5758aa337\" data-slide-to=\"1\"\n                                                    class=\"\"><\/li>\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_3a68ca04fd1eab745d99f1f5758aa337\" data-slide-to=\"2\"\n                                                    class=\"\"><\/li>\n                                                                                    <\/ol>\n                                    <\/div>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    \n\n<div id=\"selection-teaser-block_57fa4bbf3672bbf3f7656f6fe287df35\" class=\"selection-teaser \" >\n    <section>\n        <div class=\"container\">\n                            <div class=\"row\">\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper inherit\">\n                            <div class=\"image-wrapper \">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/02\/00_addiExpress-Strickmaschinen_Fadenfuhrung-400x320.png\" class=\"attachment-400x320 size-400x320\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/02\/00_addiExpress-Strickmaschinen_Fadenfuhrung-400x320.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2025\/02\/00_addiExpress-Strickmaschinen_Fadenfuhrung-16x12.png 16w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Page                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        Anleitungen Strickmaschinen                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        Kostenlose Anleitungen f\u00fcr addiExpress Strickmaschinen                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>Entdecken Sie eine Vielzahl von kostenlosen Strickmaschinen-Anleitungen, die Ihnen dabei helfen, Ihre kreative Ader auszuleben. Mit unseren detaillierten Anleitungen f\u00fcr die addiExpress Strickmaschinen wird das Stricken und Kurbeln zum Kinderspiel. Egal, ob Sie Anf\u00e4nger sind oder bereits Erfahrung haben.<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href='https:\/\/addi.de\/en\/anleitungen\/strickmaschinen\/' target='_self' class='buttonlink prio-2'>Zu den Anleitungen f\u00fcr Strickmaschinen <\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper noble\">\n                            <div class=\"image-wrapper \">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/11\/02-Stulpen-Pulswa\u0308rmer-handwarmer-Tilda-Alexstrickt-addi-400x320.jpg\" class=\"attachment-400x320 size-400x320\" alt=\"Pulsw\u00e4rmer stricken &quot;Tilda&quot; - kostenlose Anleitung mit einfachem Spiralmuster f\u00fcr Anf\u00e4nger - by Alexstrickt \u2661 addi.de\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Edles                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        Strickanleitung                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        Pulsw\u00e4rmer stricken &#8222;Tilda&#8220;                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>Diese kleinen und sehr stylischen Pulsw\u00e4rmer sind ein ideales Zwischendurch-Projekt f\u00fcr jede(n) StrickerIn. Ein einfaches Design mit einem sehr effektvollen Spiralmuster, dass ganz unkompliziert mit rechten und linken Maschen gearbeitet wird. Am St\u00fcck gestrickt sind sie super schnell fertig. Zus\u00e4tzlich k\u00f6nnen Garnreste aus dem Stash wunderbar aufgebraucht werden. Ideal auch als Geschenk!<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href='https:\/\/addi.de\/en\/story\/pulswaermer-stricken-tilda\/' target='_self' class='buttonlink prio-2'>Anleitung anschauen<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper inspiration\">\n                            <div class=\"image-wrapper \">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2022\/08\/Newsletter-400x320.png\" class=\"attachment-400x320 size-400x320\" alt=\"\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Page                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        Newsletter                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        addiFan Gefl\u00fcster                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>Mit unserem Newsletter sind Sie immer bestens informiert und verpassen so garantiert keine Produktneuheiten, Trends, kommenden Webinare oder Events rund um das sch\u00f6nste Hobby der Welt.<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href='https:\/\/addi.de\/en\/addigefluester\/' target='_self' class='buttonlink prio-2'>Jetzt anschauen und anmelden<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/section>\n<\/div>\n","protected":false},"parent":0,"menu_order":0,"template":"","kategorie_sy":[31],"kategorie_blog":[560,36,577,550,573,567,568],"class_list":["post-53606","story","type-story","status-publish","hentry","kategorie_sy-inspiration","kategorie_blog-anfaenger","kategorie_blog-anleitung","kategorie_blog-babys-kinder","kategorie_blog-herbst","kategorie_blog-home-deko","kategorie_blog-stricken","kategorie_blog-strickmaschine"],"acf":[],"_links":{"self":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/story\/53606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/types\/story"}],"wp:attachment":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/media?parent=53606"}],"wp:term":[{"taxonomy":"kategorie_sy","embeddable":true,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/kategorie_sy?post=53606"},{"taxonomy":"kategorie_blog","embeddable":true,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/kategorie_blog?post=53606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}