{"id":73246,"date":"2026-03-11T10:37:19","date_gmt":"2026-03-11T09:37:19","guid":{"rendered":"https:\/\/addi.de\/?post_type=story&#038;p=73246"},"modified":"2026-04-28T12:18:41","modified_gmt":"2026-04-28T10:18:41","slug":"stola-tilda-stricken","status":"publish","type":"story","link":"https:\/\/addi.de\/en\/story\/stola-tilda-stricken\/","title":{"rendered":"Stola Tilda stricken (Alexstrickt)"},"content":{"rendered":"<div id=\"header-text-block_caf852c1576db115c7b0023a7be6876e\" class=\"header-text\" >\n    <section>\n        <div class=\"container\">\n            <div class=\"row position-relative\">\n                <div class=\"col-12 col-lg-3 offset-lg-1 order-2 order-lg-1\">\n                    <div class=\"text-wrapper\">\n                        <div class=\"color-area-secondary\"><\/div>\n                                                    <div class=\"topline hl-color\">\n                                Strickanleitung                            <\/div>\n                                                                                                    <h1>Stola Tilda stricken<\/h1>\n                                                <div class=\"share-links\">\n                            <span>Teilen:<\/span>\n                            <a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Faddi.de%2Fen%2Fstory%2Fstola-tilda-stricken%2F\" class=\"d-inline-block px-2\" onclick=\"window.open(this.href, 'mywin', 'left=20,top=20,width=500,height=500,toolbar=1,resizable=0'); return false;\"><i class=\"fab fa-facebook-f hl-color\"><\/i><\/a>\n                            <a href=\"https:\/\/twitter.com\/intent\/tweet?text=https%3A%2F%2Faddi.de%2Fen%2Fstory%2Fstola-tilda-stricken%2F\" class=\"d-inline-block px-2\" onclick=\"window.open(this.href, 'mywin', 'left=20,top=20,width=500,height=500,toolbar=1,resizable=0'); return false;\"><i class=\"fa-brands fa-x-twitter hl-color\"><\/i><\/a>\n                        <\/div>\n                        <div class=\"text\">\n                            <p>Frostbeulen aufgepasst! Egal ob zum festlichen Kleid, auf dem Sofa oder im B\u00fcro \u2013 Die Stola Tilda erg\u00e4nzt dir nahezu jedes Outfit, setzt Akzente und w\u00e4rmt nat\u00fcrlich auch. Ein \u201emindless\u201c Projekt, das ganz schnell aus dem Kopf gestrickt und die Nadeln einfach gl\u00fchen lassen kann.<\/p>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                <div class=\"col-12 col-lg-7 offset-lg-1 mb-3 mb-lg-0 order-1 order-lg-2\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"970\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_kostenlose-Strickanleitung_Alexstrickt_addi_2-1280x970.png\" class=\"attachment-1280x970 size-1280x970\" alt=\"\" \/>                                        <div class=\"row toc-wrapper\">\n                        <div class=\"col-12 col-lg-6 offset-lg-5\">\n                            <div class=\"toc-title\">\n                                Inhaltsverzeichnis                            <\/div>\n                            <div class=\"toc-content\">\n\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<\/div>\n\n\n\n<div id=\"infobox-block_27163b3edf3f0fa2191528279240e131\" class=\"infobox\" >\n    <section>\n        <div class=\"container-fluid container-md\">\n            <div class=\"row\">\n                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                    <div class=\"infobox-wrapper\">\n                        \n                        <div class=\"row\">\n                            <div class=\"col-7 col-sm-5 col-md-2 col-lg-2 col-xl-2\">\n                                <div class=\"difficulty-wrapper color-area-primary\" style=\"position:relative; z-index:1;\">\n                                                                                <i class=\"fa-solid fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-solid fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-regular fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-regular fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-regular fa-heart d-inline-block d-md-block\"><\/i>\n                                                                            <\/div>\n                            <\/div>\n                            <div class=\"col-12 col-md-6 col-lg-6 col-xl-7\">\n                            <div class=\"color-area-secondary\" style=\"right: 5%;\"><\/div>\n                                <div class=\"text-wrapper\">\n                                                                            <div class=\"topline hl-color\" style=\"position:relative; z-index:1;\">\n                                            Was ben\u00f6tigt wird                                        <\/div>\n                                                                                                                <div class=\"text\">\n                                            <ul>\n<li>6x 50g BELLE von Lang Yarns (50g \/ 190m) in je 2x Farbe 09, 27, 29 zusammengehalten mit<\/li>\n<li>6x ZEN von Lang Yarns (25g \/ 200m) in Farbe 094 natur (Ergibt Garnkategorie DK)<\/li>\n<li>addiMystic in St\u00e4rke 3.5 mm\/120cm<\/li>\n<li>2 Maschenmarkierer<\/li>\n<li>Stopfnadel, Scher<\/li>\n<\/ul>\n<p><strong>Maschenprobe<\/strong><\/p>\n<ul>\n<li>Glatt rechts: 23M x 34R = 10&#215;10 cm mit NS 3,50mm<\/li>\n<\/ul>\n<p><strong>Gr\u00f6\u00dfe<\/strong><\/p>\n<ul>\n<li>Breite x H\u00f6he: 150cm x 51cm<\/li>\n<\/ul>\n<p><strong>Anpassung der Gr\u00f6\u00dfe:<\/strong> Korrektur der Maschenzahl beim Anschlag +4M oder -4M. Die H\u00f6he der Stola kann nach Belieben angepasst werden der H\u00f6he d. Beachte, dass du dann ggf. mehr oder weniger Garn ben\u00f6tigst.<\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                            <div class=\"col-7 col-offset-3 col-md-3 col-lg-4 col-xl-3\">\n                                <a href=\"https:\/\/addi.de\/en\/produkt\/addimystic-lace-rundstricknadel\/\">\n                                <div class=\"wrapper-nk\">\n                                    <div class=\"color-area-primary\"><\/div>\n                                        <div class=\"produkt-wraper-nk\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                        <\/div>\n                                    <\/div>\n                                    <div class=\"headline-rodukt-nk hl-color\">\n                                        <p><\/p>\n                                        <p>addiMystic Lace Rundstricknadel<\/p>\n                                    <\/div>\n                                <\/div>\n                                <\/a>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<\/div>\n\n\n\n            \n<div id=\"text-gallery-video-block_88cd78296b1ac83b1782e17ba9a6949f\" class=\"text-gallery-video alignment-left balance\" >\n    <section>\n        <div class=\"container position-relative\">\n            \n\n                                                                                <div class=\"gallery-wrapper  d-lg-block\">\n                                                                                                                        <div class=\"row align-items-end\">\n                                                <div class=\"col-12 col-lg-6 offset-lg-1\">\n                                                    <div class=\"text-wrapper mb-3\">\n                                                                                                                                                                            <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    <div class=\"topline\">So geht es:<\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                                                                                    <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    <div class=\"text\">\n                                                                        <p>Der sch\u00f6ne Farbverlauf der Stola entsteht durch die Kombination zweier Garne. Dabei wird Lang Yarns Zen (Wolle, Alpaka und Seide) in cremewei\u00df mit verschiedenen harmonischen Farben Lang Yarns Belle (Viskose und Baumwolle) kombiniert.<\/p>\n<p>So entsteht ein kuscheliges Tuch mit sanftem Farbverlauf.<\/p>\n<p><strong>Tipp:<\/strong>\u00a0F\u00fcr die richtige Farbverlaufskombination kannst du verschiedene Wickelproben machen.<\/p>\n                                                                    <\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                                                                            <\/div>\n                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_88cd78296b1ac83b1782e17ba9a6949f\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"650\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Wickelprobe-Farbverlauf-900x650.png\" class=\"attachment-900x650 size-900x650\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Wickelprobe-Farbverlauf-900x650.png 900w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Wickelprobe-Farbverlauf-16x12.png 16w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/>                                                        <\/div>\n                                                                                                    <\/div>\n\n                              \n                                                <div class=\"col-12 col-lg-4 elements-count-2\">\n                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_88cd78296b1ac83b1782e17ba9a6949f\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Material-Lang-Zen_Lang-Belle-400x400.png\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Material-Lang-Zen_Lang-Belle-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Material-Lang-Zen_Lang-Belle-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Material-Lang-Zen_Lang-Belle-100x100.png 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                        <\/div>\n                                                                                                                                                                <div class=\"buttonspacer\"><\/div>\n                                                                                                                                                                <div class=\"scriptheadlinespacer\"><\/div>\n                                                        <div class=\"underlinespacer\"><\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                                                                                            <\/div>\n                               \n                                 \n                            <div class=\"gallery-wrapper d-block d-lg-none\">\n                                                                    <div class=\"text-wrapper mb-5\">\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                                    <div class=\"topline\">So geht es:<\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                                                                    <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                    <div class=\"text\">\n                                                        <p>Der sch\u00f6ne Farbverlauf der Stola entsteht durch die Kombination zweier Garne. Dabei wird Lang Yarns Zen (Wolle, Alpaka und Seide) in cremewei\u00df mit verschiedenen harmonischen Farben Lang Yarns Belle (Viskose und Baumwolle) kombiniert.<\/p>\n<p>So entsteht ein kuscheliges Tuch mit sanftem Farbverlauf.<\/p>\n<p><strong>Tipp:<\/strong>\u00a0F\u00fcr die richtige Farbverlaufskombination kannst du verschiedene Wickelproben machen.<\/p>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                                                            <\/div>\n                                                                            <div class=\"row mb-4\">\n                                            <div class=\"col-12\">\n                                                                                                    <div id=\"galleryCarousel-block_88cd78296b1ac83b1782e17ba9a6949f\" class=\"carousel slide\" data-ride=\"carousel\" data-interval=\"2500\" data-pause=\"false\" data-keyboard=\"false\">\n                                                        <div class=\"carousel-inner\" data-countslides=\"2\">\n                                                                                                                            <div class=\"carousel-item active\">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_88cd78296b1ac83b1782e17ba9a6949f\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Wickelprobe-Farbverlauf.png\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Wickelprobe-Farbverlauf-400x320.png\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                            <div class=\"carousel-item \">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_88cd78296b1ac83b1782e17ba9a6949f\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Material-Lang-Zen_Lang-Belle.png\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Material-Lang-Zen_Lang-Belle-400x320.png\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                    <\/div>\n                                                    <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                                                                                                                                                            <\/div>\n                                                                                    <\/div>\n    <\/section>\n<\/div>\n\n            \n        <div class=\"modal fade modal-move-to-body gallery-modal balance\" id=\"modal-text-gallery-video-block_88cd78296b1ac83b1782e17ba9a6949f\" tabindex=\"-1\"\n             aria-labelledby=\"modal-text-gallery-video-block_88cd78296b1ac83b1782e17ba9a6949f\" aria-hidden=\"true\">\n            <div class=\"modal-dialog modal-xl modal-dialog-centered\">\n                <div class=\"modal-content\">\n                    <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n                        <i class=\"fas fa-times\"><\/i>\n                    <\/button>\n                    <div class=\"modal-body\">\n                        <div class=\"container-fluid\">\n                                                            <div id=\"modal-carousel-text-gallery-video-block_88cd78296b1ac83b1782e17ba9a6949f\" class=\"carousel slide keepsize\">\n                                    <div class=\"carousel-inner\" data-countslides=\"2\">\n                                                                                    <div class=\"carousel-item active\">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Wickelprobe-Farbverlauf.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Wickelprobe-Farbverlauf.png 1000w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Wickelprobe-Farbverlauf-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Wickelprobe-Farbverlauf-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Wickelprobe-Farbverlauf-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Wickelprobe-Farbverlauf-600x450.png 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                                    <div class=\"carousel-item \">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Material-Lang-Zen_Lang-Belle.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Material-Lang-Zen_Lang-Belle.png 1000w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Material-Lang-Zen_Lang-Belle-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Material-Lang-Zen_Lang-Belle-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Material-Lang-Zen_Lang-Belle-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Material-Lang-Zen_Lang-Belle-600x450.png 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                            <\/div>\n                                    <a class=\"carousel-control-prev\" href=\"#modal-carousel-text-gallery-video-block_88cd78296b1ac83b1782e17ba9a6949f\" role=\"button\" data-slide=\"prev\">\n                                        <i class=\"fas fa-angle-left\"><\/i>\n                                    <\/a>\n                                    <a class=\"carousel-control-next\" href=\"#modal-carousel-text-gallery-video-block_88cd78296b1ac83b1782e17ba9a6949f\" role=\"button\" data-slide=\"next\">\n                                        <i class=\"fas fa-angle-right\"><\/i>\n                                    <\/a>\n                                    <div class=\"carousel-indicators-wrapper\">\n                                        <ol class=\"carousel-indicators\">\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_88cd78296b1ac83b1782e17ba9a6949f\" data-slide-to=\"0\"\n                                                    class=\"active\"><\/li>\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_88cd78296b1ac83b1782e17ba9a6949f\" data-slide-to=\"1\"\n                                                    class=\"\"><\/li>\n                                                                                    <\/ol>\n                                    <\/div>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    \n\n\n\n<div id=\"text-gallery-video-block_0d91e11163bec54b698d294cb3dfce3d\" class=\"text-gallery-video alignment-left inherit\" >\n    <section>\n        <div class=\"container position-relative\">\n            \n\n                                                                                <div class=\"gallery-wrapper\">\n                                    <div class=\"text-wrapper mb-5\">\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                                    <div class=\"topline\">Schritt 1:<\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                    <div class=\"heading-tag\">\n                                                        \n                                                        <h2> Anleitung Stola Tilda <\/h2>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                    <div class=\"text\">\n                                                        <p>291M anschlagen mit zwei F\u00e4den.<\/p>\n<ul>\n<li><strong>Reihe 1:<\/strong> 3li \/\/ MM platzieren \/\/ alle M re bis 3M vor Ende \/\/ MM platzieren \/\/ 3re (RR)<\/li>\n<li><strong>Reihe 2:<\/strong> 3M abhmFv \/\/ alle M re bis 3M vor Ende \/\/ 3re (HR)<\/li>\n<li><strong>Reihe 3:<\/strong>\u00a03M abhmFv \/\/ 6re, 14x (+1QF, 19re), +1QF, 7re \/\/ 3re (=300M)<\/li>\n<\/ul>\n<p><strong>Video tutorial: <\/strong>Maschenanschlag\u00a0von Alexstrickt: Kreuzanschlag mit zwei F\u00e4den (bspw. f\u00fcr hohe Maschenanzahl):<\/p>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                                                            <\/div>\n                                    <div class=\"row\">\n                                        <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                            <div class=\"video-wrapper\">\n                                                <iframe loading=\"lazy\" title=\"Tutorial: Kreuzanschlag mit zwei F\u00e4den (bspw. f\u00fcr hohe Maschenanzahl)\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/7c8cMkbH-mQ?feature=oembed&#038;rel=0&#038;autoplay=0&#038;loop=0&#038;mute=0&#038;controls=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen frameborder=\"0\"><\/iframe>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                                                    <\/div>\n                                                                                    <\/div>\n    <\/section>\n<\/div>\n\n\n\n\n\n        \n<div id=\"text-gallery-video-block_e74d36df50f4968e4750770fa3c927f4\" class=\"text-gallery-video alignment-right balance\" >\n    <section>\n        <div class=\"container position-relative\">\n                                                        <div class=\"text-wrapper\">\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-9 offset-lg-3\">\n                                        <div class=\"topline\">Schritt 2<\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                                                    <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-3\">\n                                        <div class=\"text\">\n                                            <p><strong>Nun zum Tilda Muster wechseln:<\/strong><\/p>\n<ul>\n<li><strong>Reihe 1:<\/strong> 3M abhmFv \/\/ *1li, 3re* \/\/ 3re<\/li>\n<li><strong>Reihe 2:<\/strong> 3M abhmFv \/\/ *2li, 1re, 1li* \/\/ 3re<\/li>\n<li><strong>Reihe 3:<\/strong> 3M abhmFv \/\/ *2re, 1li, 1re* \/\/ 3re<\/li>\n<li><strong>Reihe 4:<\/strong> 3M abhmFv \/\/ *1re, 3li* \/\/ 3re<\/li>\n<li>Diese 4 Reihen stetig wiederholen.<\/li>\n<\/ul>\n<p>Bis zur gew\u00fcnschten H\u00f6he str (bspw. 50cm) und in R2 oder R4 auf den Abschluss wechseln.<\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                                            <\/div>\n                                                <\/div>\n    <\/section>\n<\/div>\n\n\n\n\n            \n<div id=\"text-gallery-video-block_abf83e9aa6ba802482dec04556507e40\" class=\"text-gallery-video alignment-left balance\" >\n    <section>\n        <div class=\"container position-relative\">\n            \n\n                                                                                <div class=\"gallery-wrapper  d-lg-block\">\n                                                                                                                        <div class=\"row align-items-end\">\n                                                <div class=\"col-12 col-lg-6 offset-lg-1\">\n                                                    <div class=\"text-wrapper mb-3\">\n                                                                                                                                                                            <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    <div class=\"topline\">Schritt 3<\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                            <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    \n                                                                    <div class=\"heading-tag\">\n                                                                    <h2> Abschluss <\/h2>\n                                                                    <\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                            <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    <div class=\"text\">\n                                                                        <ul>\n<li><strong>Reihe 1:<\/strong> 3M abhmFv \/\/ 5re, 14x (2M re zus str, 18re), 2M re zus str, 6re \/\/ 3re (= 291M)<\/li>\n<li><strong>Reihe 2:<\/strong> 3M abhmFv \/\/ alle M re \/\/ 3re<\/li>\n<li><strong>Reihe 3:<\/strong>\u00a01M abhmFv, 2M li zus str \/\/ MM entf \/\/ alle M re \/\/ MM entf \/\/ 2M re zus str, 1re<\/li>\n<\/ul>\n<p>Alle M locker abketten.<br \/>\n<strong>Tipp f\u00fcr einfaches lockeres Abketten: <\/strong>Benutze eine etwas gr\u00f6\u00dfere Stricknadel.<\/p>\n<ul>\n<li>Faden abschneiden und vern\u00e4hen.<\/li>\n<li>Die Stola waschen und liegend trocknen, dabei etwas in Form ziehen.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n                                                                    <\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                                                                            <\/div>\n                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_abf83e9aa6ba802482dec04556507e40\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"650\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Strickmuster-900x650.png\" class=\"attachment-900x650 size-900x650\" alt=\"\" \/>                                                        <\/div>\n                                                                                                    <\/div>\n\n                              \n                                                <div class=\"col-12 col-lg-4 elements-count-2\">\n                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_abf83e9aa6ba802482dec04556507e40\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-400x400.png\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-100x100.png 100w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                        <\/div>\n                                                                                                                                                                <div class=\"buttonspacer\"><\/div>\n                                                                                                                                                                <div class=\"scriptheadlinespacer\"><\/div>\n                                                        <div class=\"underlinespacer\"><\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                                                                                            <\/div>\n                               \n                                 \n                            <div class=\"gallery-wrapper d-block d-lg-none\">\n                                                                    <div class=\"text-wrapper mb-5\">\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                                    <div class=\"topline\">Schritt 3<\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                              \n                                                    <div class=\"heading-tag\">\n                                                        <h2>Abschluss<\/h2>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                    <div class=\"text\">\n                                                        <ul>\n<li><strong>Reihe 1:<\/strong> 3M abhmFv \/\/ 5re, 14x (2M re zus str, 18re), 2M re zus str, 6re \/\/ 3re (= 291M)<\/li>\n<li><strong>Reihe 2:<\/strong> 3M abhmFv \/\/ alle M re \/\/ 3re<\/li>\n<li><strong>Reihe 3:<\/strong>\u00a01M abhmFv, 2M li zus str \/\/ MM entf \/\/ alle M re \/\/ MM entf \/\/ 2M re zus str, 1re<\/li>\n<\/ul>\n<p>Alle M locker abketten.<br \/>\n<strong>Tipp f\u00fcr einfaches lockeres Abketten: <\/strong>Benutze eine etwas gr\u00f6\u00dfere Stricknadel.<\/p>\n<ul>\n<li>Faden abschneiden und vern\u00e4hen.<\/li>\n<li>Die Stola waschen und liegend trocknen, dabei etwas in Form ziehen.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                                                            <\/div>\n                                                                            <div class=\"row mb-4\">\n                                            <div class=\"col-12\">\n                                                                                                    <div id=\"galleryCarousel-block_abf83e9aa6ba802482dec04556507e40\" class=\"carousel slide\" data-ride=\"carousel\" data-interval=\"2500\" data-pause=\"false\" data-keyboard=\"false\">\n                                                        <div class=\"carousel-inner\" data-countslides=\"2\">\n                                                                                                                            <div class=\"carousel-item active\">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_abf83e9aa6ba802482dec04556507e40\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Strickmuster-1000x970.png\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Strickmuster-400x320.png\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                            <div class=\"carousel-item \">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_abf83e9aa6ba802482dec04556507e40\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-1280x970.png\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-400x320.png\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                    <\/div>\n                                                    <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                                                                                                                                                            <\/div>\n                                                                                    <\/div>\n    <\/section>\n<\/div>\n\n            \n        <div class=\"modal fade modal-move-to-body gallery-modal balance\" id=\"modal-text-gallery-video-block_abf83e9aa6ba802482dec04556507e40\" tabindex=\"-1\"\n             aria-labelledby=\"modal-text-gallery-video-block_abf83e9aa6ba802482dec04556507e40\" aria-hidden=\"true\">\n            <div class=\"modal-dialog modal-xl modal-dialog-centered\">\n                <div class=\"modal-content\">\n                    <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n                        <i class=\"fas fa-times\"><\/i>\n                    <\/button>\n                    <div class=\"modal-body\">\n                        <div class=\"container-fluid\">\n                                                            <div id=\"modal-carousel-text-gallery-video-block_abf83e9aa6ba802482dec04556507e40\" class=\"carousel slide keepsize\">\n                                    <div class=\"carousel-inner\" data-countslides=\"2\">\n                                                                                    <div class=\"carousel-item active\">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Strickmuster.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Strickmuster.png 1000w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Strickmuster-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Strickmuster-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Strickmuster-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Strickmuster-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Strickmuster-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Strickmuster-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda-stricken_Strickmuster-100x100.png 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                                    <div class=\"carousel-item \">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3.png\" class=\"attachment-full size-full wpsmartcrop-image wpsmartcrop-image\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3.png 1000w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/Stola-Tilda_3-100x100.png 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-smartcrop-focus=\"[49,22]\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                            <\/div>\n                                    <a class=\"carousel-control-prev\" href=\"#modal-carousel-text-gallery-video-block_abf83e9aa6ba802482dec04556507e40\" role=\"button\" data-slide=\"prev\">\n                                        <i class=\"fas fa-angle-left\"><\/i>\n                                    <\/a>\n                                    <a class=\"carousel-control-next\" href=\"#modal-carousel-text-gallery-video-block_abf83e9aa6ba802482dec04556507e40\" role=\"button\" data-slide=\"next\">\n                                        <i class=\"fas fa-angle-right\"><\/i>\n                                    <\/a>\n                                    <div class=\"carousel-indicators-wrapper\">\n                                        <ol class=\"carousel-indicators\">\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_abf83e9aa6ba802482dec04556507e40\" data-slide-to=\"0\"\n                                                    class=\"active\"><\/li>\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_abf83e9aa6ba802482dec04556507e40\" data-slide-to=\"1\"\n                                                    class=\"\"><\/li>\n                                                                                    <\/ol>\n                                    <\/div>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    \n\n\n\n        \n<div id=\"text-gallery-video-block_0c1fa0bbc9f8b30ca41ddda492d83d6c\" class=\"text-gallery-video alignment-left balance\" >\n    <section>\n        <div class=\"container position-relative\">\n                                                        <div class=\"text-wrapper\">\n                                                                                                                    <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                        \n                                        <div class=\"heading-tag\">\n                                            <h2> Abk\u00fcrzungen  <\/h2>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                        <div class=\"text\">\n                                            <ul>\n<li><strong>M<\/strong> = Masche<\/li>\n<li><strong>re<\/strong>= rechts<\/li>\n<li><strong>li<\/strong> = links<\/li>\n<li><strong>zus<\/strong> = zusammen<\/li>\n<li><strong>str<\/strong> = stricken<\/li>\n<li><strong>MM <\/strong>= Maschenmarkierer<\/li>\n<li><strong>\/\/ <\/strong>= Maschenmarkierer abheben<\/li>\n<li><strong>entf<\/strong> = entfernen<\/li>\n<li><strong>RR<\/strong> = R\u00fcckreihe<\/li>\n<li><strong>HR<\/strong> = Hinreihe<\/li>\n<li><strong>abhmFv<\/strong> = Abheben wie zu li str mit Faden vor der Arbeit<\/li>\n<li><strong>+1QF<\/strong> = Zunahme: eine M aus dem Querfaden zwischen zwei M heraus stricken (mit der linken Nadel von vorn in den Querfaden einstechen und li verschr stricken)<\/li>\n<li>** = wiederholen von * bis *<\/li>\n<\/ul>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                                            <\/div>\n                                                <\/div>\n    <\/section>\n<\/div>\n\n\n\n\n\n        \n<div id=\"text-gallery-video-block_e169eba0cb444e0ef897c51e2172da31\" class=\"text-gallery-video alignment-left balance\" >\n    <section>\n        <div class=\"container position-relative\">\n                                                        <div class=\"text-wrapper\">\n                                                            <div class=\"text-background-big color-area-secondary\"><\/div>\n                                                                                                                    <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                        \n                                        <div class=\"heading-tag\">\n                                            <h2> Anleitung auch zum Drucken oder in der addi2go App <\/h2>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                                                    <div class=\"row\">\n                                    <div class=\"col-12 col-lg-6 offset-lg-2\">\n                                        <div class=\"text text_indented\">\n                                            <p><strong>Die schriftliche Anleitung zum Ausdrucken in Deutsch gibt es bei Designerin <a href=\"https:\/\/addi.de\/story\/alexstrickt-alexandra-sakota\/\">Alexandra Sakota<\/a> k\u00e4uflich zu erwerben.<\/strong><\/p>\n<p>Die kostenlose Version der Anleitung finden Sie au\u00dferdem digital in unserer <a href=\"https:\/\/addi.de\/addi2go\/\">addi2go App<\/a>. Dort k\u00f6nnen Sie die Anleitung in einem Projekt mit Reihenz\u00e4hlern und Notizen speichern.<\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                        <div class=\"row link-wrapper\">\n                                    <div class=\"col-12 col-lg-6 offset-lg-2\">\n                                        <div class=\"row\">\n                                                                                            <div class=\"col-12 col-lg-6\">\n                                                    <a href=\"https:\/\/ravel.me\/stola-tilda\" target=\"_blank\" class=\"buttonlink prio-1\" rel=\"noopener\">Anleitung bei Ravelry kaufen<\/a>                                                <\/div>\n                                                                                                                                <\/div>\n                                    <\/div>\n                                <\/div>\n                                                    <\/div>\n                                                <\/div>\n    <\/section>\n<\/div>\n\n\n\n<div id=\"selection-teaser-block_0035742f8f94507bd4d853bc7e9d167b\" class=\"selection-teaser \" >\n    <section>\n        <div class=\"container\">\n                            <div class=\"row\">\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper company\">\n                            <div class=\"image-wrapper product\">\n                                                                                                            <div class=\"product-dimensions\"><\/div>\n                                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-600x600.png\" class=\"attachment-woocommerce_single size-woocommerce_single\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c-100x100.png 100w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/706-2_addiMystic_Rundstricknadel_5-0_frei_4c.png 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                        <div class=\"product-background color-area-secondary\"><\/div>\n                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Product                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                                                    <div class=\"headline\">\n                                        addiMystic Lace Rundstricknadel                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        Die edle, mystisch schimmernde Rundstricknadel f\u00fchlt sich durch ihre matte Oberfl\u00e4che wunderbar sanft an.\r\n\r\nDer Hands&#8230;                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href=\"https:\/\/addi.de\/en\/produkt\/addimystic-lace-rundstricknadel\/\" target=\"_self\" class=\"buttonlink prio-2\">Zum Produkt<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper company\">\n                            <div class=\"image-wrapper \">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/10-Jahre-Garantie-400x320.jpg\" class=\"attachment-400x320 size-400x320\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/10-Jahre-Garantie-400x320.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/10-Jahre-Garantie-16x12.jpg 16w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Unternehmen                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        Unsere Garantie                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        10 Jahre Garantie: Qualit\u00e4t, die bleibt.                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>Immer ein gutes Gef\u00fchl. Wir glauben daran, dass gute Dinge lange halten \u2013 und dass man das auch sp\u00fcren sollte. Deshalb geben wir auf unsere addi-Produkte <strong>10 Jahre Garantie<\/strong>.<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href=\"https:\/\/addi.de\/en\/story\/10-jahre-garantie\/\" target=\"_self\" class=\"buttonlink prio-2\">addi-Garantieversprechen<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper company\">\n                            <div class=\"image-wrapper \">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2021\/10\/000-addi-Sideshot2.2-Nadelspitzen-400x320.png\" class=\"attachment-400x320 size-400x320\" alt=\"\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Unternehmen                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        addi Basics                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        Welches Stricknadel-<br \/>\r\nMaterial w\u00e4hle ich?                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>Du fragst dich, welche Stricknadel perfekt zu dir und deinem Projekt passt? Welches Material f\u00fcr Stricknadeln welche Vorteile bietet, erf\u00e4hrst du hier.<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href=\"https:\/\/addi.de\/en\/story\/welches-stricknadel-material-waehle-ich\/\" target=\"_self\" class=\"buttonlink prio-2\">Story lesen<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/section>\n<\/div>\n","protected":false},"parent":0,"menu_order":0,"template":"","kategorie_sy":[32],"kategorie_blog":[571,36,578,563,548,559,567,565,570,576],"class_list":["post-73246","story","type-story","status-publish","hentry","kategorie_sy-balance","kategorie_blog-accessoires","kategorie_blog-anleitung","kategorie_blog-damen","kategorie_blog-fortgeschrittene-anfaenger","kategorie_blog-fruehling","kategorie_blog-schwierigkeit","kategorie_blog-stricken","kategorie_blog-technik","kategorie_blog-thema","kategorie_blog-zielgruppe"],"acf":[],"_links":{"self":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/story\/73246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/types\/story"}],"wp:attachment":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/media?parent=73246"}],"wp:term":[{"taxonomy":"kategorie_sy","embeddable":true,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/kategorie_sy?post=73246"},{"taxonomy":"kategorie_blog","embeddable":true,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/kategorie_blog?post=73246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}