{"id":73673,"date":"2026-02-25T13:44:03","date_gmt":"2026-02-25T12:44:03","guid":{"rendered":"https:\/\/addi.de\/?post_type=story&#038;p=73673"},"modified":"2026-02-26T16:48:44","modified_gmt":"2026-02-26T15:48:44","slug":"fische-haekeln-hh-will-chatlosh","status":"publish","type":"story","link":"https:\/\/addi.de\/en\/story\/fische-haekeln-hh-will-chatlosh\/","title":{"rendered":"Fische h\u00e4keln h+h (Will Chatlosh)"},"content":{"rendered":"<div id=\"header-text-block_3375c3be2a053cee314c0df57da50f6b\" class=\"header-text\" >\n    <section>\n        <div class=\"container\">\n            <div class=\"row position-relative\">\n                <div class=\"col-12 col-lg-3 offset-lg-1 order-2 order-lg-1\">\n                    <div class=\"text-wrapper\">\n                        <div class=\"color-area-secondary\"><\/div>\n                                                    <div class=\"topline hl-color\">\n                                Crochet tutorial                            <\/div>\n                                                                                                    <h1>Let's make some fish - h+h cologne special<\/h1>\n                                                <div class=\"share-links\">\n                            <span>Teilen:<\/span>\n                            <a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Faddi.de%2Fen%2Fstory%2Ffische-haekeln-hh-will-chatlosh%2F\" class=\"d-inline-block px-2\" onclick=\"window.open(this.href, 'mywin', 'left=20,top=20,width=500,height=500,toolbar=1,resizable=0'); return false;\"><i class=\"fab fa-facebook-f hl-color\"><\/i><\/a>\n                            <a href=\"https:\/\/twitter.com\/intent\/tweet?text=https%3A%2F%2Faddi.de%2Fen%2Fstory%2Ffische-haekeln-hh-will-chatlosh%2F\" class=\"d-inline-block px-2\" onclick=\"window.open(this.href, 'mywin', 'left=20,top=20,width=500,height=500,toolbar=1,resizable=0'); return false;\"><i class=\"fa-brands fa-x-twitter hl-color\"><\/i><\/a>\n                        <\/div>\n                        <div class=\"text\">\n                            <p>For our community artwork at h+h, artist Will Chatlosh has designed customisable fish to crochet. Would you like to crochet your very own fish?<\/p>\n<p>For our community artwork at h+h, artist Will Chatlosh has designed customisable fish to crochet. Would you like to crochet your very own fish? This year, we are once again inviting our partners and trade visitors to h+h in Cologne. Over three days, we will be collaborating with the artist #wccrochet to create a joint work of art. <strong>We invite our visitors to bring along lots of individual fish and help complete the artwork at our booth.<\/strong><\/p>\n<p>&nbsp;<\/p>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                <div class=\"col-12 col-lg-7 offset-lg-1 mb-3 mb-lg-0 order-1 order-lg-2\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"752\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fische-hakeln-quer.png\" class=\"attachment-1280x970 size-1280x970\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fische-hakeln-quer.png 1000w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fische-hakeln-quer-399x300.png 399w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fische-hakeln-quer-768x578.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fische-hakeln-quer-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fische-hakeln-quer-600x451.png 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                        <div class=\"row toc-wrapper\">\n                        <div class=\"col-12 col-lg-6 offset-lg-5\">\n                            <div class=\"toc-title\">\n                                Inhaltsverzeichnis                            <\/div>\n                            <div class=\"toc-content\">\n\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<\/div>\n\n\n\n<div id=\"infobox-block_3c92c418667c09e872256c43c35f29d7\" class=\"infobox\" >\n    <section>\n        <div class=\"container-fluid container-md\">\n            <div class=\"row\">\n                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                    <div class=\"infobox-wrapper\">\n                        \n                        <div class=\"row\">\n                            <div class=\"col-7 col-sm-5 col-md-2 col-lg-2 col-xl-2\">\n                                <div class=\"difficulty-wrapper color-area-primary\" style=\"position:relative; z-index:1;\">\n                                                                                <i class=\"fa-solid fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-solid fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-regular fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-regular fa-heart d-inline-block d-md-block\"><\/i>\n                                            <i class=\"fa-regular fa-heart d-inline-block d-md-block\"><\/i>\n                                                                            <\/div>\n                            <\/div>\n                            <div class=\"col-12 col-md-6 col-lg-6 col-xl-7\">\n                            <div class=\"color-area-secondary\" style=\"right: 5%;\"><\/div>\n                                <div class=\"text-wrapper\">\n                                                                            <div class=\"topline hl-color\" style=\"position:relative; z-index:1;\">\n                                            What you need:                                         <\/div>\n                                                                                                                <div class=\"text\">\n                                            <ul>\n<li>Leftover yarn in various accent colours (see tutorial)<\/li>\n<li>H\u00e4kelnadel passend zur Garnst\u00e4rke<\/li>\n<li>Darning needle<\/li>\n<li>Scissors<\/li>\n<\/ul>\n<p>Any yarn with a suitable needle size can be used. Thin yarns produce small fish, thick yarns produce large fish. Ideal for using up leftovers.<br \/>\n<strong>We are delighted to receive every unique example!<\/strong><\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                            <div class=\"col-7 col-offset-3 col-md-3 col-lg-4 col-xl-3\">\n                                <a href=\"https:\/\/addi.de\/en\/produkt\/addinature-walnut-gold-haekelnadel\/\">\n                                <div class=\"wrapper-nk\">\n                                    <div class=\"color-area-primary\"><\/div>\n                                        <div class=\"produkt-wraper-nk\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/588-7_addiNature_Walnut_Gold_Hakelnadel_5-0mm_4c.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/588-7_addiNature_Walnut_Gold_Hakelnadel_5-0mm_4c.png 1200w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/588-7_addiNature_Walnut_Gold_Hakelnadel_5-0mm_4c-300x300.png 300w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/588-7_addiNature_Walnut_Gold_Hakelnadel_5-0mm_4c-768x768.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/588-7_addiNature_Walnut_Gold_Hakelnadel_5-0mm_4c-12x12.png 12w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/588-7_addiNature_Walnut_Gold_Hakelnadel_5-0mm_4c-800x800.png 800w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/588-7_addiNature_Walnut_Gold_Hakelnadel_5-0mm_4c-400x400.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/588-7_addiNature_Walnut_Gold_Hakelnadel_5-0mm_4c-600x600.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2025\/01\/588-7_addiNature_Walnut_Gold_Hakelnadel_5-0mm_4c-100x100.png 100w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                        <\/div>\n                                    <\/div>\n                                    <div class=\"headline-rodukt-nk hl-color\">\n                                        <p><\/p>\n                                        <p>addiNature Walnut Gold crochet hook<\/p>\n                                    <\/div>\n                                <\/div>\n                                <\/a>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<\/div>\n\n\n\n\n        \n<div id=\"text-gallery-video-block_1bee6390ced8f80793ec8db72b189ba1\" class=\"text-gallery-video alignment-left inspiration\" >\n    <section>\n        <div class=\"container position-relative\">\n                                                        <div class=\"text-wrapper\">\n                                                                                                                                                <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                        <div class=\"text\">\n                                            <p><strong>Call for entries:<\/strong> Are you unable to attend h+h but would still like to contribute to the artwork? Then please send us your crocheted fish by post by 13 March 2026 to: GUSTAV SELTER GmbH &amp; Co. KG, Marketing Department, Hauptstra\u00dfe 2-6, 58762 Altena, Germany<\/p>\n<p>GUSTAV SELTER GmbH &amp; Co. KG, Marketing, Hauptstra\u00dfe 2-6, 58762 Altena<\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                                            <\/div>\n                                                <\/div>\n    <\/section>\n<\/div>\n\n\n\n\n\n        \n<div id=\"text-gallery-video-block_ad2b34d39c57bc4cf5108f5c80420136\" class=\"text-gallery-video alignment-left inspiration\" >\n    <section>\n        <div class=\"container position-relative\">\n                                                        <div class=\"text-wrapper\">\n                                                            <div class=\"text-background-big color-area-secondary\"><\/div>\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                        <div class=\"topline\">How it works<\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                        \n                                        <div class=\"heading-tag\">\n                                            <h2> Crochet fish in 5 variants <\/h2>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                                                    <div class=\"row\">\n                                    <div class=\"col-12 col-lg-6 offset-lg-2\">\n                                        <div class=\"text text_indented\">\n                                            <ol>\n<li><strong>There are three different body shapes that can be designed with any fin style and individual details such as stripes or embroidery. Combine them freely according to the mix and match principle.<\/strong><\/li>\n<li><strong>Next, the fins and decorative stripes of the different fish varieties can be designed and attached.<\/strong><\/li>\n<li><strong>Eye<\/strong><\/li>\n<\/ol>\n<p><strong>Tip:<\/strong> Combine details such as stripes or embroidery freely according to the mix-and-match principle.<\/p>\n<p>The pattern includes 5 fish with individual decorations. You are welcome to mix them up or design your own.<\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                <\/div>\n                                                <\/div>\n    <\/section>\n<\/div>\n\n\n\n<div id=\"accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf\" class=\"accordeon toc\"  data-toctitle=\"K\u00f6performen\">\n    <section>\n        <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                    <h2>Body shapes<\/h2>\n                <\/div>\n            <\/div>\n            <div class=\"row\">\n                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                    <div class=\"accordion\" id=\"accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf\">\n                                                    <div class=\"accordion-card mb-4\">\n                                <div class=\"accordion-card-header\" id=\"heading-0\">\n                                    <div class=\"row no-gutters\">\n                                        <div class=\"col-1\">\n                                            <div class=\"btn btn-link btn-block text-center p-0\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapse-accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf-0\" aria-expanded=\"true\" aria-controls=\"collapse-accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf-0\">\n                                                <i class=\"fas fa-chevron-down hl-color\"><\/i>\n                                            <\/div>\n                                        <\/div>\n                                        <div class=\"col-11\">\n                                            <div class=\"btn btn-link btn-block text-left p-0\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapse-accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf-0\" aria-expanded=\"true\" aria-controls=\"collapse-accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf-0\">\n                                                <p class=\"mb-2\">Body variant 1<\/p>\n                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                <div id=\"collapse-accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf-0\" class=\"collapse show\" aria-labelledby=\"heading-0\" data-parent=\"#accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf\">\n                                    <div class=\"accordion-card-body\">\n                                        <div class=\"row no-gutters\">\n                                            <div class=\"col-11 offset-1\">\n                                                <ul>\n<li>The body is crocheted in the round, beginning with a oval foundation chain.<\/li>\n<li>Starting chains do not count as stitches.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73726 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-01-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-01-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-01-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-01-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-01-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-01.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<ul>\n<li>ch 22<\/li>\n<li>work beginning in the second ch from hook:<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73727 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-02-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-02-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-02-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-02-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-02-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-02.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><strong>Round 1:<\/strong><\/p>\n<ul>\n<li>sc 2, hdc 6, dc 5, hdc 6, sc 1, (sc 3) in last st, turn onto other side: sc 1, hdc 6, dc 5, hdc 6, sc 1, (sc 1, dc 1) in next st<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73728 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-03-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-03-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-03-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-03-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-03-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-03.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><strong>Round 2:<\/strong><\/p>\n<ul>\n<li>hdc-inc, hdc 6, dc 7, hdc 7, (sc 3) in next st, hdc 7, dc 7, hdc 7, sc-inc<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73729 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-04-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-04-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-04-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-04-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-04-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-04.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><strong>Round 3:<\/strong><\/p>\n<ul>\n<li>sc-inc, sc 2, hdc 3, dc 11, hdc 3, sc 3, 2 x (sc-inc), sc 2, hdc 3, dc 12, hdc 3, sc 3<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73730 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-05-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-05-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-05-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-05-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-05-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-05.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><strong>Round 4<\/strong><\/p>\n<ul>\n<li>(sc 3) in next st, sc 4, hdc 3, dc 10, hdc 3, sc 4, sc 3 in next st, sc 4, hdc 3, dc 10, hdc 3, sc 4, slst<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73731 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-06-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-06-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-06-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-06-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-06-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-06.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<ul>\n<li>fasten off in next st.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73732 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-07-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-07-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-07-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-07-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-07-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V1-07.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                                                    <div class=\"accordion-card mb-4\">\n                                <div class=\"accordion-card-header\" id=\"heading-1\">\n                                    <div class=\"row no-gutters\">\n                                        <div class=\"col-1\">\n                                            <div class=\"btn btn-link btn-block text-center p-0\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapse-accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf-1\" aria-expanded=\"false\" aria-controls=\"collapse-accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf-1\">\n                                                <i class=\"fas fa-chevron-down hl-color\"><\/i>\n                                            <\/div>\n                                        <\/div>\n                                        <div class=\"col-11\">\n                                            <div class=\"btn btn-link btn-block text-left p-0\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapse-accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf-1\" aria-expanded=\"false\" aria-controls=\"collapse-accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf-1\">\n                                                <p class=\"mb-2\">Body variant 2<\/p>\n                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                <div id=\"collapse-accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf-1\" class=\"collapse\" aria-labelledby=\"heading-1\" data-parent=\"#accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf\">\n                                    <div class=\"accordion-card-body\">\n                                        <div class=\"row no-gutters\">\n                                            <div class=\"col-11 offset-1\">\n                                                <ul>\n<li>The body is crocheted in the round, beginning with a oval foundation chain.<\/li>\n<li>Starting chains do not count as stitches.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73733 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-01-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-01-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-01-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-01-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-01-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-01.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<ul>\n<li>ch 25.<\/li>\n<li>work beginning in the second ch from hook:<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73734 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-02-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-02-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-02-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-02-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-02-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-02.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><strong>Round 1:<\/strong><\/p>\n<ul>\n<li>hdc 23, hdc 4 in the last ch, turn and continue onto other side of ch: hdc 22, (hdc 1, dc 2) in last ch<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73735 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-03-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-03-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-03-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-03-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-03-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-03.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><strong>Round 2:<\/strong><\/p>\n<ul>\n<li>ignore the last turning ch and move up to continue in the round<\/li>\n<li>hdc 7, dc 8, hdc 9, (hdc 1, dc 1) in next st, (dc 1, hdc 1) in next st, hdc 9, dc 8, hdc 8, hdc-inc<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73736 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-04-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-04-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-04-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-04-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-04-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-04.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><strong>Round 3:<\/strong><\/p>\n<ul>\n<li>hdc-inc, hdc 5, dc 10, hdc 10, 2x hdc-inc, hdc 6, dc 13, hdc 7, hdc-inc<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73737 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-05-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-05-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-05-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-05-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-05-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-05.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><strong>Round 4<\/strong><\/p>\n<ul>\n<li>hdc-inc, hdc 3, hdc-inc, hdc 13, sc 11, hdc-inc, (hdc 1, dc 1) in next st, (dc 1, hdc 1) in next st, sc 1, slst and fasten off in next st<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73738 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-06-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-06-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-06-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-06-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-06-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V2-06.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<ul>\n<li>fasten off in next st.<\/li>\n<li>The side you fasten off will be the back side of your fish.<\/li>\n<\/ul>\n                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                                                    <div class=\"accordion-card mb-4\">\n                                <div class=\"accordion-card-header\" id=\"heading-2\">\n                                    <div class=\"row no-gutters\">\n                                        <div class=\"col-1\">\n                                            <div class=\"btn btn-link btn-block text-center p-0\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapse-accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf-2\" aria-expanded=\"false\" aria-controls=\"collapse-accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf-2\">\n                                                <i class=\"fas fa-chevron-down hl-color\"><\/i>\n                                            <\/div>\n                                        <\/div>\n                                        <div class=\"col-11\">\n                                            <div class=\"btn btn-link btn-block text-left p-0\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapse-accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf-2\" aria-expanded=\"false\" aria-controls=\"collapse-accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf-2\">\n                                                <p class=\"mb-2\">Body variant 3<\/p>\n                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                <div id=\"collapse-accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf-2\" class=\"collapse\" aria-labelledby=\"heading-2\" data-parent=\"#accordeon-block_462ddbc2e420a2dd5736a2eba3aa8faf\">\n                                    <div class=\"accordion-card-body\">\n                                        <div class=\"row no-gutters\">\n                                            <div class=\"col-11 offset-1\">\n                                                <ul>\n<li>The body is crocheted in the round, beginning with a stariting ch.<\/li>\n<li>Turning chains do not count as stitches.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73835 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-01-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-01-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-01-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-01-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-01-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-01.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<ul>\n<li>ch 20.<\/li>\n<li>Work beginning in the second ch from hook:<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73836 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-02-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-02-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-02-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-02-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-02-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-02.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><strong>Round 1:<\/strong><\/p>\n<ul>\n<li>sc 2, hdc 5, dc 5, hdc 5, sc 1, in last ch from hook: sc 3 in next st, continue around other side of ch: sc 1, hdc 5, dc 5, hdc 5, sc 1, sc-inc and skip your turning ch &amp; continue up in the round<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73837 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-03-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-03-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-03-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-03-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-03-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-03.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><strong>Round 2:<\/strong><\/p>\n<ul>\n<li>slst 1, sc 2, hdc 4, dc 6, hdc 4, sc 2, sc-inc, sc 2, hdc 4, dc 7, hdc 4, sc 2, slst 1<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73838 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-04-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-04-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-04-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-04-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-04-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-04.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><strong>Round 3:<\/strong><\/p>\n<ul>\n<li>slst 1, sc 3, hdc 3, dc 7, hdc 4, sc 2, sc-inc, sc 3, hdc 3, dc 7, hdc 3, sc 3, slst 1<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73839 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-05-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-05-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-05-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-05-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-05-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-05.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><strong>Round 4<\/strong><\/p>\n<ul>\n<li>2 x (sc-inc, sc 3, hdc 3, dc 3, dc-inc, dc 3, hdc 3, sc 4)<\/li>\n<\/ul>\n<p><strong>Round 5<\/strong><\/p>\n<ul>\n<li>sc-inc, 2x (sc 3) in next st, hdc 3, dc 3, dc-inc, dc 4, hdc 3, sc 4, slst<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-73840 size-thumbnail\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-06-400x300.png\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-06-400x300.png 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-06-768x576.png 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-06-16x12.png 16w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-06-600x450.png 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Body-V3-06.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<ul>\n<li>fasten off<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<\/div>\n\n\n\n\n        \n<div id=\"text-gallery-video-block_207d6ab77935876fdeb2a15f9c08e619\" class=\"text-gallery-video toc alignment-left inspiration\"  data-toctitle=\"Fisch No.1\">\n    <section>\n        <div class=\"container position-relative\">\n                                                        <div class=\"text-wrapper\">\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                        <div class=\"topline\">design proposal<\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                        \n                                        <div class=\"heading-tag\">\n                                            <h3> Fisch No.1 <\/h3>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                        <div class=\"text\">\n                                            <p>Crochet Body variant 1<\/p>\n<p><strong>Top fin (photo 1):<\/strong> join in 3rd hdc of bold 3 hdc from body row 4. Begin in next st: (hdc 1, dc 1) in next st, 2 x tr-inc, (hdc 1, dc 1) in next st, slst and fasten off in next st.<\/p>\n<p><strong>Bottom fins (photo 2):<\/strong> join in second dc of row 4 and begin in the next st: \n(hdc 1, dc 1) in next st, dc-inc, hdc 1, slst and fasten off in same st as hdc, rejoin yarn 5 sts later &amp; repeat for a second bottom fin<\/p>\n<p><strong>Tail (photo 3):<\/strong> join 4 sts after 2nd fin, 1 st before the 3 sc at the tail end: ch 3 &amp; in same st, dc 1. continue: dc-inc, dc 1,  2 x dc-inc, ch 3, turn, dc 9 (starting in same st as last ch 3) ch 1 and fasten off<\/p>\n<p><strong>Side fin (photo 4-6):<\/strong> ch 7 &amp; work beginning in second ch from hook: \nhdc 5, (hdc 4) in next st continue back on opposite side of ch: hdc 1, sc 4, ch 1 and fasten off<\/p>\n<p>Crochet the eye (see next step).<\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                                            <\/div>\n                                                <\/div>\n    <\/section>\n<\/div>\n\n\n\n\n\n<div class=\"container pictures-gallery\">\n    <div class=\"row\">\n        <div class=\"col-12 col-md-10 offset-md-1\">\n            <div class=\"swiper mySwiperGallery\">\n                <div class=\"swiper-wrapper\">\n\n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-No1.jpg\" class=\"img-fluid\" alt=\"\" title=\"Fish No1\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-1_step-01.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 1_step 01\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-1_step-02.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 1_step 02\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-1_step-03.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 1_step 03\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-1_step-04.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 1_step 04\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-1_step-05.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 1_step 05\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-1_step-06.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 1_step 06\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-1_step-07.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 1_step 07\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-1_step-08.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 1_step 08\" \/>\n                            <\/div>\n                        \n                        \n                                \n                <\/div>\n                <div class=\"swiper-pagination\"><\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n        \n<div id=\"text-gallery-video-block_c0eb3d9b8a1d7432b19dc50e0aab058f\" class=\"text-gallery-video toc alignment-right inspiration\"  data-toctitle=\"Fisch No.2\">\n    <section>\n        <div class=\"container position-relative\">\n                                                        <div class=\"text-wrapper\">\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-9 offset-lg-3\">\n                                        <div class=\"topline\">design proposal<\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-3\">\n                                        <div class=\"heading-tag\">\n                                            <h3> Fisch No.2 <\/h3>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-3\">\n                                        <div class=\"text\">\n                                            <p>Crochet Body variant 1<\/p>\n<p><strong>Top fin (photo 1-2):<\/strong> join in first hdc of body Row 4, begin in the next st: \nsc 1, hdc 1, dc 2, tr 2, tr-inc, tr 2, dc 2, hdc 1, sc 1, slst and fasten off in next st.<\/p>\n<p><strong>Bottom fin (photo 3-4):<\/strong> join in your first dc on the opposite side of body Row 4, begin in the next st: sc 1, hdc 2, dc 1, dc-inc, dc 1, hdc 2, sc 1, slst and fasten off in next st.<\/p>\n<p><strong>Tail (photo 5-6):<\/strong> join yarn in the final slst of body Row 4 and ch 3. Begin in the same st: 1. dc 1, 2 x dc-inc, ch 3 and turn\n2. dc-inc, dc 4, dc-inc in the 3rd ch of last row, ch 1 and fasten off<\/p>\n<p><strong>Side fin (photo 7-9):<\/strong> ch 6 and work back, beginning in fourth ch from hook: dc 2, dc-inc, ch 3 and turn, dc 3, dc-inc, ch 1 and fasten off<\/p>\n<p>Crochet the eye (see next step).<\/p>\n<p>&nbsp;<\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                                            <\/div>\n                                                <\/div>\n    <\/section>\n<\/div>\n\n\n\n\n\n<div class=\"container pictures-gallery\">\n    <div class=\"row\">\n        <div class=\"col-12 col-md-10 offset-md-1\">\n            <div class=\"swiper mySwiperGallery\">\n                <div class=\"swiper-wrapper\">\n\n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-No2-V2.jpg\" class=\"img-fluid\" alt=\"\" title=\"Fish No2 V2\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-2_step-01.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 2_step 01\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-2_step-02.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 2_step 02\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-2_step-03.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 2_step 03\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-2_step-04.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 2_step 04\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-2_step-05.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 2_step 05\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-2_step-06.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 2_step 06\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-2_step-07.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 2_step 07\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-2_step-08.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 2_step 08\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-2_step-09.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 2_step 09\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-No2.jpg\" class=\"img-fluid\" alt=\"\" title=\"Fish No2\" \/>\n                            <\/div>\n                        \n                        \n                                \n                <\/div>\n                <div class=\"swiper-pagination\"><\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n        \n<div id=\"text-gallery-video-block_159d2d013360154f98ecf8b91e3fe32d\" class=\"text-gallery-video toc alignment-left inspiration\"  data-toctitle=\"Fisch No.3\">\n    <section>\n        <div class=\"container position-relative\">\n                                                        <div class=\"text-wrapper\">\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                        <div class=\"topline\">design proposal<\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                        \n                                        <div class=\"heading-tag\">\n                                            <h3> Fisch No.3 <\/h3>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                        <div class=\"text\">\n                                            <p>Crochet Body variant 2.<\/p>\n<p><strong>Tail (photo 1-6):<\/strong> Ch 12, work back along the ch: beginning in the second ch from hook, sc 10, sc 3 in last ch, continue along other side of ch, sc 2, slst 1, continue...\nch 5, work back along this new ch, beginning in the second ch from hook, sc 4, move back down to the remaining sts of original 12 ch: sc 7, ch 1, turn, hdc 10 back along the stitches you just made, in last st, (hdc 2) in next st, slst 1 in 5th ch &amp; fasten off<\/p>\n<p><strong>Back stripes (photo 7-11):<\/strong> ch 6, work back along the ch, beginning in the second ch from hook: sc 4, sc 3 in last st, turn and work along opposite side of ch: sc 4, ch 1 and fasten off. Make 4 back stripes.<\/p>\n<p><strong>Side fin (photo 12-14):<\/strong> Ch 10, work back along ch: sl st 1, sc 1, hdc 1, dc 1, hdc 1, sc 3, sl st 1, ch 1 &amp; fasten off with a long tail to sew onto the back of the fish.<\/p>\n<p>Crochet the eye (see next step).<\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                                            <\/div>\n                                                <\/div>\n    <\/section>\n<\/div>\n\n\n\n\n\n<div class=\"container pictures-gallery\">\n    <div class=\"row\">\n        <div class=\"col-12 col-md-10 offset-md-1\">\n            <div class=\"swiper mySwiperGallery\">\n                <div class=\"swiper-wrapper\">\n\n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-No3.jpg\" class=\"img-fluid\" alt=\"\" title=\"Fish No3\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-3_step-01.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 3_step 01\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-3_step-02.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 3_step 02\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-3_step-03.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 3_step 03\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-3_step-04.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 3_step 04\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-3_step-05.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 3_step 05\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-3_step-06.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 3_step 06\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-3_step-07.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 3_step 07\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-3_step-08.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 3_step 08\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-3_step-09.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 3_step 09\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-3_step-10.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 3_step 10\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-3_step-11.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 3_step 11\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-3_step-12.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 3_step 12\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-3_step-13.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 3_step 13\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-3_step-14.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 3_step 14\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-3_step-15.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 3_step 15\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-No3-V2.jpg\" class=\"img-fluid\" alt=\"\" title=\"Fish No3 V2\" \/>\n                            <\/div>\n                        \n                        \n                                \n                <\/div>\n                <div class=\"swiper-pagination\"><\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n        \n<div id=\"text-gallery-video-block_7549b7e0b5f06366ff743c72391f6b47\" class=\"text-gallery-video toc alignment-right inspiration\"  data-toctitle=\"Fisch No.4\">\n    <section>\n        <div class=\"container position-relative\">\n                                                        <div class=\"text-wrapper\">\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-9 offset-lg-3\">\n                                        <div class=\"topline\">design proposal<\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-3\">\n                                        <div class=\"heading-tag\">\n                                            <h3> Fisch No.4 <\/h3>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-3\">\n                                        <div class=\"text\">\n                                            <p>Crochet Body variant 2.<\/p>\n<p><strong>Tail (photo 1-4):<\/strong> Join yarn in the the first hdc-inc at the tail end of body Row 4 (in the 2nd hdc), ch 3 (this will count as a first dc). Begin in that same st: dc 2, dc-inc (in the ch 3 from last row), ch 3 and turn, dc-inc, hdc, sc, hdc, dc-inc, ch 3 and turn, dc-inc, hdc, slst 3, hdc, dc-inc, dc 1 in the 3rd ch of last row, ch 1 and fasten off<\/p>\n<p><strong>Head (photo 5-11):<\/strong> ch 7, begin in 2nd ch from hook: hdc 2, sc 3, sc 3 in next st, work back: sc 3, hdc 2, ch 1, turn, hdc 3, sc 3, sc 3 in next st, sc 3, hdc 3, ch 2, turn, dc 2, hdc 3, sc 2, sc 3 in next st, sc 2, hdc 3, dc 2\nOptional: continue along the next side, working in your turning chains and spaces between rows, roughly 8-9 sts<\/p>\n<p><strong>Long stripe (photo 12-16):<\/strong> ch 20, work back along ch: slst 3, sc 6, hdc 10, change color, ch 1 &amp; turn. sc 16, slst and fasten off<\/p>\n<p><strong>Side fin (photo 18-22):<\/strong>ch 8, work back beginning in second ch from hook:\nsc 2, hdc 2, dc 2, (dc 2, hdc 2) in last st, continue on other side of ch, hdc 1, sc 3, slst 2, ch 1 and fasten off<\/p>\n<p>Crochet the eye (see next step).<\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                                            <\/div>\n                                                <\/div>\n    <\/section>\n<\/div>\n\n\n\n\n\n<div class=\"container pictures-gallery\">\n    <div class=\"row\">\n        <div class=\"col-12 col-md-10 offset-md-1\">\n            <div class=\"swiper mySwiperGallery\">\n                <div class=\"swiper-wrapper\">\n\n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-No4.jpg\" class=\"img-fluid\" alt=\"\" title=\"Fish No4\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-01.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 01\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-02.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 02\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-03.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 03\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-04.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 04\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-05.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 05\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-06.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 06\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-07.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 07\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-08.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 08\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-09.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 09\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-10.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 10\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-11.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 11\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-12.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 12\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-13.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 13\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-14.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 14\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-15.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 15\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-16.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 16\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-17.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 17\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-18.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 18\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-19.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 19\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-20.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 20\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-4_step-21.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 4_step 21\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-No4-V2.jpg\" class=\"img-fluid\" alt=\"\" title=\"Fish No4 V2\" \/>\n                            <\/div>\n                        \n                        \n                                \n                <\/div>\n                <div class=\"swiper-pagination\"><\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n        \n<div id=\"text-gallery-video-block_732923ec9255edae7807f905e3b013dc\" class=\"text-gallery-video toc alignment-left inspiration\"  data-toctitle=\"Fisch No.5\">\n    <section>\n        <div class=\"container position-relative\">\n                                                        <div class=\"text-wrapper\">\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                        <div class=\"topline\">design proposal<\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                        \n                                        <div class=\"heading-tag\">\n                                            <h3> Fisch No.5 <\/h3>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                        <div class=\"text\">\n                                            <p>Crochet Body variant 3.<\/p>\n<p><strong>Tail (photo 1-4):<\/strong> join yarn 2 sts before your slst off from Row 5, ch 3 in next st: 2 dc's, &amp; 2 dc's in slst; in st after the slst from Row 4, make 2 dc's, ch 3, turn, dc 6, ch 3, turn, dc 2, hdc 2, sc 2, slst in 3rd ch from Row 2 fasten off<\/p>\n<p><strong>Top fin (photo 5-8):<\/strong> join yarn in the next st above the tail &amp; ch 1, beginning in next st: sc 2, hdc 1, hdc-inc, dc 3, dc-inc, dc 4, dc-inc, dc 1, ch 3 &amp; turn, continue to work back down the fin, dc 4, hdc 4, sc 6, slst &amp; fasten off<\/p>\n<p><strong>Bottom fin (photo 9-10):<\/strong> join yarn in body Row 5, 2 sts after the dc-inc, ch 1, sc 1, hdc 1, dc 1, in the next st: dc + hdc, sc 1, slst in next st &amp; fasten off (2 sts before beginning the tail)<\/p>\n<p><strong>Horizontal stripe (photo 11-13):<\/strong> ch 16, beginning in second ch from hook, sc 14 back along ch, in last ch: sc 2 and turn, sc 14 back along the opposite side of ch, sc 1 &amp; fasten off in last st<\/p>\n<p><strong>Vertical stripes (photo 14-15):<\/strong><\/p>\n<ol>\n<li>ch 19, beginning in second ch from hook, sc 19 ch, 1 and fasten off<\/li>\n<li>ch 17, beginning in second ch from hook, sc 18 ch, 1 and fasten off<\/li>\n<li>ch 15, beginning in second ch from hook, sc 14 ch, 1 and fasten off<\/li>\n<\/ol>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                                            <\/div>\n                                                <\/div>\n    <\/section>\n<\/div>\n\n\n\n\n\n<div class=\"container pictures-gallery\">\n    <div class=\"row\">\n        <div class=\"col-12 col-md-10 offset-md-1\">\n            <div class=\"swiper mySwiperGallery\">\n                <div class=\"swiper-wrapper\">\n\n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-No5.jpg\" class=\"img-fluid\" alt=\"\" title=\"Fish No5\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-01.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 01\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-02.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 02\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-03.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 03\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-04.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 04\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-05.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 05\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-06.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 06\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-07.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 07\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-08.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 08\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-09.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 09\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-10.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 10\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-11.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 11\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-12.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 12\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-13.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 13\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-14.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 14\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-15.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 15\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-5_step-16.png\" class=\"img-fluid\" alt=\"\" title=\"Fish 5_step 16\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Fish-No5-V2.jpg\" class=\"img-fluid\" alt=\"\" title=\"Fish No5 V2\" \/>\n                            <\/div>\n                        \n                        \n                                \n                <\/div>\n                <div class=\"swiper-pagination\"><\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n        \n<div id=\"text-gallery-video-block_58f9e4a0e217c92248cf11492b3de0de\" class=\"text-gallery-video toc alignment-left inspiration\"  data-toctitle=\"Auge h\u00e4keln\">\n    <section>\n        <div class=\"container position-relative\">\n                                                        <div class=\"text-wrapper\">\n                                                                                                                    <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                        \n                                        <div class=\"heading-tag\">\n                                            <h3> Eye <\/h3>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                        <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                        <div class=\"text\">\n                                            <ul>\n<li>Make a magic loop.<\/li>\n<li>Ch 1 and sc 5 into the loop.<\/li>\n<li>\u00a0slst 1 into the first sc, ch 1 and fasten off, with a long end to sew the eye onto the body.\nInsert a plastic eye or alternative &amp; pull on your starting yarn end to tightern the loop.<\/li>\n<\/ul>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                                            <\/div>\n                                                <\/div>\n    <\/section>\n<\/div>\n\n\n\n\n\n<div class=\"container pictures-gallery\">\n    <div class=\"row\">\n        <div class=\"col-12 col-md-10 offset-md-1\">\n            <div class=\"swiper mySwiperGallery\">\n                <div class=\"swiper-wrapper\">\n\n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Auge-01.png\" class=\"img-fluid\" alt=\"\" title=\"Auge 01\" \/>\n                            <\/div>\n                        \n                        \n                \n                                                    <div class=\"swiper-slide\">\n                            <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Auge-02.png\" class=\"img-fluid\" alt=\"\" title=\"Auge 02\" \/>\n                            <\/div>\n                        \n                        \n                                \n                <\/div>\n                <div class=\"swiper-pagination\"><\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n        \n<div id=\"text-gallery-video-block_ee92345eff823fb7c1d879a7ea0a6133\" class=\"text-gallery-video alignment-left inspiration\" >\n    <section>\n        <div class=\"container position-relative\">\n                                                        <div class=\"text-wrapper\">\n                                                            <div class=\"text-background-big color-area-secondary\"><\/div>\n                                                                                                                    <div class=\"row\">\n                                    <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                        \n                                        <div class=\"heading-tag\">\n                                            <h4> Share your progress with us: <\/h4>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                                                    <div class=\"row\">\n                                    <div class=\"col-12 col-lg-6 offset-lg-2\">\n                                        <div class=\"text text_indented\">\n                                            <p>Arbeitest du gerade an dieser Anleitung? Teile das Ergebnis gerne auf Instagram unter <strong>@wccrochet @addi_by_selter<\/strong> or share it with us in our Facebook group \"addiFriends\".<\/p>\n<p><strong>Design + Photos:<\/strong> <a href=\"https:\/\/www.wc-crochet.com\/\" rel=\"noopener\">Will Chatlosh<\/a><\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                                                <\/div>\n                                                <\/div>\n    <\/section>\n<\/div>\n\n\n\n\n            \n<div id=\"text-gallery-video-block_74881ceb89ebdf0abb40b16bedb2fca4\" class=\"text-gallery-video alignment-left inspiration\" >\n    <section>\n        <div class=\"container position-relative\">\n            \n\n                                                                                <div class=\"gallery-wrapper  d-lg-block\">\n                                                                                                                        <div class=\"row align-items-end\">\n                                                <div class=\"col-12 col-lg-6 offset-lg-1\">\n                                                    <div class=\"text-wrapper mb-3\">\n                                                                                                                                                                            <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    <div class=\"topline\">About the artist and designer<\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                            <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    \n                                                                    <div class=\"heading-tag\">\n                                                                    <h2> Will Chatlosh <\/h2>\n                                                                    <\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                            <div class=\"row\">\n                                                                <div class=\"col-12\">\n                                                                    <div class=\"text\">\n                                                                        <p>Will Chatlosh is a 22-year-old fiber artist who is working to reinvent how people view crochet!<br \/>\nHe is living in New York, NY, but originally from Grand Rapids, MI. Will recently received his Bachelor\u2019s of Fine Arts in Fashion Studies from Kendall College of Art and Design and associates in Fashion Design from the Fashion Institute of Technology (FIT) in New York, NY, graduating with honors in both programs.<\/p>\n<p>Will initially taught himself to crochet at the age of eleven using Youtube as his main resource for information Initially only crocheting for leisure and for gifts, he began within the field of amigurumi, and has since created unique patterns and designs of his own. His mission has always been to change the way that people view crochet in the field of arts and crafts. He has grown a community by sharing his work on social media under the name @wccrochet, and has been posting his crochet projects since 2017.<br \/>\nOver the last three years, his has been motivated to communicate and create messages with his ability to crochet: delving into the world of freeform crochet art and now primarily creates crocheted portraits.<\/p>\n                                                                    <\/div>\n                                                                <\/div>\n                                                            <\/div>\n                                                                                                                                                                                                                            <\/div>\n                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_74881ceb89ebdf0abb40b16bedb2fca4\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"650\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Portrait-900x650.jpg\" class=\"attachment-900x650 size-900x650\" alt=\"\" \/>                                                        <\/div>\n                                                                                                    <\/div>\n\n                              \n                                                <div class=\"col-12 col-lg-4 elements-count-2\">\n                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_74881ceb89ebdf0abb40b16bedb2fca4\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Marilyn-400x400.webp\" class=\"attachment-400x400 size-400x400\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Marilyn-400x400.webp 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Marilyn-800x800.webp 800w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Marilyn-300x300.webp 300w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Marilyn-100x100.webp 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                        <\/div>\n                                                                                                                                                                <div class=\"buttonspacer\"><\/div>\n                                                                                                                                                                <div class=\"scriptheadlinespacer\"><\/div>\n                                                        <div class=\"underlinespacer\"><\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n                                                                                                            <\/div>\n                               \n                                 \n                            <div class=\"gallery-wrapper d-block d-lg-none\">\n                                                                    <div class=\"text-wrapper mb-5\">\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                                    <div class=\"topline\">About the artist and designer<\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                              \n                                                    <div class=\"heading-tag\">\n                                                        <h2>Will Chatlosh<\/h2>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                            <div class=\"row\">\n                                                <div class=\"col-12 col-lg-8 offset-lg-1\">\n                                                    <div class=\"text\">\n                                                        <p>Will Chatlosh is a 22-year-old fiber artist who is working to reinvent how people view crochet!<br \/>\nHe is living in New York, NY, but originally from Grand Rapids, MI. Will recently received his Bachelor\u2019s of Fine Arts in Fashion Studies from Kendall College of Art and Design and associates in Fashion Design from the Fashion Institute of Technology (FIT) in New York, NY, graduating with honors in both programs.<\/p>\n<p>Will initially taught himself to crochet at the age of eleven using Youtube as his main resource for information Initially only crocheting for leisure and for gifts, he began within the field of amigurumi, and has since created unique patterns and designs of his own. His mission has always been to change the way that people view crochet in the field of arts and crafts. He has grown a community by sharing his work on social media under the name @wccrochet, and has been posting his crochet projects since 2017.<br \/>\nOver the last three years, his has been motivated to communicate and create messages with his ability to crochet: delving into the world of freeform crochet art and now primarily creates crocheted portraits.<\/p>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                                                                                                                                            <\/div>\n                                                                            <div class=\"row mb-4\">\n                                            <div class=\"col-12\">\n                                                                                                    <div id=\"galleryCarousel-block_74881ceb89ebdf0abb40b16bedb2fca4\" class=\"carousel slide\" data-ride=\"carousel\" data-interval=\"2500\" data-pause=\"false\" data-keyboard=\"false\">\n                                                        <div class=\"carousel-inner\" data-countslides=\"2\">\n                                                                                                                            <div class=\"carousel-item active\">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_74881ceb89ebdf0abb40b16bedb2fca4\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Portrait-1280x970.jpg\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Portrait-400x320.jpg\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                            <div class=\"carousel-item\">\n                                                                                                                                            <div data-toggle=\"modal\" data-target=\"#modal-text-gallery-video-block_74881ceb89ebdf0abb40b16bedb2fca4\">\n                                                                            <picture>\n                                                                                <source media=\"(min-width: 400px)\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Marilyn-1280x970.webp\">\n                                                                                <img decoding=\"async\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Marilyn-400x320.webp\" alt=\"\">\n                                                                            <\/picture>\n                                                                        <\/div>\n                                                                                                                                    <\/div>\n                                                                                                                    <\/div>\n                                                    <\/div>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                                                                                                                                                            <\/div>\n                                                                                    <\/div>\n    <\/section>\n<\/div>\n\n            \n        <div class=\"modal fade modal-move-to-body gallery-modal inspiration\" id=\"modal-text-gallery-video-block_74881ceb89ebdf0abb40b16bedb2fca4\" tabindex=\"-1\"\n             aria-labelledby=\"modal-text-gallery-video-block_74881ceb89ebdf0abb40b16bedb2fca4\" aria-hidden=\"true\">\n            <div class=\"modal-dialog modal-xl modal-dialog-centered\">\n                <div class=\"modal-content\">\n                    <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n                        <i class=\"fas fa-times\"><\/i>\n                    <\/button>\n                    <div class=\"modal-body\">\n                        <div class=\"container-fluid\">\n                                                            <div id=\"modal-carousel-text-gallery-video-block_74881ceb89ebdf0abb40b16bedb2fca4\" class=\"carousel slide keepsize\">\n                                    <div class=\"carousel-inner\" data-countslides=\"2\">\n                                                                                    <div class=\"carousel-item active\">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1366\" height=\"1366\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Portrait.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Portrait.jpg 1366w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Portrait-300x300.jpg 300w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Portrait-768x768.jpg 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Portrait-12x12.jpg 12w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Portrait-800x800.jpg 800w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Portrait-400x400.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Portrait-1320x1320.jpg 1320w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Portrait-600x600.jpg 600w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Portrait-100x100.jpg 100w\" sizes=\"auto, (max-width: 1366px) 100vw, 1366px\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                                    <div class=\"carousel-item\">\n                                                <div class=\"row carousel-item-image-wrapper\">\n                                                    <div class=\"col-12\">\n                                                        <div class=\"carousel-item-image\">\n                                                            <div class=\"color-area-secondary\"><\/div>\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1875\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Marilyn.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Marilyn.webp 1500w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Marilyn-240x300.webp 240w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Marilyn-768x960.webp 768w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Marilyn-1229x1536.webp 1229w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Marilyn-10x12.webp 10w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Marilyn-1320x1650.webp 1320w, https:\/\/addi.de\/wp-content\/uploads\/2026\/02\/Will-Chatlosh-Marilyn-600x750.webp 600w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/>                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/div>\n                                                                            <\/div>\n                                    <a class=\"carousel-control-prev\" href=\"#modal-carousel-text-gallery-video-block_74881ceb89ebdf0abb40b16bedb2fca4\" role=\"button\" data-slide=\"prev\">\n                                        <i class=\"fas fa-angle-left\"><\/i>\n                                    <\/a>\n                                    <a class=\"carousel-control-next\" href=\"#modal-carousel-text-gallery-video-block_74881ceb89ebdf0abb40b16bedb2fca4\" role=\"button\" data-slide=\"next\">\n                                        <i class=\"fas fa-angle-right\"><\/i>\n                                    <\/a>\n                                    <div class=\"carousel-indicators-wrapper\">\n                                        <ol class=\"carousel-indicators\">\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_74881ceb89ebdf0abb40b16bedb2fca4\" data-slide-to=\"0\"\n                                                    class=\"active\"><\/li>\n                                                                                            <li data-target=\"#modal-carousel-text-gallery-video-block_74881ceb89ebdf0abb40b16bedb2fca4\" data-slide-to=\"1\"\n                                                    class=\"\"><\/li>\n                                                                                    <\/ol>\n                                    <\/div>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    \n\n<div id=\"selection-teaser-block_d72f5608780fa00ffb07b4102f8c7091\" class=\"selection-teaser\" >\n    <section>\n        <div class=\"container\">\n                            <div class=\"row\">\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper inherit\">\n                            <div class=\"image-wrapper\">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/10\/Haekeln-Banner_addiDuett-400x320.jpg\" class=\"attachment-400x320 size-400x320\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/10\/Haekeln-Banner_addiDuett-400x320.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2025\/10\/Haekeln-Banner_addiDuett-16x12.jpg 16w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Page                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        Instructions crochet                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        Free crochet instructions                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>Discover the wonderful world of crochet and get inspired by our free crochet tutorials. Whether it's crochet jackets for ladies, cute crochet decorations, stylish crochet scarves or beautiful granny square tutorials - with us you will find high-quality, simple crochet instructions.<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href=\"https:\/\/addi.de\/en\/anleitungen\/haekeln\/\" target=\"_self\" class=\"buttonlink prio-2\">To the crochet instructions<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper inspiration\">\n                            <div class=\"image-wrapper\">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2026\/01\/North-Sea-Fish_Varianten-400x320.jpg\" class=\"attachment-400x320 size-400x320\" alt=\"\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Inspiration                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        Knitting tutorial                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        North Sea Fish                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>As colourful as the sea. The knitted fish with colourful patterns are created by combining two Scheepjes Downtown striped yarns and different knitting patterns.<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href=\"https:\/\/addi.de\/en\/story\/nordsee-fische-stricken\/\" target=\"_self\" class=\"buttonlink prio-2\">Read tutorial<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-12 col-lg-4 mb-4 mb-lg-0 tile-wrapper service\">\n                            <div class=\"image-wrapper\">\n                                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"320\" src=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/04\/addi2go-App-Banner-400x320.jpg\" class=\"attachment-400x320 size-400x320\" alt=\"\" srcset=\"https:\/\/addi.de\/wp-content\/uploads\/2025\/04\/addi2go-App-Banner-400x320.jpg 400w, https:\/\/addi.de\/wp-content\/uploads\/2025\/04\/addi2go-App-Banner-16x12.jpg 16w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                                                                                                        <div class=\"batch color-area-primary\">\n                                        Page                                    <\/div>\n                                                            <\/div>\n                            <div class=\"text-wrapper\">\n                                                                    <div class=\"topline\">\n                                        app                                    <\/div>\n                                                                                                    <div class=\"headline\">\n                                        addi2go                                    <\/div>\n                                                                                                    <div class=\"text\">\n                                        <p>Getting creative has never been simpler with the addi2go app. Our app provides inspiration, tips and help for everyone \u2013 whenever, wherever. Download now, and let the fun begin!<\/p>\n                                    <\/div>\n                                                                                                    <div class=\"link-wrapper\">\n                                        <a href=\"https:\/\/addi.de\/en\/addi2go\/\" target=\"_self\" class=\"buttonlink prio-2\">To the app<\/a>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/section>\n<\/div>","protected":false},"parent":0,"menu_order":0,"template":"","kategorie_sy":[31],"kategorie_blog":[547,36,563,566,573,559,553,565,570],"class_list":["post-73673","story","type-story","status-publish","hentry","kategorie_sy-inspiration","kategorie_blog-anlass","kategorie_blog-anleitung","kategorie_blog-fortgeschrittene-anfaenger","kategorie_blog-haekeln","kategorie_blog-home-deko","kategorie_blog-schwierigkeit","kategorie_blog-sommer","kategorie_blog-technik","kategorie_blog-thema"],"acf":[],"_links":{"self":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/story\/73673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/types\/story"}],"wp:attachment":[{"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/media?parent=73673"}],"wp:term":[{"taxonomy":"kategorie_sy","embeddable":true,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/kategorie_sy?post=73673"},{"taxonomy":"kategorie_blog","embeddable":true,"href":"https:\/\/addi.de\/en\/wp-json\/wp\/v2\/kategorie_blog?post=73673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}